{"id":18142,"date":"2012-06-23T04:00:00","date_gmt":"2012-06-23T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/john-travolta-se-enfrenta-a-una-nueva-demanda-por-acoso\/"},"modified":"2012-06-23T04:00:00","modified_gmt":"2012-06-23T08:00:00","slug":"john-travolta-se-enfrenta-a-una-nueva-demanda-por-acoso","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/john-travolta-se-enfrenta-a-una-nueva-demanda-por-acoso\/","title":{"rendered":"John Travolta se enfrenta a una nueva demanda por acoso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18141\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_travolta-denuncia--644x362.jpg\" width=\"644\" height=\"362\" alt=\"travolta-denuncia--644x362\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_travolta-denuncia--644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_travolta-denuncia--644x362-300x168.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/>La pol\u00e9mica sigue rodeando al actor, las v\u00edctimas no paran de salir y su sexualidad est\u00e1 en entredicho.<\/p>\n<p>  <!--more-->  <\/p>\n<div>\n<p id=\"story-texto\" xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">Ya son&nbsp;tres las personas&nbsp;que acusan a John Travolta de acoso sexual. tres hombres, varias demandas y muchos rumores.&nbsp;Robert Randolph,el \u00faltimo en demandar al actor, adem\u00e1s dice que el abogado de Travolta le acusa de tener problemas mentales para desmentir la informaci\u00f3n. Seg\u00fan el letrado, las acusaciones son \u00ababsurdas\u00bb. Randolph, escritor de profesi\u00f3n, se queja de que las ventas de sus libros han disminu\u00eddo ante las acusaciones de Travolta.<\/p>\n<p id=\"U1502978697873DhB\" xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">Despu\u00e9s de que una primera persona le culpara por sus comportamientos, aparecieron&nbsp;<a href=\"http:\/\/www.abc.es\/20120524\/estilo-gente\/abci-john-travolta-vestido-mujer-201205240957.html\">unas fotos del actor travestido&nbsp;<\/a>y luego lleg\u00f3 el supuesto&nbsp;<a href=\"http:\/\/www.abcdesevilla.es\/20120528\/estilo-gente\/rc-matrimonio-travolta-cuerda-floja-201205281328.html\">abandono de su mujer, Kelly Preston<\/a>, quien no aguantaba m\u00e1s. Ahora&nbsp;la homosexualidad de Travolta es casi un hecho&nbsp;en Hollywood y el protagonista de Grease espera escondido que se celebren los juicios.<\/p>\n<p xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\"><a href=\"http:\/\/www.abc.es\/20120622\/estilo-gente\/abci-denuncias-john-travolta-201206221336.html\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La pol\u00e9mica sigue rodeando al actor, las v\u00edctimas no paran de salir y su sexualidad est\u00e1 en entredicho.<\/p>\n","protected":false},"author":3,"featured_media":18141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18142"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18141"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}