{"id":18165,"date":"2012-06-24T04:00:00","date_gmt":"2012-06-24T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/dormir-juntos-es-tan-importante-como-hacer-el-amor\/"},"modified":"2012-06-24T04:00:00","modified_gmt":"2012-06-24T08:00:00","slug":"dormir-juntos-es-tan-importante-como-hacer-el-amor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dormir-juntos-es-tan-importante-como-hacer-el-amor\/","title":{"rendered":"Dormir juntos es tan importante como hacer el amor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18164\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_dormir-juntos23465789.jpg\" width=\"270\" height=\"179\" alt=\"dormir-juntos23465789\" class=\"caption\" style=\"float: left;\" \/>La manera en que las parejas duermen juntas afecta su salud, su felicidad y la satisfacci\u00f3n de uno con el otro. Problemas y soluciones.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Un sinn\u00famero de estudios revelan que el tiempo que las parejas est\u00e1n en contacto f\u00edsico despu\u00e9s del sexo es parte importante de una relaci\u00f3n sexual saludable. No obstante, m\u00e1s all\u00e1 de ese momento, se ha probado cu\u00e1n significativo es, para la relaci\u00f3n de pareja, dormir juntos.<\/p>\n<p>Wendy Troxel, psiquiatra del Sleep Medicine Institute de la Universidad de Pittsburgh, se dedica a estudiar c\u00f3mo la gente duerme en lo que ella llama \u201csu h\u00e1bitat natural\u201d: con alguien junto a ellos. Explica que, aunque dormimos m\u00e1s profundamente si dormimos solos, preferimos dormir con alguien, lo que sugiere una necesidad humana fundamental de apegarnos durante la noche. Las mujeres en relaciones largas y estables se duermen m\u00e1s r\u00e1pido y se despiertan menos cuando duermen con su pareja; disfrutan dormir con un hombre al lado y les da sensaci\u00f3n de seguridad.<\/p>\n<p>Troxel tambi\u00e9n afirma que para ambos el hombre y la mujer, dormir con la pareja contribuye al bienestar mental y reduce la enfermedad card\u00edaca. Baja los niveles de cortisol (la hormona de estr\u00e9s), reduce las citocinas causantes de inflamaciones y aumenta la oxitocina (la hormona del amor).<\/p>\n<p>El soci\u00f3logo Paul C. Rosenblatt alega que muchas parejas pasan m\u00e1s tiempo en la cama que en sus pies. Dormir juntos en armon\u00eda, que \u00e9l traduce en ponerse de acuerdo sobre la temperatura ambiental y hora de dormir, requiere tanto compromiso como otras negociaciones que hace una pareja sobre otros asuntos. Seg\u00fan sus estudios, dormir con la pareja es un logro de coordinaci\u00f3n que tiene muchas dimensiones.<\/p>\n<p>\u00bfQu\u00e9 puede impedirnos dormir en paz junto a la pareja y c\u00f3mo lo resolvemos?<br \/>-El ronquido. Dormir al lado de una persona que ronca o padece insomnio produce cambios de \u00e1nimo, depresi\u00f3n, insatisfacci\u00f3n en la relaci\u00f3n, deterioro en la salud mental y f\u00edsica y otros defectos de poder tener un sue\u00f1o profundo y reparador. Soluci\u00f3n: Si tu pareja se queja de que roncas, en vez de enojarte, discutir, ponerte terco o dormir separado, busca ayuda m\u00e9dica. Cuando un c\u00f3nyuge que padece apnea de sue\u00f1o recibe tratamiento, se reducen los desacuerdos en la pareja.<\/p>\n<p>-La batalla por la cobija. Soluci\u00f3n: Compren una cobija m\u00e1s grande para que por m\u00e1s que la halen, ninguno de los dos quede al descubierto. No se aconseja dormir con dos cobijas separadas, pero si no hay otro remedio, es una alternativa.<\/p>\n<p>-El exceso de movimiento de uno de los dos mientras duerme. Soluci\u00f3n: Adquieran un colch\u00f3n de impacto separado, de manera que uno no sienta los movimientos del otro durante la noche.<\/p>\n<p>-La hora de irse a dormir. Soluci\u00f3n: P\u00f3nganse de acuerdo seg\u00fan sus horarios de trabajo y otras obligaciones del hogar. Probablemente no ser\u00e1 la misma diariamente, pero es un tema importante a discutir antes de que sea un problema.<\/p>\n<p>-Las diferencias sobre la temperatura ambiental favorita para dormir. Soluci\u00f3n: Negocien y decidan la temperatura ambiental correcta para ambos.<\/p>\n<p>-Desacuerdos no resueltos. Soluci\u00f3n: Conversen las desavenencias antes de irse a dormir. La mujer duerme mejor despu\u00e9s de conversar esos asuntos con su pareja. El hombre duerme mejor tambi\u00e9n, despierta m\u00e1s contento y pasa mejor el d\u00eda siguiente.<\/p>\n<p><a href=\"http:\/\/www.cachicha.com\/2012\/06\/dormir-juntos-es-tan-importante-como-hacer-el-amor\/\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La manera en que las parejas duermen juntas afecta su salud, su felicidad y la satisfacci\u00f3n de uno con el otro. Problemas y soluciones.<\/p>\n","protected":false},"author":3,"featured_media":18164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-18165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18165"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18164"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}