{"id":18220,"date":"2012-06-26T18:28:36","date_gmt":"2012-06-26T22:28:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ellos-piensan-mas-en-sexo-imito-o-realidad\/"},"modified":"2012-06-26T18:28:36","modified_gmt":"2012-06-26T22:28:36","slug":"ellos-piensan-mas-en-sexo-imito-o-realidad","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ellos-piensan-mas-en-sexo-imito-o-realidad\/","title":{"rendered":"\u201cEllos\u201d piensan m\u00e1s en sexo: \u00bfmito o realidad?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18219\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_Las-ganas-de-sexo-no-slo-son-terreno-masculino.jpg\" width=\"270\" height=\"203\" alt=\"Las-ganas-de-sexo-no-slo-son-terreno-masculino\" class=\"caption\" style=\"float: left;\" \/>Deportes, comida y sexo. El orden puede variar, pero hasta ahora cre\u00edamos que esas tres cosas dominaban la cabeza de los hombres. \u00bfSer\u00e1 verdad o lleg\u00f3 el momento de derrumbar el mito? La respuesta la dio un estudio realizado por la Universidad Estatal de Ohio (EEUU) que se publicar\u00e1, completa, en el pr\u00f3ximo n\u00famero de la revista The Journal of Sex Research.<\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 12pt;\"><strong>La imaginaci\u00f3n, en n\u00fameros<\/strong><\/span><\/p>\n<p>Dirigida por Terri Fisher, profesor de psicolog\u00eda, la encuesta involucr\u00f3 300 personas de ambos sexos: 163 mujeres y 120 estudiantes universitarios varones, entre 18 y 25 a\u00f1os. Y estos son los resultados que, al menos, sorprenden:<\/p>\n<p>-La mayor\u00eda de los hombres tienen 19 pensamientos sexuales al d\u00eda.<\/p>\n<p>-Algunos, sin embargo, llegan al exceso de pensar en el tema 388 veces durante las 24 hs.<\/p>\n<p>-Las mujeres piensan en sexo 10 veces al d\u00eda.<\/p>\n<p>-La que m\u00e1s pensamientos registr\u00f3, lo hizo 140 veces en 14 horas.<\/p>\n<p>-Los hombres, por su parte, no piensan en sexo mucho m\u00e1s de lo que piensan en comida (18 veces por d\u00eda) o en dormir (11 veces al d\u00eda).<\/p>\n<p>-Las mujeres m\u00e1s preocupadas por ser socialmente aceptadas reportaron menos pensamientos sexuales.<\/p>\n<p>En primer lugar, los participantes respondieron un cuestionario que buscaba evaluar si sent\u00edan algo positivo o negativo sobre la sexualidad en general. Luego, se organizaron tres grupos: uno registr\u00f3 la frecuencia con la que pensaba en sexo, otro la frecuencia con la que pensaba en alimentos y el \u00faltimo, la frecuencia con la que pensaba en el sue\u00f1o.<\/p>\n<p>Para Fisher, estos resultados son extremadamente significativos ya que contradicen estereotipos impuestos. Ellos no piensan en sexo mucho m\u00e1s que ellas. La guerra de los sexos tambi\u00e9n lleg\u00f3 al cerebro.<\/p>\n<p><a href=\"http:\/\/www.cachicha.com\/2012\/06\/ellos-piensan-mas-en-sexo-mito-o-realidad\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deportes, comida y sexo. El orden puede variar, pero hasta ahora cre\u00edamos que esas tres cosas dominaban la cabeza de los hombres. \u00bfSer\u00e1 verdad o lleg\u00f3 el momento de derrumbar el mito? La respuesta la dio un estudio realizado por la Universidad Estatal de Ohio (EEUU) que se publicar\u00e1, completa, en el pr\u00f3ximo n\u00famero de la revista The Journal of Sex Research.<\/p>\n","protected":false},"author":3,"featured_media":18219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18220"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18219"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}