{"id":18228,"date":"2012-06-27T16:00:00","date_gmt":"2012-06-27T20:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/iel-fin-del-latex-inventan-preservativos-en-aerosol\/"},"modified":"2012-06-27T16:00:00","modified_gmt":"2012-06-27T20:00:00","slug":"iel-fin-del-latex-inventan-preservativos-en-aerosol","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/iel-fin-del-latex-inventan-preservativos-en-aerosol\/","title":{"rendered":"\u00bfEl fin del l\u00e1tex? Inventan preservativos en \u201caerosol\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18227\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_Lo-ltimo.-El-mtodo-anticonceptivo-sera-mediante-un-spray.jpg\" width=\"270\" height=\"202\" alt=\"Lo-ltimo.-El-mtodo-anticonceptivo-sera-mediante-un-spray\" class=\"caption\" style=\"float: left;\" \/>El Instituto Condom Consultancy de Berl\u00edn, Alemania, desarroll\u00f3 mediante nuevas tecnolog\u00edas, un nuevo m\u00e9todo anticonceptivo para la prevenci\u00f3n de infecciones y embarazos no deseados a trav\u00e9s de un cond\u00f3n en spray, el cual a\u00fan no se encuentra la venta, pero se espera que despu\u00e9s de la etapa de prueba pueda hallarse en el mercado.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Para usar el novedoso anticonceptivo en aerosol, debe rociarse sobre el pene y esperar unos segundos a que seque. Al entrar en contacto con el aire, se convierte en una especie de capa gelatinosa al efectuar la penetraci\u00f3n.<\/p>\n<p>Cada aerosol tendr\u00e1 suficiente l\u00e1tex para contemplar unos 20 condones o 20 relaciones sexuales, y tardar\u00eda aproximadamente 25 segundos o menos en hacer efecto, para comenzar con la relaci\u00f3n.<\/p>\n<p>Cuando el hombre eyacula, el aerosol entra contacto con el semen y vuelve a convertirse a su estado l\u00edquido, liberando una droga encargada de atacar el VIH SIDA, por lo que ni los espermatozoides prosperan para fecundar el \u00f3vulo, ni ning\u00fan virus puede infectar a la pareja.<\/p>\n<p>Seg\u00fan indican los investigadores, la principal ventaja de este desarrollo es que se anular\u00edan las complicaciones por colocaci\u00f3n, eliminando el riesgo de que se rompa.<\/p>\n<p>Adem\u00e1s de que representa una opci\u00f3n c\u00f3moda y f\u00e1cil de llevar, lo que dejar\u00e1 de lado las excusas para no emplear un m\u00e9todo anticonceptivo en las relaciones sexuales.<\/p>\n<p><a href=\"http:\/\/www.cachicha.com\/2012\/06\/el-fin-del-latex-inventan-preservativos-en-aerosol\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Condom Consultancy de Berl\u00edn, Alemania, desarroll\u00f3 mediante nuevas tecnolog\u00edas, un nuevo m\u00e9todo anticonceptivo para la prevenci\u00f3n de infecciones y embarazos no deseados a trav\u00e9s de un cond\u00f3n en spray, el cual a\u00fan no se encuentra la venta, pero se espera que despu\u00e9s de la etapa de prueba pueda hallarse en el mercado.<\/p>\n","protected":false},"author":3,"featured_media":18227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18228"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18227"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}