{"id":18257,"date":"2012-06-28T19:00:00","date_gmt":"2012-06-28T23:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/como-crear-aplicaciones-gratis-para-iphone-y-android\/"},"modified":"2012-06-28T19:00:00","modified_gmt":"2012-06-28T23:00:00","slug":"como-crear-aplicaciones-gratis-para-iphone-y-android","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/como-crear-aplicaciones-gratis-para-iphone-y-android\/","title":{"rendered":"C\u00f3mo crear aplicaciones gratis para iPhone y Android"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18256\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_aplicaciones-gratis.jpg\" width=\"499\" height=\"400\" alt=\"aplicaciones-gratis\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_aplicaciones-gratis.jpg 499w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_aplicaciones-gratis-300x240.jpg 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/>Uno de los campos de la tecnolog\u00eda que m\u00e1s relevancia est\u00e1 consiguiendo en los \u00faltimos a\u00f1os es el de las aplicaciones m\u00f3viles, tanto en el segmento de los tel\u00e9fonos m\u00f3viles como en los tablets. Muchos desarrolladores han pasado de programar en lenguajes para PC a aprender Flash o HTML5 para crear aplicaciones que funcionen en esta plataforma, sobre todo en los sistemas operativos m\u00f3viles Android e iOS.&nbsp;<a href=\"http:\/\/www.brightcove.com\/es\/plataforma-aplicaciones-contenidos\" target=\"_blank\">Brightcove<\/a>&nbsp;ha presentado su nueva versi\u00f3n de App Cloud Core, una plataforma gratuita para crear aplicaciones tanto para los smartphones y tablets Android como para el iPhone y el iPad.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La plataforma de Brightcove est\u00e1 basada en la nube (es decir, se trabaja por entero en Internet, sin necesidad de instalar aplicaciones en el ordenador). Permite publicar un n\u00famero ilimitado de aplicaciones tanto en Android como en iOS. App Cloud Core permite a los desarrolladores trabajar con una SDK (plataforma de desarrollo de aplicaciones) de c\u00f3digo abierto basado en JavaScript y contenedores nativos para crear aplicaciones que luego se pueden trasladar a estos entornos sin necesidad de conocer lenguajes espec\u00edficos para cada plataforma.<\/p>\n<p>Una de las ventajas que incorpora App Cloud Core es la compilaci\u00f3n multiplataforma en la nube, con la que se pueden compilar al un\u00edsono las aplicaciones para varias plataformas. Tampoco hay que desde\u00f1ar la herramienta incluida App Cloud Workshop, a trav\u00e9s de la cual se pueden realizar las pruebas de las aplicaciones que se est\u00e1n desarrollando en el mismo dispositivo m\u00f3vil (tanto smartphone como tablet) en el que luego va a funcionar, lo que supone una manera muy \u00fatil de cerciorarse de que no pasen desapercibidos los errores que luego pueden aparecer en la versi\u00f3n definitiva.<\/p>\n<p>Adem\u00e1s, en el momento en el que se est\u00e1 probando la aplicaci\u00f3n en el dispositivo es posible conectar, a trav\u00e9s de un solo movimiento del smartphone o el tablet,&nbsp;<a href=\"http:\/\/www.brightcove.com\/es\/plataforma-aplicaciones-contenidos\" target=\"_blank\">la App Cloud Workshop&nbsp;<\/a>con la consola de correcci\u00f3n de errores a distancia de App Cloud. Con esta consola se realizar\u00e1 un diagn\u00f3stico para tratar de identificar los posibles errores que se est\u00e9n produciendo en la aplicaci\u00f3n. A la hora de crear las apps, se cuenta con una extensa librer\u00eda de componentes con soporte para texto, audio, v\u00eddeo, im\u00e1genes y cualquier tipo de datos que se introducen en el entorno t\u00e1ctil del dispositivo.<\/p>\n<p>Otro de los aspectos interesantes de esta plataforma es la posibilidad de acceder a fuentes de contenido en Internet, como por ejemplo sistemas de gesti\u00f3n de contenidos o blogs. Hay que tener en cuenta que la versi\u00f3n gratuita de esta plataforma solo permite un m\u00e1ximo de cinco de estas fuentes para las aplicaciones desarrolladas.<\/p>\n<p>Por \u00faltimo, la App Cloud Core genera estad\u00edsticas en tiempo real para medir aspectos como el tiempo medio de uso, el n\u00famero de instalaciones o las sesiones abiertas. En definitiva, una plataforma bastante completa para la creaci\u00f3n de apps h\u00edbridas para los dos sistemas m\u00e1s populares del momento, Android e iOS. En caso de necesitar una versi\u00f3n m\u00e1s avanzada, por medio de un pago eso s\u00ed, Brightcove tambi\u00e9n cuenta con las versiones App Cloud Pro y App Cloud Enterprise.<\/p>\n<p><a href=\"http:\/\/www.tuexpertoit.com\/2012\/06\/26\/como-crear-aplicaciones-gratis-para-iphone-y-android\/\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los campos de la tecnolog\u00eda que m\u00e1s relevancia est\u00e1 consiguiendo en los \u00faltimos a\u00f1os es el de las aplicaciones m\u00f3viles, tanto en el segmento de los tel\u00e9fonos m\u00f3viles como en los tablets. Muchos desarrolladores han pasado de programar en lenguajes para PC a aprender Flash o HTML5 para crear aplicaciones que funcionen en esta plataforma, sobre todo en los sistemas operativos m\u00f3viles Android e iOS.&nbsp;Brightcove&nbsp;ha presentado su nueva versi\u00f3n de App Cloud Core, una plataforma gratuita para crear aplicaciones tanto para los smartphones y tablets Android como para el iPhone y el iPad.<\/p>\n","protected":false},"author":3,"featured_media":18256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18257"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18256"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}