{"id":18393,"date":"2012-07-03T16:15:33","date_gmt":"2012-07-03T20:15:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/una-hormona-preserva-la-produccion-de-insulina-y-la-funcion-de-las-celulas-beta-en-la-diabetes\/"},"modified":"2012-07-03T16:15:33","modified_gmt":"2012-07-03T20:15:33","slug":"una-hormona-preserva-la-produccion-de-insulina-y-la-funcion-de-las-celulas-beta-en-la-diabetes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/una-hormona-preserva-la-produccion-de-insulina-y-la-funcion-de-las-celulas-beta-en-la-diabetes\/","title":{"rendered":"Una hormona preserva la producci\u00f3n de insulina y la funci\u00f3n de las c\u00e9lulas beta en la diabetes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18392\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_hormona-preserva-produccion-insulina-funcion-celulas-beta-diabetes_1_1282011.jpg\" width=\"440\" height=\"600\" alt=\"hormona-preserva-produccion-insulina-funcion-celulas-beta-diabetes_1_1282011\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_hormona-preserva-produccion-insulina-funcion-celulas-beta-diabetes_1_1282011.jpg 440w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_hormona-preserva-produccion-insulina-funcion-celulas-beta-diabetes_1_1282011-220x300.jpg 220w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/>Investigadores de la Universidad de Duke, en Estados Unidos, han encontrado funciones anti-diab\u00e9ticas en una hormona que, como la insulina, es producida por las c\u00e9lulas de los islotes del p\u00e1ncreas. La nueva hormona estimula la secreci\u00f3n de insulina en ratas y en humanos, y protege las c\u00e9lulas de los islotes pancre\u00e1ticos en la presencia de t\u00f3xicos. El estudio ha sido publicado en la revista &#8216;Cell Metabolism&#8217;.&nbsp;&nbsp;&nbsp; El nuevo hallazgo proporciona informaci\u00f3n sobre la supervivencia de las c\u00e9lulas beta, un tipo de c\u00e9lulas de los islotes pancre\u00e1ticos que producen insulina para regular los niveles de az\u00facar. As\u00ed, el descubrimiento podr\u00eda abrir v\u00edas para futuras investigaciones hacia la prevenci\u00f3n y el tratamiento de la diabetes tipo 1, y la diabetes tipo 2.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;&nbsp; Los investigadores administraron la hormona, llamada TLQP-21, a ratas Zucker (gen\u00e9ticamente obesas), que poseen una propensi\u00f3n gen\u00e9tica a desarrollar diabetes tipo 2. En los animales tratados con esta hormona, mejoraron los niveles de glucosa y la muerte de c\u00e9lulas beta fue menor.<\/p>\n<p>&nbsp;&nbsp; \u00abEsta es la primera demostraci\u00f3n de que la hormona TLQP-21 evita el deterioro de las c\u00e9lulas beta, y estimula la secreci\u00f3n de insulina en presencia de glucosa\u00bb, se\u00f1ala el autor principal, Christopher B. Newgard, director del Centro de Metabolismo y Nutrici\u00f3n Sarah W. Stedman.<\/p>\n<p>&nbsp;&nbsp; Aunque los investigadores han probado hasta el momento la hormona TLQP-21 solo en modelos de diabetes tipo 2, planean estudiar la hormona en el tipo 1 en futuros estudios. Ambos tipos de diabetes se caracterizan por una p\u00e9rdida de masa funcional de las c\u00e9lulas beta: el tipo 1 es una enfermedad autoinmune caracterizada por la p\u00e9rdida selectiva y progresiva de las c\u00e9lulas beta funcionales que producen insulina, y es m\u00e1s grave; por otro lado, el tipo 2 es una enfermedad caracterizada por la disfunci\u00f3n de las c\u00e9lulas beta, as\u00ed como la resistencia perif\u00e9rica a la insulina. La mayor\u00eda de las personas con diabetes tipo 2, eventualmente, llegan a ser insulinodependientes.<\/p>\n<p>&nbsp;&nbsp; \u00abEstos resultados proporcionan una visi\u00f3n novedosa sobre c\u00f3mo puede ser regulada en el cuerpo la supervivencia de las c\u00e9lulas beta\u00bb, afirma la coautora Patricia Kilian, quien a\u00f1ade que \u00abfuturos estudios pondr\u00e1n a prueba c\u00f3mo afecta esta hormona a la funci\u00f3n de las c\u00e9lulas beta en modelos de diabetes tipo 1\u00bb.<\/p>\n<p>&nbsp;&nbsp; La hormona TLQP-21 es parecida en algunas de sus funciones a otra hormona natural producida en el tracto digestivo, el p\u00e9ptido similar al glucag\u00f3n GLP-1. A trav\u00e9s de diferentes mecanismos, ambas hormonas protegen y promueven la secreci\u00f3n de insulina. Actualmente, el GLP-1, o los f\u00e1rmacos que lo estabilizan, son ampliamente utilizados para tratar la diabetes tipo 2, pero con algunos efectos secundarios, como el aumento del ritmo card\u00edaco, y un reducido vaciado del est\u00f3mago, que han dado lugar a la suspensi\u00f3n del tratamiento en algunas personas.<\/p>\n<p>&nbsp;&nbsp; \u00abLo que interesante es que en los estudios con animales tratados con TLQP-21 no hemos visto estos efectos secundarios\u00bb, afirma el coautor Samuel B. Stephens, quien a\u00f1ade que \u00ablas ratas del estudio comieron una cantidad normal de alimentos, y no mostraron ning\u00fan cambio en la frecuencia card\u00edaca o en los patrones de la digesti\u00f3n cuando se les administr\u00f3 grandes dosis de la hormona\u00bb.<\/p>\n<p> &nbsp;&nbsp; Seg\u00fan los investigadores, el siguiente paso es encontrar una peque\u00f1a mol\u00e9cula que estimule las c\u00e9lulas de los islotes pancre\u00e1ticos que producen la hormona TLQP-21, o desarrollar versiones m\u00e1s potentes y estables de la hormona inyectada. La investigaci\u00f3n para el desarrollo de un f\u00e1rmaco de acci\u00f3n prolongada ayudar\u00e1 a acelerar las pruebas en modelos de diabetes tipo 1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investigadores de la Universidad de Duke, en Estados Unidos, han encontrado funciones anti-diab\u00e9ticas en una hormona que, como la insulina, es producida por las c\u00e9lulas de los islotes del p\u00e1ncreas. La nueva hormona estimula la secreci\u00f3n de insulina en ratas y en humanos, y protege las c\u00e9lulas de los islotes pancre\u00e1ticos en la presencia de t\u00f3xicos. El estudio ha sido publicado en la revista &#8216;Cell Metabolism&#8217;.&nbsp;&nbsp;&nbsp; El nuevo hallazgo proporciona informaci\u00f3n sobre la supervivencia de las c\u00e9lulas beta, un tipo de c\u00e9lulas de los islotes pancre\u00e1ticos que producen insulina para regular los niveles de az\u00facar. As\u00ed, el descubrimiento podr\u00eda abrir v\u00edas para futuras investigaciones hacia la prevenci\u00f3n y el tratamiento de la diabetes tipo 1, y la diabetes tipo 2.<\/p>\n","protected":false},"author":3,"featured_media":18392,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18393"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18392"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}