{"id":18413,"date":"2012-07-04T14:26:00","date_gmt":"2012-07-04T18:26:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/director-regional-norte-de-la-policia-nacional-visita-cuartel-sosua\/"},"modified":"2012-07-04T14:26:00","modified_gmt":"2012-07-04T18:26:00","slug":"director-regional-norte-de-la-policia-nacional-visita-cuartel-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/director-regional-norte-de-la-policia-nacional-visita-cuartel-sosua\/","title":{"rendered":"Director regional Norte de la Polic\u00eda Nacional Visita Cuartel Sos\u00faa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18412\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_0_general_ppp.jpg\" width=\"425\" height=\"346\" alt=\"0_general_ppp\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_0_general_ppp.jpg 425w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_0_general_ppp-300x244.jpg 300w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/>Sos\u00faa. \u2013 Por M\u00e1ximo Reynoso.&nbsp; El director regional Norte de la Polic\u00eda Nacional general de brigada Pablo Roberto Almonte Morales, visito ayer el cuartel policial del municipio de Sos\u00faa para dar instrucciones a todos los miembros de esa instituci\u00f3n en este pueblo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El jefe polic\u00edal de la zona dijo que es una forma de este explicarle a estos agentes que se debe trabajar de la mano con la comunidad y apegados a las leyes.<\/p>\n<p>En tanto el inspector de la polic\u00eda nacional en Sos\u00faa coronel Raymundo de la Rosa Ogando, dijo sentirse satisfecho con esta reuni\u00f3n llevada a cabo por el general Almonte Morales.<\/p>\n<p>En otro orden al ser consultado por periodistas con relaci\u00f3n a la muerte en Sabaneta de Yasica del hacendado Miguel Morales Mart\u00ednez y su hijo&nbsp;&nbsp; el general Almonte Morales explico que contin\u00faan las investigaciones.<\/p>\n<p>Dijo que no descansara hasta dar con el o los responsables de este horrendo hecho.<\/p>\n<p><a href=\"http:\/\/www.cnntv3.tv\/noticias\/index.php\/noticias\/locales\/797-director-regional-norte-de-la-policia-nacional-visita-cuartel-sosua\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa. \u2013 Por M\u00e1ximo Reynoso.&nbsp; El director regional Norte de la Polic\u00eda Nacional general de brigada Pablo Roberto Almonte Morales, visito ayer el cuartel policial del municipio de Sos\u00faa para dar instrucciones a todos los miembros de esa instituci\u00f3n en este pueblo.<\/p>\n","protected":false},"author":3,"featured_media":18412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18413"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18412"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}