{"id":18459,"date":"2012-07-06T12:00:00","date_gmt":"2012-07-06T16:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/fiscalia-de-santiago-cita-a-qlos-teke-tekeq-por-supuesto-plagio\/"},"modified":"2012-07-06T12:00:00","modified_gmt":"2012-07-06T16:00:00","slug":"fiscalia-de-santiago-cita-a-qlos-teke-tekeq-por-supuesto-plagio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fiscalia-de-santiago-cita-a-qlos-teke-tekeq-por-supuesto-plagio\/","title":{"rendered":"Fiscal\u00eda de Santiago cita a \u00abLos Teke Teke\u00bb por supuesto plagio"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18458\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_Los-Teke-Teke.jpeg\" width=\"320\" height=\"238\" alt=\"Los-Teke-Teke\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_Los-Teke-Teke.jpeg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_Los-Teke-Teke-300x223.jpeg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>El Departamento de Investigaciones Especiales y Falsificaciones del Ministerio P\u00fablico de la Procuradur\u00eda Fiscal del Distrito Judicial de Santiago cit\u00f3 para el pr\u00f3ximo 16 de este mes a Rafael Col\u00f3n y Carlos Santana, mejor conocidos como Crazy Design y Carlitos Way (Los Teke Teke).<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>Ambos ser\u00e1n escuchados con relaci\u00f3n a la querella interpuesta en su contra por el se\u00f1or Anyelfry Garc\u00eda Almonte, quien los acusa de reproducir e incluir en una producci\u00f3n discogr\u00e1fica sin su autorizaci\u00f3n su canci\u00f3n \u201cMira como e que t\u00e1\u201d, sin indicar adem\u00e1s que la misma es de su autor\u00eda.&nbsp;<\/div>\n<div><\/div>\n<div>En su querella Almonte sostiene que en el a\u00f1o 2007 escribi\u00f3 la canci\u00f3n \u201cMira como e\u2019 que t\u00e1\u201d, cuya autor\u00eda es reconocida por un certificado de registro expedido por la Oficina Nacional de Derecho de Autor y que en el curso de 2011, los imputados la reprodujeron e incluyeron en una producci\u00f3n fonogr\u00e1fica sin su consentimiento y sin hacer referencia a su paternidad.&nbsp;<\/div>\n<div><\/div>\n<div>De acuerdo al sitio Gentetuya.com, los int\u00e9rpretes de \u201cEl Teke Teke\u201d y \u201cHasta a ti te doy\u201d podr\u00edan enfrentar una pena de tres a\u00f1os de prisi\u00f3n, una multa de mil salarios m\u00ednimos y el pago de una indemnizaci\u00f3n de RD$2 millones por los da\u00f1os y perjuicios causados.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/fuegoalalata.blogspot.com\/2012\/07\/fiscalia-de-santiago-cita-los-teke-teke.html?utm_source=feedburner&amp;utm_medium=feed&amp;utm_campaign=Feed%253A+Fuegoalalatanet+(Fuegoalalata.net)\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Investigaciones Especiales y Falsificaciones del Ministerio P\u00fablico de la Procuradur\u00eda Fiscal del Distrito Judicial de Santiago cit\u00f3 para el pr\u00f3ximo 16 de este mes a Rafael Col\u00f3n y Carlos Santana, mejor conocidos como Crazy Design y Carlitos Way (Los Teke Teke).<\/p>\n","protected":false},"author":3,"featured_media":18458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18459"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18458"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}