{"id":18491,"date":"2012-07-07T14:57:53","date_gmt":"2012-07-07T18:57:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/hotel-sosua-bay-paga-prestaciones-a-ex-empleados\/"},"modified":"2012-07-07T14:57:53","modified_gmt":"2012-07-07T18:57:53","slug":"hotel-sosua-bay-paga-prestaciones-a-ex-empleados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hotel-sosua-bay-paga-prestaciones-a-ex-empleados\/","title":{"rendered":"HOTEL SOSUA BAY PAGA PRESTACIONES A EX EMPLEADOS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18490\" style=\"float: left;\" alt=\"sosua-bay\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_sosua-bay.jpg\" width=\"400\" height=\"311\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_sosua-bay.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_sosua-bay-300x233.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>El Hotel Sosua Bay, procedi\u00f3 a pagar las prestaciones laborales a los ex empleados de esa empresa.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La informaci\u00f3n la ofreci\u00f3 la licenciada Anny Infante, quien dijo que unos 123 empleados recibieron cerca de diez millones de pesos, por sus prestaciones laborales.<\/p>\n<p>La licenciada Infante agradeci\u00f3 al empresario Armando Casiatti, propietario del hotel Sosua Bay, el haber honrado el compromiso con los ex trabajadores del referido hotel.<\/p>\n<p>Hacemos de conocimiento p\u00fablico que la deuda de prestaciones pagada no fueron contraida por las empresas Casiatti, sino por un consorcio ajeno a los propietarios de Sosua Bay. Por lo que ha sido una medida honorable el saldo de estos empleados.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Hotel Sosua Bay, procedi\u00f3 a pagar las prestaciones laborales a los ex empleados de esa empresa.<\/p>\n","protected":false},"author":3,"featured_media":18490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18491"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18490"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}