{"id":18597,"date":"2012-07-11T19:17:08","date_gmt":"2012-07-11T23:17:08","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/nota-luctuosa-ha-fallecido-nuestro-querido-profesor-jose-morel\/"},"modified":"2012-07-11T19:17:08","modified_gmt":"2012-07-11T23:17:08","slug":"nota-luctuosa-ha-fallecido-nuestro-querido-profesor-jose-morel","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nota-luctuosa-ha-fallecido-nuestro-querido-profesor-jose-morel\/","title":{"rendered":"NOTA LUCTUOSA: Ha fallecido nuestro querido Profesor JOSE MOREL"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18596\" style=\"float: left;\" alt=\"Jose_morel\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_sosua1315443583_Jose_morel.jpg\" width=\"358\" height=\"314\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_sosua1315443583_Jose_morel.jpg 358w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_sosua1315443583_Jose_morel-300x263.jpg 300w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/>Falleci\u00f3 este mi\u00e9rcoles 11 de Julio del 2012, nuestro querido profesor JOSE (EL CHEPE) MOREL, ilustre mestro de la letras y la literatura, nacido en otro municipio, pero hijo honorable de Sos\u00faa, por todos los aportes en la formaci\u00f3n de todos sus alumnos que hoy nos vemos unidos a sus seres queridos en el dolor de su partida, pero a la vez sentimos tranquilidad, porque sabemos que est\u00e1 al lado de nuestro Dios creador.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El staff de Sosuaonline.net siente mucho y acompa\u00f1a en su dolor a su esposa FELLA, hijos JOSELITO Y JOSEP, dem\u00e1s familiares y amigos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falleci\u00f3 este mi\u00e9rcoles 11 de Julio del 2012, nuestro querido profesor JOSE (EL CHEPE) MOREL, ilustre mestro de la letras y la literatura, nacido en otro municipio, pero hijo honorable de Sos\u00faa, por todos los aportes en la formaci\u00f3n de todos sus alumnos que hoy nos vemos unidos a sus seres queridos en el dolor de su partida, pero a la vez sentimos tranquilidad, porque sabemos que est\u00e1 al lado de nuestro Dios creador.<\/p>\n","protected":false},"author":3,"featured_media":18596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18597"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18596"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}