{"id":18605,"date":"2012-07-12T15:28:59","date_gmt":"2012-07-12T19:28:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-moviles-danan-el-cerebro-de-las-hormigas-segun-un-estudio\/"},"modified":"2012-07-12T15:28:59","modified_gmt":"2012-07-12T19:28:59","slug":"los-moviles-danan-el-cerebro-de-las-hormigas-segun-un-estudio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-moviles-danan-el-cerebro-de-las-hormigas-segun-un-estudio\/","title":{"rendered":"Los m\u00f3viles da\u00f1an el cerebro de las hormigas, seg\u00fan un estudio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18604\" style=\"float: left;\" class=\"caption\" alt=\"Dos-hormigas-en-una-hoja-300x251\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_Dos-hormigas-en-una-hoja-300x251.jpg\" width=\"300\" height=\"251\" \/>Un experimento sugiere que las ondas que emiten los terminales perjudican sus capacidades de memoria y orientaci\u00f3n, de forma que son incapaces de encontrar el camino de regreso al hormiguero.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Si usted se preguntaba por qu\u00e9 las hormigas no usan tel\u00e9fonos m\u00f3viles, la Universidad Libre de Bruselas ha dado con la respuesta: las ondas que emiten les da\u00f1an gravemente el cerebro y perjudican sus capacidades olfativas, visuales y los mecanismos de aprendizaje. El estudio, realizado por un equipo dirigido por la profesora Marie-Claire Cammaerts ha sido publicado por la revista \u201cElectromagnetic Biology and Medicine\u201d y aunque no est\u00e1 claro que las conclusiones puedan aplicarse a los seres humanos, demuestra que puede haber una relaci\u00f3n entre las ondas electromagn\u00e9ticas y ciertos efectos negativos en mecanismos neurol\u00f3gicos.<\/p>\n<p>Las hormigas que fueron sometidas a una exposici\u00f3n a las ondas similares a las de los tel\u00e9fonos m\u00f3viles perdieron m\u00e1s de un 50 por ciento de sus capacidades de orientaci\u00f3n y memorizaci\u00f3n, algo esencial para la organizaci\u00f3n de los hormigueros. Los efectos no son irreversibles, ya que al cabo de 30 horas las mismas hormigas recuperaban parte de sus capacidades, aunque seg\u00fan el estudio, nunca completamente.<\/p>\n<p>La experiencia consist\u00eda en atraer a un grupo de hormigas hacia un lugar donde encontraban comida, a trav\u00e9s de las feromonas, sustancias bien conocidas que sirven a estos insectos para orientarse a trav\u00e9s del olfato. Normalmente, las hormigas son capaces de seguir el rastro del camino de vuelta al hormiguero con la comida a cuestas y el resto de las hormigas puede orientarse por la misma ruta para repetir el trayecto tantas veces como sea necesario. Sin embargo, sometidas a una exposici\u00f3n de una frecuencia de 900 megahercios y una potencia de 2 watios, muy inferior a la de una antena de un tel\u00e9fono ordinario, las hormigas perd\u00edan el camino y eran incapaces de orientarse, a pesar de que ya conoc\u00edan el trayecto.<\/p>\n<p><strong>Catastr\u00f3fico en una colmena<\/strong><\/p>\n<p>Seg\u00fan la profesora Cammaerts, las ondas \u201cafectan a la membrana celular, lo que tiene consecuencias sobre el sistema nervioso\u201d y a su juicio en el caso de los insectos puede afectar directamente el desarrollo larvario y las neurosecreciones. En concreto, ella hubiera querido investigar sobre las abejas, pero \u201cno he sido autorizada, cuando se sabe que si se coloca un tel\u00e9fono m\u00f3vil en la colmena, se produce una cat\u00e1strofe\u201d. En su opini\u00f3n, \u201cel mundo no puede vivir ya sin los aparatos que funcionan con ondas electromagn\u00e9ticas, pero creo que har\u00edamos bien en aumentar las precauciones sobre las emisiones de las antenas.<\/p>\n<p><a href=\"http:\/\/www.cachicha.com\/2012\/07\/los-moviles-danan-el-cerebro-de-las-hormigas-segun-un-estudio\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un experimento sugiere que las ondas que emiten los terminales perjudican sus capacidades de memoria y orientaci\u00f3n, de forma que son incapaces de encontrar el camino de regreso al hormiguero.<\/p>\n","protected":false},"author":3,"featured_media":18604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-18605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18605"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18604"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}