{"id":18669,"date":"2012-07-14T18:00:00","date_gmt":"2012-07-14T22:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/un-compuesto-que-se-extrae-del-olivo-podria-actuar-contra-el-virus-del-sida\/"},"modified":"2012-07-14T18:00:00","modified_gmt":"2012-07-14T22:00:00","slug":"un-compuesto-que-se-extrae-del-olivo-podria-actuar-contra-el-virus-del-sida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-compuesto-que-se-extrae-del-olivo-podria-actuar-contra-el-virus-del-sida\/","title":{"rendered":"Un compuesto que se extrae del olivo podr\u00eda actuar contra el virus del sida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18668\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_1342005710_0.jpg\" width=\"650\" height=\"433\" alt=\"1342005710_0\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_1342005710_0.jpg 650w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_1342005710_0-300x199.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>Un proyecto europeo liderado por el Instituto de Salud Carlos&nbsp;III&nbsp;(Espa\u00f1a) probar\u00e1&nbsp;<strong>si un compuesto que se extrae del olivo tiene propiedades que podr\u00edan frenar la acci\u00f3n del virus del sida<\/strong>, evaluando si esta mol\u00e9cula es eficaz en animales, sentando las bases para realizar ensayos cl\u00ednicos en humanos.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El aceite de oliva no solo tiene innumerables propiedades beneficiosas, sino que tambi\u00e9n contiene peque\u00f1as cantidades de&nbsp;<strong>hydroxytyrosol<\/strong>, el m\u00e1s potente antioxidante natural que se conoce hasta ahora. La empresa biotecnol\u00f3gica espa\u00f1ola Seprox ha sido la encargada de descubrir un mecanismo que permite sintetizarla f\u00e1cilmente (y a un coste asequible) en el laboratorio para emplear un derivado qu\u00edmico (y no el compuesto natural directamente), y se piensa que pudiera tener efectividad como agente antiinflamatorio y antiviral, tal y como explica&nbsp;<strong>Jos\u00e9 Alcam\u00ed<\/strong>, coordinador del proyecto:<\/p>\n<blockquote><p>Se trata de una sustancia totalmente nueva y pionera tanto por su mecanismo de acci\u00f3n como por su estructura qu\u00edmica molecular. Combina dos mecanismos diferentes frente al VIH: la actividad antiviral directa y la antiinflamatoria; esta \u00faltima reduce la capacidad del virus para infectar los linfocitos en las mucosas.<\/p><\/blockquote>\n<p>La mol\u00e9cula podr\u00eda convertirse en una nueva alternativa terap\u00e9utica para combatir el&nbsp;VIH&nbsp;que se emplear\u00eda en zonas en las que por el contexto social el uso del preservativo no es generalizado.<\/p>\n<p><a href=\"http:\/\/www.xatakaciencia.com\/salud\/un-compuesto-que-se-extrae-del-olivo-podria-actuar-contra-el-virus-del-sida\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un proyecto europeo liderado por el Instituto de Salud Carlos&nbsp;III&nbsp;(Espa\u00f1a) probar\u00e1&nbsp;si un compuesto que se extrae del olivo tiene propiedades que podr\u00edan frenar la acci\u00f3n del virus del sida, evaluando si esta mol\u00e9cula es eficaz en animales, sentando las bases para realizar ensayos cl\u00ednicos en humanos.<\/p>\n","protected":false},"author":3,"featured_media":18668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18669"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18668"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}