{"id":18686,"date":"2012-07-15T15:29:51","date_gmt":"2012-07-15T19:29:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/nota-luctuosa-ha-fellecido-bernardo-quintana-la-mala-palabra-de-felicia\/"},"modified":"2012-07-15T15:29:51","modified_gmt":"2012-07-15T19:29:51","slug":"nota-luctuosa-ha-fellecido-bernardo-quintana-la-mala-palabra-de-felicia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nota-luctuosa-ha-fellecido-bernardo-quintana-la-mala-palabra-de-felicia\/","title":{"rendered":"NOTA LUCTUOSA: HA FALLECIDO BERNARDO QUINTANA (EL G. DE FELICIA)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18685\" style=\"float: left;\" alt=\"Bernando_Quinta_El_Huevo_de_Felicia_-_Fallecido_14-07-2012\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_sosua1315443583_Bernando_Quinta_El_Huevo_de_Felicia_-_Fallecido_14-07-2012.jpg\" width=\"516\" height=\"440\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_sosua1315443583_Bernando_Quinta_El_Huevo_de_Felicia_-_Fallecido_14-07-2012.jpg 516w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_sosua1315443583_Bernando_Quinta_El_Huevo_de_Felicia_-_Fallecido_14-07-2012-300x255.jpg 300w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/>Bronx, NY.- Ha &nbsp;fallecido en una accidente tr\u00e1gica en la madrugada de este s\u00e1bado 14 de julio del 2012, en el Bronx de New York el sosuense, <strong>BERNARDO QUINTANA<\/strong>, m\u00e1s bien conocido como \u00ab<strong>El G. de Felicia<\/strong>\u201d, el cual fue uno de los grandes pitcher de Softbol de la zona en la d\u00e9cada de los 90\u2019s. Bernardo es hijo de Felicia Quintana, era oriundo de Loma Bajita, Sos\u00faa&nbsp;y siempre se caracteriz\u00f3 por ser un hombre de trabajo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Bernardo se dio conocer en la d\u00e9cada de los 90\u2019s cuando clubes como: Cobra, Bronco, Los Castillo y Casa Blanca hicieron de Sos\u00faa un pueblo de grandes luminarias y \u00e9l era uno de los pitcher dominante en el mont\u00edculo del softbol.<\/p>\n<p>Sosuaonline.net se une a la pena de la familia y amigos por la perdida de este hombre de bien y deportistas ido a destiempo. PAZ A SU ALMA! &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bronx, NY.- Ha &nbsp;fallecido en una accidente tr\u00e1gica en la madrugada de este s\u00e1bado 14 de julio del 2012, en el Bronx de New York el sosuense, BERNARDO QUINTANA, m\u00e1s bien conocido como \u00abEl G. de Felicia\u201d, el cual fue uno de los grandes pitcher de Softbol de la zona en la d\u00e9cada de los 90\u2019s. Bernardo es hijo de Felicia Quintana, era oriundo de Loma Bajita, Sos\u00faa&nbsp;y siempre se caracteriz\u00f3 por ser un hombre de trabajo.<\/p>\n","protected":false},"author":3,"featured_media":18685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18686"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18685"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}