{"id":18881,"date":"2012-07-23T16:38:10","date_gmt":"2012-07-23T20:38:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-cancer-es-tercera-causa-de-muertes-entre-dominicanos\/"},"modified":"2012-07-23T16:38:10","modified_gmt":"2012-07-23T20:38:10","slug":"el-cancer-es-tercera-causa-de-muertes-entre-dominicanos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-cancer-es-tercera-causa-de-muertes-entre-dominicanos\/","title":{"rendered":"El c\u00e1ncer es tercera causa de muertes entre dominicanos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18880\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_41392e788971fbcdbcdc7fcda8e1ed02_300x226.jpg\" width=\"300\" height=\"226\" alt=\"41392e788971fbcdbcdc7fcda8e1ed02_300x226\" class=\"caption\" style=\"float: left;\" \/>La enfermedad, que se cre\u00eda era de la vejez, principalmente, ahora ataca a miles de j\u00f3venes y ni\u00f1os por factores hereditarios y malos h\u00e1bitos de vida.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>La incidencia del c\u00e1ncer en Rep\u00fablica Dominicana es cada vez mayor en los distintos segmentos sociales, constituy\u00e9ndose en la tercera causa de muerte, al punto de que 15 de cada 100 fallecimientos son atribuidos a esta enfermedad.&nbsp;<\/p>\n<p>Esta patolog\u00eda se caracteriza por un conjunto de enfermedades que tienen su origen en el crecimiento descontrolado de c\u00e9lulas&nbsp; anormales que, en muchos casos se presentan con tumoraciones, es una de las principales causas de muerte del mundo.<\/p>\n<p>De acuerdo con un estudio de la Agencia de Salud de la Rep\u00fablica Dominicana y Centroam\u00e9rica 2008 -2017, poco m\u00e1s de&nbsp; 32 mil personas mueren cada a\u00f1o&nbsp; de distintos tipos de c\u00e1nceres en el pa\u00eds y Am\u00e9rica Central.&nbsp; Hasta hace tres a\u00f1os, 51 mil 724 fueron diagnosticados como nuevos casos.<\/p>\n<p>Organismos de salud internacionales pronostican que de continuar la tendencia en la incidencia de la enfermedad, para el 2020 en el mundo habr\u00eda, al menos, 15 millones de nuevos casos&nbsp; de c\u00e1ncer.&nbsp;<\/p>\n<p>Su incremento en el pa\u00eds es tan frecuente que las autoridades de salud la consideran como una de las enfermedades m\u00e1s preocupantes, y para diagnosticarla y darle seguimiento, se cre\u00f3 hace tres a\u00f1os la Comisi\u00f3n Nacional de Prevenci\u00f3n y Control del C\u00e1ncer, integrada&nbsp; por 19 instituciones oficiales y de la sociedad civil.&nbsp;<\/p>\n<p>El doctor Alexis Yadir Ram\u00edrez, onc\u00f3logo e investigador, afirma que, ciertamente, en el pa\u00eds hay un mayor n\u00famero de pacientes diagnosticados con c\u00e1ncer, pero entiende que hay que tomar en cuenta que tambi\u00e9n se ha registrado un aumento de la poblaci\u00f3n en general y por eso se ven m\u00e1s casos.&nbsp;<\/p>\n<p>\u201cEs que somos m\u00e1s personas a lo largo del tiempo, o sea, en los a\u00f1os de 1940&nbsp; nosotros&nbsp; ten\u00edamos una poblaci\u00f3n dominicana equis, quiz\u00e1s nos hemos duplicado en cuanto a la poblaci\u00f3n y por ende hemos multiplicado el n\u00famero de c\u00e1ncer que se presenta, o sea las tasas se mantienen\u201d, precisa.<\/p>\n<p><strong>El origen<\/strong><\/p>\n<p>Los or\u00edgenes del c\u00e1ncer son diversos y van desde malos h\u00e1bitos alimenticios y sedentarismo hasta, factores hereditarios. Para mucha gente el factor hereditario es la principal causa de la frecuencia de c\u00e1nceres en el pa\u00eds, pero&nbsp; como dice el doctor Ram\u00edrez, el porcentaje no es grande.<\/p>\n<p>&nbsp;\u201cLa mayor\u00eda de la gente cree que el c\u00e1ncer es hereditario, que si un familiar tuyo tuvo c\u00e1ncer, tu lo puedes tener. Ciertamente hay un 10% de todos los c\u00e1nceres que son gen\u00e9ticos, en el sentido hereditario\u201d.<\/p>\n<p>Otros investigadores aseguran que s\u00f3lo el 5% de los distintos tipos de c\u00e1ncer son heredados por familiares.<\/p>\n<p>Ram\u00edrez afirma que la mayor\u00eda de los c\u00e1nceres son adquiridos por estilos de vida. \u201cMe refiero a c\u00e1ncer de cabeza y cuello, d\u00edgase c\u00e1ncer de lengua, boca, laringe y faringe, se sabe que la exposici\u00f3n al alcohol y al tabaco, favorece la aparici\u00f3n del c\u00e1ncer de cabeza y cuello\u201d, dice.<\/p>\n<p><strong>Todos expuestos<\/strong>&nbsp;<\/p>\n<p>El especialista en prevenci\u00f3n y tratamiento del c\u00e1ncer dijo que&nbsp; hist\u00f3ricamente se ha caracterizado como una enfermedad de la vejez, en personas longevas, pero que su incidencia aumenta en j\u00f3venes y hasta en ni\u00f1os, aunque en esta \u00faltima etapa los casos son menores.<\/p>\n<p>El profesional de la salud asegura que siempre ha existido el c\u00e1ncer en la ni\u00f1ez y por eso es que existe la especialidad en oncolog\u00eda pedi\u00e1trica y a pesar de que&nbsp; son c\u00e1nceres que no&nbsp; se mencionan&nbsp; muy com\u00fanmente por la naturaleza del mismo, si han existido siempre.<\/p>\n<p>\u201cLos c\u00e1nceres de la ni\u00f1ez se presentan a nivel del sistema nervioso central, a nivel de la sangre, ya sea leucemia o linfomas; a nivel de v\u00edas urinarias, especialmente el ri\u00f1\u00f3n y estos casos generalmente se deben a alteraciones a nivel de la v\u00eda intrauterina, y exposici\u00f3n a factores dentro del desarrollo embrionario\u201d, explica.<\/p>\n<p>El c\u00e1ncer de mama es el m\u00e1s frecuente en las mujeres dominicanas, sin importar que sean j\u00f3venes o adultas, pero tambi\u00e9n existe una alta incidencia de la enfermedad en la c\u00e9rvix y tambi\u00e9n en el colon, de acuerdo a estad\u00edsticas.<\/p>\n<p>En el caso de los hombres j\u00f3venes o adultos&nbsp; mayores los m\u00e1s comunes son de pr\u00f3stata y el colon. Mientras que los que afectan la cabeza y el cuello como el c\u00e1ncer de lengua, labios, faringe y laringe son frecuentes tanto en hombres como en&nbsp; mujeres.<\/p>\n<p>El doctor Ram\u00edrez indica&nbsp; que los casos de c\u00e1ncer en las diferentes ramas,&nbsp; como el que afecta a la ni\u00f1ez, no es el mismo que se&nbsp; presenta generalmente&nbsp; en la etapa adulta, y en ese sentido hay que dividir a los pacientes y su incidencia en los diferentes grupos sectarios y cit\u00f3 como ejemplo el grupo del c\u00e1ncer infantil o pedi\u00e1trico.<\/p>\n<p>Hay controversia sobre eso porque el Fondo de las Naciones Unidas para al Infancia (UNICEF) tiene una edad para definir cu\u00e1ndo es pedi\u00e1trico.&nbsp;<\/p>\n<p>Hay hospitales que lo consideran hasta los 18 a\u00f1os y otros hasta los 14 a\u00f1os, pero existe una nueva categor\u00eda para los adolescentes que va desde los 15 hasta los 19 a\u00f1os. Tambi\u00e9n se ha definido una categor\u00eda de adulto joven que es la que abarca a las personas con edades entre los 20 a 39 a\u00f1os, y de adulto que&nbsp; van desde los 40&nbsp; hasta los 60 a\u00f1os.<\/p>\n<p><strong>En citas<\/strong><\/p>\n<p>\u00abLa mayor\u00eda de gente cree que el c\u00e1ncer es hereditario, que si un familiar tuvo c\u00e1ncer, tu lo puedes tener\u201d.<\/p>\n<p>\u00abLos c\u00e1nceres en la ni\u00f1ez se presentan a nivel del sistema nervioso central y a nivel de la sangre\u201d.<\/p>\n<p><a href=\"http:\/\/www.elcaribe.com.do\/2012\/07\/23\/incidencia-tipos-cancer-aumento-pais\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La enfermedad, que se cre\u00eda era de la vejez, principalmente, ahora ataca a miles de j\u00f3venes y ni\u00f1os por factores hereditarios y malos h\u00e1bitos de vida.<\/p>\n","protected":false},"author":3,"featured_media":18880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18881"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18880"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}