{"id":18948,"date":"2012-07-26T16:57:05","date_gmt":"2012-07-26T20:57:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/red-twitter-se-cae-otra-vez\/"},"modified":"2012-07-26T16:57:05","modified_gmt":"2012-07-26T20:57:05","slug":"red-twitter-se-cae-otra-vez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/red-twitter-se-cae-otra-vez\/","title":{"rendered":"Red Twitter se cae otra vez"},"content":{"rendered":"<article itemscope=\"\" itemtype=\"http:\/\/schema.org\/Article\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18947\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_45e0bab7f15b2c5153b7ca47015a115e_300x226.jpg\" width=\"300\" height=\"226\" alt=\"45e0bab7f15b2c5153b7ca47015a115e_300x226\" title=\"Es la segunda vez que deja de funcionar en menos de un mes\" style=\"float: left;\" \/>Usuarios de la red social Twitter han reportado este jueves problemas para acceder y usar su cuenta. La ca\u00edda de la red fue confirmada por la compa\u00f1\u00eda.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La web Twitter Status anunci\u00f3 que su servicio dej\u00f3 de&nbsp; funcionar este jueves para casi todos los usuarios en el mundo. Pa\u00edses comGran Breta\u00f1a, Estados Unidos, jap\u00f3n y Johannesburgo reportaron problemas para entrar a la p\u00e1gina.<\/p>\n<p>\u201cLos usuarios pueden estar experimentando problemas para acceder a Twitter. Nuestros ingenieros est\u00e1n trabajando para resolver este problema\u201d, subray\u00f3 la compa\u00f1\u00eda.<\/p>\n<p>Tampoco est\u00e1n funcionando las aplicaciones para Twitter, como la versi\u00f3n web, la cual no responde y las APIs aparecen desconectadas.<\/p>\n<p>Aunque el servidor indic\u00f3 que \u201cel problema fue resuelto y todos los servicios est\u00e1n operando\u201d, aun en el pa\u00eds el servicio no ha sido restablecido por completo.<\/p>\n<p>El pasado 21 de junio Twitter report\u00f3 fallas en sus servicios aunque no precis\u00f3 la gravedad de la aver\u00eda ni el n\u00famero de usuarios afectados.<\/p>\n<p><a href=\"http:\/\/www.elcaribe.com.do\/2012\/07\/26\/red-twitter-cae-otra-vez\">fuente<\/a><\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Usuarios de la red social Twitter han reportado este jueves problemas para acceder y usar su cuenta. La ca\u00edda de la red fue confirmada por la compa\u00f1\u00eda.<\/p>\n","protected":false},"author":3,"featured_media":18947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18948"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18947"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}