{"id":18950,"date":"2012-07-26T17:12:14","date_gmt":"2012-07-26T21:12:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/uasd-expulsara-estudiantes-que-tengan-mas-8-anos-en-una-carrera\/"},"modified":"2012-07-26T17:12:14","modified_gmt":"2012-07-26T21:12:14","slug":"uasd-expulsara-estudiantes-que-tengan-mas-8-anos-en-una-carrera","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/uasd-expulsara-estudiantes-que-tengan-mas-8-anos-en-una-carrera\/","title":{"rendered":"UASD expulsar\u00e1 estudiantes que tengan m\u00e1s 8 a\u00f1os en una carrera"},"content":{"rendered":"<article itemscope=\"\" itemtype=\"http:\/\/schema.org\/Article\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18949\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_UASD1.jpg\" width=\"254\" height=\"229\" alt=\"UASD1\" style=\"float: left;\" \/>El rector de la UASD inform\u00f3 que solicit\u00f3 al Departamento de Registro de esa academia el listado de los estudiantes que tienen m\u00e1s de ocho a\u00f1os cursando una carrera.Mateo Aquino Febrillet dijo que con ello busca analizar la situaci\u00f3n de estos estudiantes y determinar cu\u00e1les deben quedarse&nbsp; en la instituci\u00f3n. La medida se acoge a las sugerencias hechas por la ministra de Educaci\u00f3n Superior, Ligia Amada Melo, de que sean expulsados de la UASD estudiantes que tienen hasta 15 a\u00f1os en la academia y que esos espacios sean cedidos a quienes quieren estudiar.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Febrillet anunci\u00f3 la medida durante una asamblea informativa con profesores de la academia, en la que ofreci\u00f3 detalles sobre diferentes aspectos, incluyendo su posici\u00f3n en relaci\u00f3n a los disturbios escenificados el pasado viernes que llevaron a paralizar las labores por cuatro d\u00edas, y que lo oblig\u00f3 a recurrir a la fuerza p\u00fablica. Neg\u00f3 que durante la intervenci\u00f3n de los miembros de la Polic\u00eda se hayan cometido excesos.<\/p>\n<p><a href=\"http:\/\/www.elcaribe.com.do\/2012\/07\/26\/revisaran-casos-estudiantes-con-mas-8-anos\">fuente<\/a><\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>El rector de la UASD inform\u00f3 que solicit\u00f3 al Departamento de Registro de esa academia el listado de los estudiantes que tienen m\u00e1s de ocho a\u00f1os cursando una carrera.Mateo Aquino Febrillet dijo que con ello busca analizar la situaci\u00f3n de estos estudiantes y determinar cu\u00e1les deben quedarse&nbsp; en la instituci\u00f3n. La medida se acoge a las sugerencias hechas por la ministra de Educaci\u00f3n Superior, Ligia Amada Melo, de que sean expulsados de la UASD estudiantes que tienen hasta 15 a\u00f1os en la academia y que esos espacios sean cedidos a quienes quieren estudiar.&nbsp;<\/p>\n","protected":false},"author":3,"featured_media":18949,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18950"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18949"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}