{"id":19006,"date":"2012-07-28T15:26:03","date_gmt":"2012-07-28T19:26:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-soledad-causa-serios-problemas-de-salud-en-adultos-mayores\/"},"modified":"2012-07-28T15:26:03","modified_gmt":"2012-07-28T19:26:03","slug":"la-soledad-causa-serios-problemas-de-salud-en-adultos-mayores","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-soledad-causa-serios-problemas-de-salud-en-adultos-mayores\/","title":{"rendered":"La soledad causa serios problemas de salud en adultos mayores"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19005\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_120710203924_sp_anciana_304x171_spl.jpg\" width=\"304\" height=\"171\" alt=\"120710203924_sp_anciana_304x171_spl\" class=\"caption\" style=\"float: left;\" title=\"Estudios indican que si el problema de la soledad no es abordada urgentemente podr\u00eda convertirse en un grave factor de salud p\u00fablica.\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_120710203924_sp_anciana_304x171_spl.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_120710203924_sp_anciana_304x171_spl-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>\u00abNing\u00fan hombre es una isla completamente, es un pedazo de continente, una parte del todo\u00bb, escribi\u00f3 el poeta John Donne en el siglo XVII para referirse a la soledad y la nostalgia.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Algunas personas buscan vivir aisladas, pero pocas eligen estar solas. Y es sencillamente porque no lo vemos como algo bueno.<\/p>\n<div>\n<div>\n<div>\n<p><a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2012\/07\/120710_soledad_vejez_jd.shtml#more-contextual-links\"><\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>Varios estudios se\u00f1alan que la soledad no es s\u00f3lo un problema de infelicidad. Incide en la mortalidad.<\/p>\n<p>Tambi\u00e9n est\u00e1 asociada con el deterioro de la salud mental y m\u00e1s sorprendentemente a enfermedades cardiovasculares, hipertensi\u00f3n y demencia.<\/p>\n<p>La soledad es un problema de salud p\u00fablica que debe ser tratado con urgencia, seg\u00fan afirma Laura Ferguson, directora de la organizaci\u00f3n Campaing to End Loneliness (Campa\u00f1a para terminar con la soledad) con sede en el Reino Unido, que se encarga de combatir el problema en ese pa\u00eds.<\/p>\n<p>\u00abSe ha encontrado que existe un v\u00ednculo con la muerte temprana. El factor de riesgo es similar a fumar y peor que la obesidad\u00bb.<\/p>\n<h2>Llegar a la vejez trae m\u00e1s soledad<\/h2>\n<p>Con el crecimiento de la poblaci\u00f3n de adultos mayores se estima que para los pr\u00f3ximos a\u00f1os la soledad se puede convertir en un problema m\u00e1s grave.<\/p>\n<p>David McCullough, presidente de la organizaci\u00f3n Women\u2019s Royal Voluntary Service, que tiene a m\u00e1s de 40.000 voluntarios apoyando a adultos mayores en Reino Unido, asegura que el problema de la soledad se est\u00e1 extendiendo.<\/p>\n<p>\u00abTratamos a personas desamparadas, mayormente poblaciones de adultos mayores que sufren enfermedades y p\u00e9rdida de movilidad\u00bb.<\/p>\n<p>\u00abCuando les llevamos comida hay mucha de esta gente en la puerta, esperando por nosotros, por una visita de otro ser humano. Es su momento social del d\u00eda\u00bb.<\/p>\n<p>Estudios en el Reino Unido llevados a cabo en las \u00faltimas d\u00e9cadas muestran de manera consistente que los adultos mayores se sienten solos o muy solos.<\/p>\n<p>Se estima que m\u00e1s de un mill\u00f3n de personas mayores de 65 a\u00f1os siempre dice sentirse sola.<\/p>\n<p>La organizaci\u00f3n Campaing to End Loneliness indica que la mitad de todos los adultos mayores, unos 5 millones, afirman que la televisi\u00f3n es su principal compa\u00f1\u00eda.<\/p>\n<div>\n<div>\n<div>\n<div>\n<blockquote>\n<p>\u00abEl principal factor que asegura una buena calidad de vida es tener relaciones sociales\u00bb<\/p>\n<\/blockquote>\n<div>\n<div>\n<p>Christina Victor, profesora de la Universidad Brunel.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>El 10% de estas cifras ha permanecido estable en los \u00faltimos 60 a\u00f1os.<\/p>\n<p>La profesora Christina Victor, de la Universidad Brunel, quien ha realizado una gran cantidad de investigaciones ligadas a la soledad al final de la vida, dice que los datos sobre la soledad y los problemas de salud son muy sorprendentes.<\/p>\n<p>\u00abNo hay evidencia alguna de que el problema de la soledad es m\u00e1s grave ahora que en a\u00f1os anteriores, a pesar de los cambios que ha experimentado la familia y el hecho de que ahora mucha m\u00e1s gente vive sola\u00bb, dice Victor, pero a\u00f1ade que reducir el problema de la soledad definitivamente tendr\u00e1 un efecto beneficioso para la salud.<\/p>\n<p>\u00abEl principal factor que asegura una buena calidad de vida es tener relaciones sociales\u00bb.<\/p>\n<p>Sin embargo, la soledad no solo afecta a personas mayores de 65 a\u00f1os. Tambi\u00e9n incide en j\u00f3venes entre los 18 y los 24 a\u00f1os.<\/p>\n<p>Mientras la soledad en los adultos mayores puede generarse por problemas de salud o la p\u00e9rdida de la pareja, en el caso de los j\u00f3venes se puede producir a consecuencia de la p\u00e9rdida del empleo, irse de la casa o tener un beb\u00e9.<\/p>\n<p>\u00abLa soledad es la diferencia que existe entre el deseo de contactar a la gente y las relaciones que en realidad uno tiene\u00bb, afirma la profesora Vanessa Burholt, del Centre of Innovative Ageing de la Universidad Swansea.<\/p>\n<p>\u00abEsto explica el porqu\u00e9 algunas personas con muchas amistades se sienten solas. Es algo subjetivo\u00bb.<\/p>\n<h2>Herramientas<\/h2>\n<p>Los estudios de la profesora Burholt sobre las formas en que la gente termina viviendo en soledad sugieren que nuestro ambiente y salud mental pueden impactar las percepciones en las relaciones sociales.<\/p>\n<p>\u00abA las personas que sufren de depresi\u00f3n se les hace m\u00e1s duro cambiar su percepci\u00f3n a nivel personal acerca de las relaciones que necesitan. Adem\u00e1s no tienen la capacidad de ajustarse\u00bb.<\/p>\n<div>\n<div> <\/p>\n<p>Los j\u00f3venes entre 18 y 24 a\u00f1os tambien estan proclives a sufrir de soledad.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>El ministro de Servicios de Salud del Reino Unido, Paul Burstow, dice que la sociedad necesita enfrentar este problema.<\/p>\n<p>\u00abLa soledad puede dejar un impacto muy significativo en la salud de las personas y a diferencia de riegos como el alcoholismo y la obesidad, la soledad no est\u00e1 siendo tratada\u00bb.<\/p>\n<p>Las buenas noticias son que las personas pueden recuperarse del problema que genera la soledad, no es una condici\u00f3n de por vida. La gente tiende a seguir adelante y salir de la soledad en diferentes etapas de su vida.<\/p>\n<p>Servicios que ofrecen amistades pueden funcionar en ciertos adultos mayores que sufren de soledad, mientras que una simple amistad con el vecino o con un voluntario local tambi\u00e9n puede servir.<\/p>\n<p>Personas con depresi\u00f3n requieren un enfoque distinto, como la terapia de conducta, dice la profesora Burholt.<\/p>\n<p>Ser\u00eda una equivocaci\u00f3n pensar que todos los adultos mayores sufren de soledad.<\/p>\n<p>\u00abLa vida tiene altos y bajos\u00bb agrega.<\/p>\n<p>\u00abConstantemente sopesamos qu\u00e9 recursos sociales tenemos y analizamos si nos sentimos solos o no\u00bb, concluye.<\/p>\n<p><a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2012\/07\/120710_soledad_vejez_jd.shtml\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abNing\u00fan hombre es una isla completamente, es un pedazo de continente, una parte del todo\u00bb, escribi\u00f3 el poeta John Donne en el siglo XVII para referirse a la soledad y la nostalgia.<\/p>\n","protected":false},"author":3,"featured_media":19005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-19006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19006"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19005"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}