{"id":19067,"date":"2012-07-30T14:28:52","date_gmt":"2012-07-30T18:28:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-hombre-de-la-piel-mas-elastica-video\/"},"modified":"2012-07-30T14:28:52","modified_gmt":"2012-07-30T18:28:52","slug":"el-hombre-de-la-piel-mas-elastica-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-hombre-de-la-piel-mas-elastica-video\/","title":{"rendered":"El hombre de la piel m\u00e1s el\u00e1stica (video)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19066\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_hombre_con_la_piel_mas_elastica.jpg\" width=\"515\" height=\"333\" alt=\"hombre_con_la_piel_mas_elastica\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_hombre_con_la_piel_mas_elastica.jpg 515w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_hombre_con_la_piel_mas_elastica-300x193.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/07\/sosua_images_hombre_con_la_piel_mas_elastica-400x260.jpg 400w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/>Conoce a Gary \u201cStretch\u201d Turner. Su piel es tan floja y el\u00e1stica que puede convertir su vientre en una tabla<br \/>Turner tiene muchos m\u00e1s trucos bajo la manga de su flacidez. El hombre de 41 a\u00f1os de edad, sufre de un caso extremo de s\u00edndrome de Ehlers-Danlos, una rara enfermedad gen\u00e9tica que ha debilitado su piel.<\/p>\n<p>  <!--more-->  <\/p>\n<p><object style=\"\" width=\"425\" height=\"350\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/CFiGkTJt5GE&amp;feature=player_embedded\" \/><embed width=\"425\" height=\"350\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/CFiGkTJt5GE&amp;feature=player_embedded\" wmode=\"opaque\"\/><\/object><\/p>\n<p><a href=\"http:\/\/www.cachicha.com\/2012\/07\/video-el-hombre-de-la-piel-mas-elastica\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conoce a Gary \u201cStretch\u201d Turner. Su piel es tan floja y el\u00e1stica que puede convertir su vientre en una tablaTurner tiene muchos m\u00e1s trucos bajo la manga de su flacidez. El hombre de 41 a\u00f1os de edad, sufre de un caso extremo de s\u00edndrome de Ehlers-Danlos, una rara enfermedad gen\u00e9tica que ha debilitado su piel.<\/p>\n","protected":false},"author":3,"featured_media":19066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-19067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19067"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19066"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}