{"id":19110,"date":"2012-08-01T13:39:01","date_gmt":"2012-08-01T17:39:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/lanzaran-muy-pronto-un-juego-para-bailar-dembowsi-leiste-muy-bien-iun-juego-para-bailar-dembow\/"},"modified":"2012-08-01T13:39:01","modified_gmt":"2012-08-01T17:39:01","slug":"lanzaran-muy-pronto-un-juego-para-bailar-dembowsi-leiste-muy-bien-iun-juego-para-bailar-dembow","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lanzaran-muy-pronto-un-juego-para-bailar-dembowsi-leiste-muy-bien-iun-juego-para-bailar-dembow\/","title":{"rendered":"Lanzar\u00e1n muy pronto un juego para bailar dembow&#8230;S\u00ed, leiste muy bien \u00a1un juego para bailar dembow!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19109\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_1f0uv.jpg\" width=\"600\" height=\"222\" alt=\"1f0uv\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_1f0uv.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_1f0uv-300x111.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\u00bfUstedes hab\u00edan visto alguna informaci\u00f3n sobre un juego de bailar dembow? Bueno, mucho hab\u00edan durado para el invento, seg\u00fan un mensaje que ha llegado, el juego dizque ser\u00e1 lanzado muy pronto.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan el portal imagenesdominicanas.com quien les envi\u00f3 la informaci\u00f3n asegura que son de esos juegos, donde la gente se para a bailar delante, pero que tendr\u00e1 m\u00fasica de exponentes criollos, espec\u00edficamente dembowseros. La noticia del juego interactivo, se maneja con tremendo misterio, seg\u00fan les inform\u00f3 una fuente.&nbsp;<\/p>\n<p>Como adelanto, advierten a los padres que se preparen porque es casi seguro que esto se convertir\u00e1 en una fiebre localmente. Unas capturas de pantallas (print screen) que les enviaron. (<a href=\"http:\/\/www.imagenesdominicanas.com\/2012\/07\/juego-para-bailar-dembow.html\" rel=\"nofollow\">Click para ver<\/a>)&nbsp;<\/p>\n<p>Por la imagen el juego podr\u00eda ser similar al de este video<\/p>\n<p><object style=\"\" width=\"425\" height=\"350\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/KWy_3NCM5EI\" \/><embed width=\"425\" height=\"350\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/KWy_3NCM5EI\" wmode=\"opaque\"\/><\/object><\/p>\n<p>fuente: <a href=\"http:\/\/www.imagenesdominicanas.com\">www.imagenesdominicanas.com<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfUstedes hab\u00edan visto alguna informaci\u00f3n sobre un juego de bailar dembow? Bueno, mucho hab\u00edan durado para el invento, seg\u00fan un mensaje que ha llegado, el juego dizque ser\u00e1 lanzado muy pronto.&nbsp;<\/p>\n","protected":false},"author":3,"featured_media":19109,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-19110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19110"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19109"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}