{"id":19290,"date":"2012-08-13T15:35:27","date_gmt":"2012-08-13T19:35:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/muestran-como-el-estres-y-la-depresion-pueden-reducir-el-tamano-del-cerebro\/"},"modified":"2012-08-13T15:35:27","modified_gmt":"2012-08-13T19:35:27","slug":"muestran-como-el-estres-y-la-depresion-pueden-reducir-el-tamano-del-cerebro","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muestran-como-el-estres-y-la-depresion-pueden-reducir-el-tamano-del-cerebro\/","title":{"rendered":"Muestran c\u00f3mo el estr\u00e9s y la depresi\u00f3n pueden reducir el tama\u00f1o del cerebro"},"content":{"rendered":"<p><i><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19289\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_fotonoticia_20120813101303_500.jpg\" width=\"333\" height=\"500\" alt=\"fotonoticia_20120813101303_500\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_fotonoticia_20120813101303_500.jpg 333w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_fotonoticia_20120813101303_500-199x300.jpg 199w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/>La depresi\u00f3n mayor, o el estr\u00e9s cr\u00f3nico, pueden causar p\u00e9rdida de volumen cerebral, una condici\u00f3n que contribuye a la alteraci\u00f3n emocional y cognitiva. Ahora, un equipo de investigadores, liderado por cient\u00edficos de Yale, ha descubierto un interruptor gen\u00e9tico que desencadena la p\u00e9rdida de conexiones cerebrales en seres humanos, y la depresi\u00f3n en modelos animales. Los resultados, han sido publicados en la revista &#8216;Nature Medicine&#8217;.<\/i>&nbsp;La investigaci\u00f3n muestra que el interruptor gen\u00e9tico, conocido como un factor de transcripci\u00f3n, reprime la expresi\u00f3n de varios genes necesarios para la formaci\u00f3n de conexiones sin\u00e1pticas entre las c\u00e9lulas cerebrales, lo que a su vez podr\u00eda contribuir a la p\u00e9rdida de masa cerebral en la corteza prefrontal.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;&nbsp; \u00abQuer\u00edamos poner a prueba la idea de que el estr\u00e9s provoca una p\u00e9rdida de sinapsis en el cerebro humano\u00bb, afirma el autor principal, Ronald Duman, profesor de Psiquiatr\u00eda, Neurobiolog\u00eda y Farmacolog\u00eda en Yale. As\u00ed, continua el investigador, \u00abhemos demostrado que los circuitos normalmente involucrados en la emoci\u00f3n, as\u00ed como la cognici\u00f3n, se interrumpen cuando este factor de transcripci\u00f3n se activa\u00bb.<\/p>\n<p>&nbsp;&nbsp; El equipo de investigaci\u00f3n analiz\u00f3 tejidos donados de pacientes deprimidos y no deprimidos, y busc\u00f3 distintos patrones de activaci\u00f3n de genes. El estudio revel\u00f3 que los cerebros de los pacientes que hab\u00edan estado deprimidos exhib\u00edan menores niveles de expresi\u00f3n de los genes requeridos para la funci\u00f3n y estructura de las sinapsis cerebrales.<\/p>\n<p>&nbsp;&nbsp; El coautor H.J. Kang descubri\u00f3 que, al menos, cinco de estos genes podr\u00edan estar regulados por un solo factor de transcripci\u00f3n, llamado GATA1. Cuando el factor de transcripci\u00f3n se hubo activado, los roedores mostraron s\u00edntomas depresivos, lo cual sugiere que GATA1 desempe\u00f1a un papel, no s\u00f3lo en la p\u00e9rdida de las conexiones entre las neuronas, sino tambi\u00e9n en los s\u00edntomas de la depresi\u00f3n.<\/p>\n<p> &nbsp;&nbsp; Duman cree que las variaciones gen\u00e9ticas en GATA1 podr\u00e1n, alg\u00fan d\u00eda, ayudar a identificar a las personas en alto riesgo de depresi\u00f3n mayor, o la sensibilidad al estr\u00e9s. \u00abEsperamos que, mediante la mejora de las conexiones sin\u00e1pticas, ya sea con nuevos medicamentos, o con psicoterapia, podamos desarrollar terapias antidepresivas m\u00e1s eficaces\u00bb, concluye Duman.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La depresi\u00f3n mayor, o el estr\u00e9s cr\u00f3nico, pueden causar p\u00e9rdida de volumen cerebral, una condici\u00f3n que contribuye a la alteraci\u00f3n emocional y cognitiva. Ahora, un equipo de investigadores, liderado por cient\u00edficos de Yale, ha descubierto un interruptor gen\u00e9tico que desencadena la p\u00e9rdida de conexiones cerebrales en seres humanos, y la depresi\u00f3n en modelos animales. Los resultados, han sido publicados en la revista &#8216;Nature Medicine&#8217;.&nbsp;La investigaci\u00f3n muestra que el interruptor gen\u00e9tico, conocido como un factor de transcripci\u00f3n, reprime la expresi\u00f3n de varios genes necesarios para la formaci\u00f3n de conexiones sin\u00e1pticas entre las c\u00e9lulas cerebrales, lo que a su vez podr\u00eda contribuir a la p\u00e9rdida de masa cerebral en la corteza prefrontal.<\/p>\n","protected":false},"author":3,"featured_media":19289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-19290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19290"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19289"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}