{"id":19442,"date":"2012-08-20T14:38:08","date_gmt":"2012-08-20T18:38:08","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/con-107-anos-nunca-ha-ido-al-medico-y-solo-le-ha-dado-una-diarrea\/"},"modified":"2012-08-20T14:38:08","modified_gmt":"2012-08-20T18:38:08","slug":"con-107-anos-nunca-ha-ido-al-medico-y-solo-le-ha-dado-una-diarrea","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/con-107-anos-nunca-ha-ido-al-medico-y-solo-le-ha-dado-una-diarrea\/","title":{"rendered":"Con 107 a\u00f1os nunca ha ido al m\u00e9dico y solo le ha dado una diarrea"},"content":{"rendered":"<p><b><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19441\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_mujer_con_107_anios_nunca_se_ha_enfermado33t45y6ui67u.jpg\" width=\"315\" height=\"297\" alt=\"mujer_con_107_anios_nunca_se_ha_enfermado33t45y6ui67u\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_mujer_con_107_anios_nunca_se_ha_enfermado33t45y6ui67u.jpg 315w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/08\/sosua_images_mujer_con_107_anios_nunca_se_ha_enfermado33t45y6ui67u-300x282.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/>Esperanza, Valverde.-<\/b>&nbsp;Tiene 107 a\u00f1os de edad, todav\u00eda con una vista de \u00e1guila que puede ensartar una aguja y un estado de \u00e1nimo que le permite cocinar y poder lavar sus ropas a manos limpias.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>Achacosa por diversos quebrantos de salud, Em\u00e9rita Rodr\u00edguez, cari\u00f1osamente conocida como Do\u00f1a Nena, confiesa que nunca ha ido al m\u00e9dico y que el problema mas grave que ha padecido en mucho tiempo fue una diarrea. <\/p>\n<p>\u201cSufro de todo pero nunca he ido a chequearme. Una diarrea grand\u00edsima ha sido mi \u00fanica enfermedad\u201d, afirm\u00f3 en una amena conversaci\u00f3n con reporteros de Caribbean Digital, en su casa de la calle principal del paraje El Manguito, Damajagua.<\/p>\n<p>Con sus 107 a\u00f1os de edad, Do\u00f1a Nena cuela caf\u00e9 y barre el patio, una costumbre que solo le impedir\u00e1 la muerte. Un poco sorda por los a\u00f1os, dice, es lo que actualmente le afecta.<\/p>\n<p>Tuvo siete hijos, cinco hembras y dos varones. Recuerda al dictador Rafael Leonidas Trujillo como un hombre que hac\u00eda maldades, pero que para ella no era malo.<\/p>\n<\/p><\/div>\n<div><\/div>\n<div>\n<div>De Joaqu\u00edn Balaguer no quiso opinar, de Hip\u00f3lito Mej\u00eda dice que es un \u201ccherchoso\u201d y a Leonel Fern\u00e1ndez lo desconoce.<\/div>\n<div>Do\u00f1a Nena naci\u00f3 en la comunidad de \u00c1mina del municipio de Mao. Perdi\u00f3 sus documentos personales (c\u00e9dula) desde que era muy joven y nunca mas lo adquiri\u00f3 de nuevo, pero sus familiares y vecinos dicen que tiene 107 a\u00f1os de edad.<\/div>\n<div>A pesar de su muy avanzada edad no recibe del Estado dominicano ni una sola ayuda social de las que el gobierno insiste que invierte millones de pesos en todo el pa\u00eds.<\/div>\n<\/p><\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.sacandomelao.com\/2012\/08\/con-107-anos-nunca-ha-ido-al-medico-y.html\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esperanza, Valverde.-&nbsp;Tiene 107 a\u00f1os de edad, todav\u00eda con una vista de \u00e1guila que puede ensartar una aguja y un estado de \u00e1nimo que le permite cocinar y poder lavar sus ropas a manos limpias.<\/p>\n","protected":false},"author":3,"featured_media":19441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-19442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19442"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19441"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}