{"id":19715,"date":"2012-09-07T14:00:32","date_gmt":"2012-09-07T18:00:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/idonde-van-a-parar-los-mensajes-y-archivos-que-compartes-por-whatsapp-2\/"},"modified":"2012-09-07T14:00:32","modified_gmt":"2012-09-07T18:00:32","slug":"idonde-van-a-parar-los-mensajes-y-archivos-que-compartes-por-whatsapp-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/idonde-van-a-parar-los-mensajes-y-archivos-que-compartes-por-whatsapp-2\/","title":{"rendered":"\u00bfD\u00f3nde van a parar los mensajes y archivos que compartes por WhatsApp?"},"content":{"rendered":"<p id=\"story-texto\" xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19713\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_whatsapp-logo-e1315303015782-1000x1024-1-515x527--644x362.jpg\" width=\"644\" height=\"362\" alt=\"whatsapp-logo-e1315303015782-1000x1024-1-515x527--644x362\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_whatsapp-logo-e1315303015782-1000x1024-1-515x527--644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_whatsapp-logo-e1315303015782-1000x1024-1-515x527--644x362-300x168.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/>\u00bfD\u00f3nde se guardan los mensajes y archivos que se comparten (fotos, v\u00eddeos&#8230;) a trav\u00e9s del sistema de mensajer\u00eda instant\u00e1nea WhatsApp? \u00bfPuede \u00absniffearlos\u00bb (t\u00e9cnica de seguridad de redes que consiste en poner un PC u otro sistema para escuchar todo el tr\u00e1fico que pasa por una red) o \u00abhackearlos\u00bb un pirata inform\u00e1tico en cualquier momento?&nbsp;La respuesta&nbsp;que dan todos los t\u00e9cnicos inform\u00e1ticos consultados&nbsp;es un sonoro \u00abs\u00ed\u00bb, as\u00ed que la conclusi\u00f3n inicial es que a pesar de las mejoras de seguridad que est\u00e1 implementando el servicio, existen otras alternativas de servicios como iMessage que<a href=\"http:\/\/www.abc.es\/20120119\/medios-redes\/abci-whatsapp-apple-201201191112.html\">&nbsp;les superan con distintos m\u00e9todos&nbsp;<\/a>para incrementar la protecci\u00f3n de la informaci\u00f3n que comparten sus usuarios. De hecho, desde que se populariz\u00f3 la aplicaci\u00f3n, su principal caballo de batalla ha sido mejorar la seguridad (y&nbsp;<a href=\"http:\/\/www.abc.es\/20120308\/tecnologia\/abci-mejoras-whatsapp-201203081249.html\">en la \u00faltima versi\u00f3n ha llegado a cifrar sus mensajes<\/a>), ya que&nbsp;<a href=\"http:\/\/www.abc.es\/sevilla\/noticias\/201105\/23\/actualidad\/tecnologia\/whatsapp.html\">las cr\u00edticas sobre los fallos<\/a>&nbsp;en este \u00e1mbito son una constante.<\/p>\n<p>  <!--more-->  <\/p>\n<p id=\"U15033225115260XB\" xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">Por partes. La pol\u00e9mica salta esta semana cuando ve la luz el v\u00eddeo er\u00f3tico&nbsp;<a href=\"http:\/\/www.abc.es\/20120906\/local-toledo\/abci-video-erotico-hormigos-201209062129.html\">protagonizado por una edil socialista del pueblo toledano de Los Y\u00e9benes<\/a>, y las acusaciones y bulos sobre qui\u00e9n lo ha \u00absubido\u00bb a internet empiezan a propalarse como la p\u00f3lvora. La propia concejal acusa a la Alcald\u00eda de haberlo difundido a trav\u00e9s de un e-mail; cobra posteriormente fuerza la tesis de que un joven amigo suyo lo hubiese hecho circular<a href=\"http:\/\/www.abc.es\/20120907\/local-toledo\/abci-sanchez-video-concejal-yebenes-201209071250.html\">&nbsp;a trav\u00e9s de WhatsApp&nbsp;<\/a>o que un \u00abpirata\u00bb hubiese podido interferir en el sistema operativo del smartphone que utiliz\u00f3&nbsp;Olvido Hormigos&nbsp;para grabar su escena \u00edntima y luego provocar su renuncia al acta de concejal haci\u00e9ndolo p\u00fablico.&nbsp;<\/p>\n<p>Las dos \u00faltimas teor\u00edas colocan al servicio de mensajer\u00eda compatible con los sistemas operativos de Google (Android), Blackberry OS, Windows Mobile, Windows 8 y el de NokiaSymbian60, as\u00ed como el de Apple (el de iOs de Mac para iPhone) en el punto de mira. Y tanto los fabricantes como los expertos inform\u00e1ticos consultados por&nbsp;<a href=\"http:\/\/www.abc.es\/\">ABC.es<\/a>&nbsp;advierten que si configuras el WhatsApp para que lo guarde&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Computaci%C3%B3n_en_la_nube\" target=\"_blank\">en la llamada \u00abnube\u00bb<\/a>&nbsp;o en la carpeta local del m\u00f3vil donde te guarda todos los archivos en caso de que uses Android,&nbsp;entonces ese v\u00eddeo estar\u00eda all\u00ed guardado, en su propio m\u00f3vil.&nbsp;Si Olvido envi\u00f3 a trav\u00e9s de WhatsApp su v\u00eddeo al del joven futbolista acusado, por ejemplo,&nbsp;estar\u00eda en ambos dispositivos,adem\u00e1s de quedar a la suerte del habilidoso \u00abhacker\u00bb que quisiera utilizar esa informaci\u00f3n reservada.<\/p>\n<h4>Una carpeta en tu m\u00f3vil de Android<\/h4>\n<p id=\"U1503322511526TJE\" xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">En Android, al instalar la aplicaci\u00f3n de mensajer\u00eda, se crea una carpeta en un punto de montaje del sistema opertivo que en el fondo es un c\u00f3digo Linux abierto (lo que no significa que sea menos seguro) y todos los contenidos compartidos por WhatSApp&nbsp;se descargan directamente&nbsp;en esa carpeta (\/scard\/WhatsApp\/media). Cualquiera que tenga acceso a ese celular puede acceder a la carpeta.<\/p>\n<p id=\"U1503322511526xlE\" xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">En el caso de los iPhone, la llamada \u00abnube\u00bb o iCloud de Apple, por ejemplo, no es m\u00e1s que un trozo de disco compartido desde un servidor al que se puede acceder con un usuario y una contrase\u00f1a desde un PC u otro dispositivo. Es decir, con ese usuario y contrase\u00f1a, o consigui\u00e9ndolo de alg\u00fan modo, tambi\u00e9n se puede tener acceso y leer toda la avalancha de informaci\u00f3n que se puede transferir a trav\u00e9s de WhatsApp.<\/p>\n<p id=\"U1503322511526f6F\" xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">No obstante, en el caso que nos ocupa y a t\u00edtulo m\u00e1s informativo o anecd\u00f3tico que policial, los inform\u00e1ticos y fabricantes testados sugieren que lo m\u00e1s probable es que la concejal socialista o una persona cercana compartir\u00eda el archivo y de ah\u00ed a la esfera p\u00fablica no habr\u00eda m\u00e1s que un salto m\u00ednimo. Ser\u00e1 la investigaci\u00f3n pertinente la que lo determine.&nbsp;<\/p>\n<h4>Se pueden recuperar siempre<\/h4>\n<p xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">El WhatsApp, a d\u00eda de hoy, se utiliza como si tratase de un chat, aparte de que esa posibilidad de compartir y enviar todo tipo de archivos de audio, v\u00eddeo e imagen hacen m\u00e1s fluida la conversaci\u00f3n, para lo cual&nbsp;solo tiene que existir la conexi\u00f3n a internet del m\u00f3vil.&nbsp;Las conversaciones tampoco se pierden, y se pueden recuperar o salvar siempre. De hecho, podemos incluso&nbsp;configurar la aplicaci\u00f3n en la pantalla de Ajustes para guardar el historial de todas las conversaciones&nbsp;(con sus im\u00e1genes y v\u00eddeos internos, incluidos) desde un principio. En esta aplicaci\u00f3n tambi\u00e9n existe la opci\u00f3n de&nbsp;enviar historial de chats, donde se selecciona la conversaci\u00f3n concreta y se env\u00eda si se desea (con la posibilidad de convertirla en archivo formato TXT, o guardar los archivos como fotos y v\u00eddeos por defecto tambi\u00e9n). El \u00faltimo paso es enviar ese historial en forma de correo electr\u00f3nico, con lo que el rastreo de esa conversaci\u00f3n tambi\u00e9n se quedar\u00eda en la bandeja de salida de e-mails de ese terminal.<\/p>\n<div xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">\n<div xmlns:dt=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.DateUtilities\" xmlns:g=\"http:\/\/www.jclark.com\/xt\/java\/http:\/\/apis.google.com\/js\/plusone.js\" xmlns:java=\"java\" xmlns:xe=\"http:\/\/www.jclark.com\/xt\/java\/htmlpub.XslExt\">\n<div>\n<h3>Existen muchos software-esp\u00eda para acceder al rastreo del WhatsApp<\/h3>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\">Por \u00faltimo, y si alguien se fiaba de tener confidencialidad en sus conversaciones, deber\u00eda conocer tambi\u00e9n que&nbsp;en el mercado existe un ampl\u00edsimo abanico de software-esp\u00eda&nbsp;y aplicaciones que se llaman \u00abC\u00f3mo espiar WhatsApp en m\u00f3viles Android e iPhone\u00bb y que por&nbsp;precios que rodean los 470 euros&nbsp;permiten espiar WhatsApp, rastrear su contenido, grabar las llamadas, la hora y fecha, su duraci\u00f3n, grabar los mensajes que contengan tambi\u00e9n fotos y v\u00eddeos, y dependiendo del tipo de tel\u00e9fono m\u00f3vil, usar GPS en los programas para saber en qu\u00e9 direcci\u00f3n o lugar del mapa se est\u00e1n produciendo esas conversaciones. Son programas que, seg\u00fan explican algunos de sus fabricantes,&nbsp;emplean sobre todos aquellos que olisquean una posible infidelidad o o padres en busca de conocer d\u00f3nde est\u00e1n sus hijos&nbsp;en todo momento. Los programas modernos para espiar m\u00f3viles son discretos y se instalan instant\u00e1neamente sin necesidad de conectarse en un ordenador. El registro se guarda en un servidor y da la opci\u00f3n de poder acceder a \u00e9l desde cualquier computadora o m\u00f3vil con conexi\u00f3n a internet. Permiten hasta hacer capturas de im\u00e1genes de los mensajes que interesen, tanto los enviados como los recibidos.<\/div>\n<div xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\"><\/div>\n<div xmlns:str=\"http:\/\/www.jclark.com\/xt\/java\/es.vocento.methode.utils.StringUtilities\"><a href=\"http:\/\/www.abc.es\/20120907\/tecnologia\/abci-whatsapp-nube-hackear-mensajes-201209071346.html\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfD\u00f3nde se guardan los mensajes y archivos que se comparten (fotos, v\u00eddeos&#8230;) a trav\u00e9s del sistema de mensajer\u00eda instant\u00e1nea WhatsApp? \u00bfPuede \u00absniffearlos\u00bb (t\u00e9cnica de seguridad de redes que consiste en poner un PC u otro sistema para escuchar todo el tr\u00e1fico que pasa por una red) o \u00abhackearlos\u00bb un pirata inform\u00e1tico en cualquier momento?&nbsp;La respuesta&nbsp;que dan todos los t\u00e9cnicos inform\u00e1ticos consultados&nbsp;es un sonoro \u00abs\u00ed\u00bb, as\u00ed que la conclusi\u00f3n inicial es que a pesar de las mejoras de seguridad que est\u00e1 implementando el servicio, existen otras alternativas de servicios como iMessage que&nbsp;les superan con distintos m\u00e9todos&nbsp;para incrementar la protecci\u00f3n de la informaci\u00f3n que comparten sus usuarios. De hecho, desde que se populariz\u00f3 la aplicaci\u00f3n, su principal caballo de batalla ha sido mejorar la seguridad (y&nbsp;en la \u00faltima versi\u00f3n ha llegado a cifrar sus mensajes), ya que&nbsp;las cr\u00edticas sobre los fallos&nbsp;en este \u00e1mbito son una constante.<\/p>\n","protected":false},"author":3,"featured_media":19713,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-19715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19715"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19713"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}