{"id":19721,"date":"2012-09-07T14:28:15","date_gmt":"2012-09-07T18:28:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-mujer-maravilla-cw-desarrolla-una-serie-sobre-los-origenes-de-la-heroina-de-dc\/"},"modified":"2012-09-07T14:28:15","modified_gmt":"2012-09-07T18:28:15","slug":"la-mujer-maravilla-cw-desarrolla-una-serie-sobre-los-origenes-de-la-heroina-de-dc","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-mujer-maravilla-cw-desarrolla-una-serie-sobre-los-origenes-de-la-heroina-de-dc\/","title":{"rendered":"\u2018La Mujer Maravilla\u2019: CW desarrolla una serie sobre los or\u00edgenes de la hero\u00edna de DC"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19720\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_120907125003793.jpg-r_640_300-f_jpg-q_x-xxyxx.jpg\" width=\"630\" height=\"295\" alt=\"120907125003793.jpg-r_640_300-f_jpg-q_x-xxyxx\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_120907125003793.jpg-r_640_300-f_jpg-q_x-xxyxx.jpg 630w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_120907125003793.jpg-r_640_300-f_jpg-q_x-xxyxx-300x140.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/>El guionista Allan Heinberg (\u2018Anatom\u00eda de Grey\u2019) ya trabaja en el libreto, que relatar\u00e1 los primeros a\u00f1os de Diana de Themyscira como sucedi\u00f3 con Superman en \u2018Smallville\u2019.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>CW estrenar\u00e1 el pr\u00f3ximo 10 de octubre la serie \u2018Arrow\u2019 sobre Flecha Verde pero, a\u00fan as\u00ed, le parece que un superh\u00e9roe de DC Comics no es suficiente. La cadena responsable de \u2018Smallville\u2019 o de la inminente \u2018La Bella y la Bestia\u2019 desarrolla en estos momentos un gui\u00f3n basado en los or\u00edgenes de Wonder Woman, informa \u2018Vulture\u2019. El proyecto marcha viento en popa y Allan Heinberg (\u2018Anatom\u00eda de Grey\u2019) ya trabaja en el libreto que, presuntamente, llevar\u00e1 por t\u00edtulo \u2018Amazon\u2019.<\/p>\n<p>La potencial serie producida por Warner Bros. TV y DC narrar\u00e1 los primeros a\u00f1os de Diana de Themyscira tal y como lo hizo \u2018Smallville\u2019 con el joven Superman. Al contrario, la famosa serie setentera protagonizada por Lynda Carter relataba sus a\u00f1os como adulta y hero\u00edna ya formada. Pero antes de emocionarte, recuerda que s\u00f3lo se trata de un encargo de gui\u00f3n, y que todav\u00eda no existe ning\u00fan acuerdo, ni siquiera para grabar un piloto. Normal, teniendo en cuenta que hace no mucho la cadena NBC pas\u00f3 de la \u2018Wonder Woman\u2019 de David E. Kelley con Adrianne Palicki (\u2018Friday Night Lights\u2019) como protagonista. Incluso el todopoderoso Joss Whedon (\u2018Los Vengadores 2\u2032, \u2018S.H.I.E.L.D.\u2019) desarroll\u00f3 un t\u00edtulo sobre ella que jam\u00e1s lleg\u00f3 a ver la luz.<\/p>\n<p><a href=\"http:\/\/www.blogs.rodando.com.do\/noticias\/noticias\/la-mujer-maravilla-cw-desarrolla-una-serie-sobre-los-origenes-de-la-heroina-de-dc\/\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El guionista Allan Heinberg (\u2018Anatom\u00eda de Grey\u2019) ya trabaja en el libreto, que relatar\u00e1 los primeros a\u00f1os de Diana de Themyscira como sucedi\u00f3 con Superman en \u2018Smallville\u2019.<\/p>\n","protected":false},"author":3,"featured_media":19720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-19721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19721"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19720"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}