{"id":19942,"date":"2012-09-17T14:14:20","date_gmt":"2012-09-17T18:14:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ies-etico-crear-un-bebe-con-tres-padres\/"},"modified":"2012-09-17T14:14:20","modified_gmt":"2012-09-17T18:14:20","slug":"ies-etico-crear-un-bebe-con-tres-padres","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ies-etico-crear-un-bebe-con-tres-padres\/","title":{"rendered":"\u00bfEs \u00e9tico crear un beb\u00e9 con tres padres?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19941\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_120124091356_baby_embryo_304x171_camerapress.jpg\" width=\"304\" height=\"171\" alt=\"120124091356_baby_embryo_304x171_camerapress\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_120124091356_baby_embryo_304x171_camerapress.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_120124091356_baby_embryo_304x171_camerapress-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>Las autoridades brit\u00e1nicas iniciaron una consulta p\u00fablica para decidir si es \u00e9tico utilizar una t\u00e9cnica de fertilizaci\u00f3n para crear beb\u00e9s con material gen\u00e9tico de tres padres.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La t\u00e9cnica ser\u00eda utilizada para evitar la transmisi\u00f3n de las llamadas enfermedades mitocondriales, que se transfieren \u00fanicamente de la madre al ni\u00f1o.<\/p>\n<p>Estos trastornos son causados por defectos en la mitocondria, el \u00abmotor\u00bb de las c\u00e9lulas, y pueden causar s\u00edntomas como atrofia muscular, ceguera, enfermedades intestinales y card\u00edacas afectando severamente a los pacientes y reduciendo sus expectativas de vida.<\/p>\n<p>Con el procedimiento de fertilizaci\u00f3n in vitro se extraer\u00eda la mitocondria defectuosa para reemplazarla con la de una donante sana.<\/p>\n<p>Pero como la mitocondria contiene sus propios genes y su propio ADN, esto significa que el embri\u00f3n producido con este procedimiento contiene material gen\u00e9tico de tres personas: sus padres y la donante.<\/p>\n<p>Actualmente en el Reino Unido est\u00e1 permitido llevar a cabo reemplazo de mitocondria en el laboratorio, pero los embriones creados no pueden usarse en los tratamientos.<\/p>\n<p>Con la consulta p\u00fablica, coordinada por la Autoridad de Fertilizaci\u00f3n Humana y Embriolog\u00eda de Reino Unido (HFEA, por sus siglas en ingl\u00e9s), el gobierno podr\u00eda reformar las leyes para que una pareja en riesgo de enfermedades mitocondriales pueda ser sometida legalmente al procedimiento.<\/p>\n<h2>Territorio no explorado<\/h2>\n<p>La mitocondria es la encargada de proveer energ\u00eda a cada c\u00e9lula en el organismo.<\/p>\n<p>\u00c9sta se transfiere en el \u00f3vulo de la madre hacia el beb\u00e9. El padre no transfiere mitocondria en el esperma.<\/p>\n<p>Una de las principales objeciones al procedimiento es que los cambios que se lleven a cabo en la mitocondria afectar\u00e1n la linea germinal. Es decir, ser\u00eda una forma permanente de modificaci\u00f3n gen\u00e9tica porque el ADN mitocondrial donado ser\u00eda transmitido a futuras generaciones.<\/p>\n<div>\n<div>\n<div>\n<div>\n<blockquote>\n<p>\u00abSe trata de equilibrar el deseo de ayudar a las familias a tener ni\u00f1os sanos con el posible impacto en los propios ni\u00f1os y en la sociedad\u00bb<\/p>\n<\/blockquote>\n<div>\n<div>\n<p>Prof. Lisa Jardine, HFEA<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>\u00c9sta es una de las consideraciones \u00e9ticas que ser\u00e1 discutida en la nueva consulta.<\/p>\n<p>\u00abLa decisi\u00f3n sobre si el reemplazo de la mitocondria debe hacerse disponible para tratar a los pacientes no s\u00f3lo es un asunto de gran importancia para las familias afectadas por estas enfermedades terribles, sino tambi\u00e9n es de enorme inter\u00e9s p\u00fablico\u00bb, expresa la profesora Lisa Jardine, presidenta de la HFEA.<\/p>\n<p>\u00abComo se trata de una modificaci\u00f3n gen\u00e9tica en el \u00f3vulo, nos encontramos con un territorio que no ha sido explorado\u00bb.<\/p>\n<p>\u00abUna vez que se ha hecho la modificaci\u00f3n gen\u00e9tica debemos estar totalmente seguros de que se ha hecho lo correcto\u00bb, agrega.<\/p>\n<p>Seg\u00fan la cient\u00edfica, es un asunto de \u00abequilibrar el deseo de ayudar a las familias a tener ni\u00f1os sanos con el posible impacto en los propios ni\u00f1os y en la sociedad\u00bb.<\/p>\n<h2>\u00bfY los ni\u00f1os?<\/h2>\n<p>La consulta tambi\u00e9n tomar\u00e1 en cuenta otros asuntos \u00e9ticos.<\/p>\n<p>Por ejemplo, \u00bfc\u00f3mo se ven afectados los ni\u00f1os que nacen con estas t\u00e9cnicas?, \u00bfcu\u00e1ndo se les debe informar y qu\u00e9 impacto tendr\u00e1 en los padres y en la mujer donante?<\/p>\n<p>Tami\u00e9n se debatir\u00e1 si la mujer que dona el material mitocondrial debe ser considerada de forma similar a las mujeres que donan \u00f3vulos para fertilizaci\u00f3n&nbsp;<em>in vitro<\/em>.<\/p>\n<div>\n<div>\n<p>Los detractores dicen que el m\u00e9todo es \u00abinnecesario y peligroso\u00bb.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>No es la primera vez que se discute el asunto.<\/p>\n<p>Un informe del Consejo Nuffiled de Bio\u00e9tica, un organismo independiente de expertos en bio\u00e9tica m\u00e9dica, afirm\u00f3 en junio pasado que el tratamiento era \u00e9tico.<\/p>\n<p>Pero el grupo&nbsp;<em>Human Genetics Alert<\/em>&nbsp;se opone al procedimiento porque, seg\u00fan dice, es \u00abinnecesario, peligroso y marca un precedente para el dise\u00f1o de beb\u00e9s gen\u00e9ticamente modificados\u00bb.<\/p>\n<p>Se espera que la consulta termine en diciembre y que los resultados se conozcan el a\u00f1o pr\u00f3ximo.<\/p>\n<p>Sin embargo, a\u00fan si el gobierno brit\u00e1nico decidiera que la t\u00e9cnica debe permitirse, todav\u00eda deber\u00e1n llevarse a cabo m\u00e1s estudios para confirmar su seguridad.<\/p>\n<p>Una de las pioneras de esta investigaci\u00f3n, la profesora Mary Herbert de la Universidad de Newcastle, Inglaterra, expresa que \u00abahora estamos llevando a cabo experimentos para probar la seguridad y eficacia de estas nuevas t\u00e9cnicas\u00bb.<\/p>\n<p>\u00abCompletar el trabajo podr\u00eda tomar entre tres y cinco a\u00f1os\u00bb, agrega.<\/p>\n<p>Se calcula que uno de cada 200 ni\u00f1os nace cada a\u00f1o con un defecto en la mitocondria.<\/p>\n<p><a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2012\/09\/120917_fertilizacion_tres_padres_consulta_publica_men.shtml\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las autoridades brit\u00e1nicas iniciaron una consulta p\u00fablica para decidir si es \u00e9tico utilizar una t\u00e9cnica de fertilizaci\u00f3n para crear beb\u00e9s con material gen\u00e9tico de tres padres.<\/p>\n","protected":false},"author":3,"featured_media":19941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-19942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19942"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19941"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}