{"id":19944,"date":"2012-09-17T14:52:59","date_gmt":"2012-09-17T18:52:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/despues-de-30-anos-las-direcciones-ipv4-llegan-a-su-fin\/"},"modified":"2012-09-17T14:52:59","modified_gmt":"2012-09-17T18:52:59","slug":"despues-de-30-anos-las-direcciones-ipv4-llegan-a-su-fin","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/despues-de-30-anos-las-direcciones-ipv4-llegan-a-su-fin\/","title":{"rendered":"Despu\u00e9s de 30 a\u00f1os las direcciones IPv4 llegan a su fin"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-19943\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_direcciones-IPv4.jpg\" width=\"428\" height=\"280\" alt=\"direcciones-IPv4\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_direcciones-IPv4.jpg 428w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_direcciones-IPv4-300x196.jpg 300w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/>Despu\u00e9s de 30 a\u00f1os, las direcciones IPv4 llegan a su l\u00edmite. Este sistema ha sido sustituido por el nuevo protocolo de Internet, IPv6, para sanar la falta de espacio para nuevas direcciones que sufre la anterior versi\u00f3n. El protocolo IPv4 fue dise\u00f1ado para que un gran n\u00famero de ordenadores se conectaran a Internet, permitiendo as\u00ed que la informaci\u00f3n circular\u00e1 de un punto a otro del mundo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Originalmente, el sistema IPv4 fue concebido en los a\u00f1os sesenta y estandarizado en 1981 para dar servicio a m\u00e1s de 4.000 millones de direcciones. Sin embargo, el n\u00famero de direcciones que abarca este protocolo de Internet ha llegado a su l\u00edmite, puesto que seg\u00fan el RIPE NCC (Centro de Coordinaci\u00f3n de redes IP europeas), este hab\u00eda utilizado el \u00faltimo bloque de 16,8 millones de direcciones.<\/p>\n<p>En contra de lo ocurrido, el director de RIPE NCC, Axel Pawlik, dijo que en los comienzos de Internet \u201cparec\u00eda muy poco probable que el espacio de direcciones IP ser\u00eda un problema\u201d. Pawlik continu\u00f3 sus declaraciones afirmando: \u201clas limitaciones del espacio de direcciones IPv4 se hicieron evidentes con el tiempo, y en los \u00faltimos a\u00f1os hemos estado monitorizando los suministros, prepar\u00e1ndonos a nosotros y a todos los inversores para la siguiente etapa de Internet\u201d.<\/p>\n<p>Como ya se supo en su momento, el hist\u00f3rico IPv4 ser\u00e1 sustituido definitivamente por el nuevo protocolo de Internet, IPv6. Este es un nuevo est\u00e1ndar de direcciones que ofrece m\u00e1s de 340 trillones de direcciones \u00fanicas.<\/p>\n<p>El padre de Internet, Vint Cerf, asegur\u00f3 a The Telegraph que el \u201carrastre de pies\u201d -refiri\u00e9ndose a la demora del lanzamiento de un nuevo protocolo de Internet- podr\u00eda poner en peligro el auge de tel\u00e9fonos inteligentes y \u2018tablets\u2019, que ya ha conectado a cientos de millones de nuevos dispositivos a la red.<\/p>\n<p>Vint Cerf explic\u00f3 al medio brit\u00e1nico que \u201cla gente se pregunta por qu\u00e9 sus nuevos y peque\u00f1os dispositivos no funcionan. Todas la promesas y el potencial de estos dispositivos caer\u00e1n en error si los ISP no lo aprovechan\u201d.<\/p>\n<p>\u201cM\u00e1s del cincuenta por ciento de nuestros miembros ya tiene una direcci\u00f3n IPv6 asignada, pero todav\u00eda hay un largo camino antes de que nosotros podamos decir que todo est\u00e1 preparado\u201d, admiti\u00f3 el pasado viernes el director del Centro de Coordinaci\u00f3n de redes IP europeas, Axel Pawlik.<\/p>\n<p>Seg\u00fan Pawlik, el nuevo protocolo IPv6 incrementa la cantidad de espacio de direcciones, \u201cayudando a hacer posible un giro emocionante en la sociedad as\u00ed como dispositivos conectados a Internet cada vez m\u00e1s sofisticados\u201d.<\/p>\n<p>&nbsp;Un punto en contra del reciente protocolo de Internet, IPv6, es que su velocidad de acceso es un 80 por ciento m\u00e1s lenta que con la anterior versi\u00f3n IPv4, seg\u00fan un an\u00e1lisis llevado a cabo por la firma especializada en soluciones para optimizar el rendimiento de las aplicaciones Compuware.<\/p>\n<p>&nbsp;Esta p\u00e9rdida de velocidad supone un riesgo a la experiencia del usuario y por lo tanto a los ingresos de las compa\u00f1\u00edas y a la reputaci\u00f3n de marca, adem\u00e1s de provocar cambios en la forma de medir y monitorizar el rendimiento, ha indicado la firma.<\/p>\n<p><a href=\"http:\/\/www.europapress.es\/portaltic\/internet\/noticia-direcciones-protocolo-ipv4-llegan-fin-20120917105141.html\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de 30 a\u00f1os, las direcciones IPv4 llegan a su l\u00edmite. Este sistema ha sido sustituido por el nuevo protocolo de Internet, IPv6, para sanar la falta de espacio para nuevas direcciones que sufre la anterior versi\u00f3n. El protocolo IPv4 fue dise\u00f1ado para que un gran n\u00famero de ordenadores se conectaran a Internet, permitiendo as\u00ed que la informaci\u00f3n circular\u00e1 de un punto a otro del mundo.<\/p>\n","protected":false},"author":3,"featured_media":19943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-19944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=19944"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/19944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/19943"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=19944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=19944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=19944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}