{"id":20135,"date":"2012-09-28T13:20:22","date_gmt":"2012-09-28T17:20:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/organizacion-no-gubernamental-firma-acuerdo-para-capacitar-jovenes\/"},"modified":"2012-09-28T13:20:22","modified_gmt":"2012-09-28T17:20:22","slug":"organizacion-no-gubernamental-firma-acuerdo-para-capacitar-jovenes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/organizacion-no-gubernamental-firma-acuerdo-para-capacitar-jovenes\/","title":{"rendered":"Organizaci\u00f3n no gubernamental firma acuerdo para capacitar jovenes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20134\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_ORGANIZACIN-NO-GUBERNAMENTAL-300x200.jpg\" width=\"300\" height=\"200\" alt=\"ORGANIZACIN-NO-GUBERNAMENTAL-300x200\" class=\"caption\" style=\"float: left;\" \/>Por Vicente Silverio.-&nbsp;La organizaci\u00f3n no gubernamental \u201cProject-Dream\u201d que opera en esta regi\u00f3n, anunci\u00f3 la concertaci\u00f3n de un acuerdo con autoridades municipales de Sos\u00faa, con el fin de iniciar un programa de formaci\u00f3n laboral para j\u00f3venes estudiantes.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El anuncio fue hecho durante un encuentro realizado en las oficinas locales del Ayuntamiento municipal de Sos\u00faa, donde junto a la alcaldesa y dem\u00e1s ediles de ese ayuntamiento, tambi\u00e9n estuvieron presentes los principales ejecutivos de la instituci\u00f3n ben\u00e9fica, entre ellos: Yann Reynaud, Yanlico Munesi, profesores.<\/p>\n<p>Igualmente particip\u00f3 en la actividad, el educador Jon Odrionzola y Kathy Reynawd qui\u00e9n est\u00e1 al mando de la entidad y coordina los cursos de capacitaci\u00f3n laboral para j\u00f3venes.<\/p>\n<p>De a cuerdo a las declaraciones de los promotores de \u201cProject-Dream\u201d ese organismo ha realizado actividades formativas en varios pa\u00edses de latino Am\u00e9rica y en Rep\u00fablica Dominicana, ya han coordinado actividades con el instituto de Formaci\u00f3n T\u00e9cnico profesional, \u2018INFOTEP- con el que ejecutaron cursos de&nbsp; Camarer\u00eda, bartender y Gu\u00eda de Turismo Ecol\u00f3gico, para j\u00f3venes de la comunidad de Cabarete.<\/p>\n<p><a href=\"http:\/\/kabarete.net\/v2.5\/?p=5941\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Vicente Silverio.-&nbsp;La organizaci\u00f3n no gubernamental \u201cProject-Dream\u201d que opera en esta regi\u00f3n, anunci\u00f3 la concertaci\u00f3n de un acuerdo con autoridades municipales de Sos\u00faa, con el fin de iniciar un programa de formaci\u00f3n laboral para j\u00f3venes estudiantes.<\/p>\n","protected":false},"author":3,"featured_media":20134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20135"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20134"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}