{"id":20151,"date":"2012-09-29T13:21:06","date_gmt":"2012-09-29T17:21:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/nueva-y-pintoresca-imagen-de-scary-movie-5\/"},"modified":"2012-09-29T13:21:06","modified_gmt":"2012-09-29T17:21:06","slug":"nueva-y-pintoresca-imagen-de-scary-movie-5","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nueva-y-pintoresca-imagen-de-scary-movie-5\/","title":{"rendered":"Nueva y pintoresca imagen de Scary Movie 5"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20150\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_scary-movie-5-pic3.jpg\" width=\"595\" height=\"365\" alt=\"scary-movie-5-pic3\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_scary-movie-5-pic3.jpg 595w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_scary-movie-5-pic3-300x184.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_scary-movie-5-pic3-440x270.jpg 440w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/>Llega una nueva imagen oficial de la comedia \u2018Scary Movie 5\u2032, en cuyo elenco encontramos nombres como los de Charlie Sheen y Lindsay Lohan.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Charlie Sheen abandon\u00f3 su papel en la serie \u2018Dos hombres y medio\u2019 por serias diferencias con los productores. Adem\u00e1s ahora disfruta de un \u00e9xito aceptable con su nuevo proyecto, \u2018Anger Management\u2019.<\/p>\n<p>El rodaje de \u2018Scary Movie 5\u2032 se desarroll\u00f3 durante el pasado mes de agosto. Contando con la direcci\u00f3n de Malcolm Lee y David Zucker, quien a su vez regresa a la saga tras ser el responsable de la tercera y cuarta entrega de la misma.<\/p>\n<p>Recordemos tambi\u00e9n que Anna Faris, la protagonista por antonomasia de Scary Movie, decidi\u00f3 dejar de lado la saga para cambiar de rumbo profesional. Lo que propici\u00f3 la llegada a la misma de la actriz Ashley Tisdale (conocida por sus papeles en \u2018High School Musical\u2019 o la serie de televisi\u00f3n \u2018Hellcats\u2019).<\/p>\n<p><a href=\"http:\/\/www.blogs.rodando.com.do\/noticias\/noticias\/nueva-y-pintoresca-imagen-de-scary-movie-5\/\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Llega una nueva imagen oficial de la comedia \u2018Scary Movie 5\u2032, en cuyo elenco encontramos nombres como los de Charlie Sheen y Lindsay Lohan.<\/p>\n","protected":false},"author":3,"featured_media":20150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20151"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20150"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}