{"id":20173,"date":"2012-09-29T18:54:17","date_gmt":"2012-09-29T22:54:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/inauguran-segunda-version-festival-gastronomico-multicultural-de-sosua-ver-fotos-y-video\/"},"modified":"2012-09-29T18:54:17","modified_gmt":"2012-09-29T22:54:17","slug":"inauguran-segunda-version-festival-gastronomico-multicultural-de-sosua-ver-fotos-y-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/inauguran-segunda-version-festival-gastronomico-multicultural-de-sosua-ver-fotos-y-video\/","title":{"rendered":"Inauguran segunda versi\u00f3n Festival Gastron\u00f3mi\u200bco Multicultu\u200bral de Sos\u00faa (VER FOTOS Y VIDEO)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20172\" style=\"float: left;\" alt=\"DSCF5855\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/09\/sosua_images_DSCF5855.jpg\" width=\"725\" height=\"511\" \/>El Batey, Sos\u00faa.- Fue inaugurado&nbsp;en la noche de este viernes, la segunda versi\u00f3n Festival Gastron\u00f3mico Multicultural de Sos\u00faa ante la presencia de las principales autoridades civiles y militares del municipio, la provincia de Puerto Plata y una nutrida representaci\u00f3n del pueblo y los propietarios de restaurantes y bares de la zona.<\/p>\n<p>  <!--more-->  <\/p>\n<p><object width=\"628\" height=\"360\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157631650528329%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157631650528329%2F&amp;set_id=72157631650528329&amp;jump_to=\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=121499\" \/><embed width=\"628\" height=\"360\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=121499\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157631650528329%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157631650528329%2F&amp;set_id=72157631650528329&amp;jump_to=\" allowFullScreen=\"true\"\/><\/object><\/p>\n<p><object width=\"629\" height=\"398\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/g8EdYgooGBQ\" \/><embed width=\"629\" height=\"398\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/g8EdYgooGBQ\" wmode=\"opaque\"\/><\/object><\/p>\n<p>La bienvenida al acto estuvo a cargo de la Licenciada Ilana Neumann, alcaldesa de Sos\u00faa que se mostr\u00f3 muy regocijada y de buen \u00e1nimo al notar el grandioso respaldo del pueblo a tan importante actividad, le secund\u00f3 Carolina G\u00f3mez, representante de la Unidad Municipal para Patrimonio Comunitario (UMPC) quien hizo subir a tarima a todos los miembros presentes de esta organizaci\u00f3n.<\/p>\n<p>La parte art\u00edstica tuvo excelentemente representada por la artista cristiana de origen sosuense, Rebeca Garc\u00eda Hern\u00e1ndez y Abrah\u00e1n Tam\u00e1rez quien ha logrado grandiosos \u00e9xitos con su canci\u00f3n al estilo sonero cubano \u00abPara Sos\u00faa me voy aunque no haya carretera\u00bb<\/p>\n<p>Durante el acto de inauguraci\u00f3n del segundo Festival Gastron\u00f3mico Multicultural de Sos\u00faa fue reconocida la joven Mimi Islas por su trayectoria internacional en los quehaceres de la gastronom\u00eda. Mimi, hermana del reconocido productor de televisi\u00f3n Junior Henr\u00edquez ha sido presentada al mundo a trav\u00e9s de los m\u00e1s importantes espacios televisamos hispanos de Los <br \/>Estados Unidos, tales como S\u00e1bado Gigante y Despierta Am\u00e9rica entre otros.<\/p>\n<p>Todo el espacio del parque Las Flores y la calle entre la Pedro Clisante y Alejo Mart\u00ednez fue abarrotado por el p\u00fablico y los restaurantes que serv\u00edan a precios muy econ\u00f3micos sus mejores platos.<\/p>\n<p>Entre las autoridades vistas en el acto estuvo el ex alcalde y actual concejal del municipio de Sos\u00faa, Arismendy Medina y la concejal \u00c1ngela de Jes\u00fas, adem\u00e1s el vice ministro de turismo de la provincia de Puerto Plata C\u00e9sar Jos\u00e9 de Los Santos, Manuel Finke, Jorge Espaillat entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Batey, Sos\u00faa.- Fue inaugurado&nbsp;en la noche de este viernes, la segunda versi\u00f3n Festival Gastron\u00f3mico Multicultural de Sos\u00faa ante la presencia de las principales autoridades civiles y militares del municipio, la provincia de Puerto Plata y una nutrida representaci\u00f3n del pueblo y los propietarios de restaurantes y bares de la zona.<\/p>\n","protected":false},"author":3,"featured_media":20172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20173"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20172"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}