{"id":20226,"date":"2012-10-03T15:06:21","date_gmt":"2012-10-03T19:06:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/llamada-de-atencion-el-uso-de-celulares-podria-provocar-trastornos-mentales\/"},"modified":"2012-10-03T15:06:21","modified_gmt":"2012-10-03T19:06:21","slug":"llamada-de-atencion-el-uso-de-celulares-podria-provocar-trastornos-mentales","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/llamada-de-atencion-el-uso-de-celulares-podria-provocar-trastornos-mentales\/","title":{"rendered":"Llamada de atenci\u00f3n: El uso de celulares podr\u00eda provocar trastornos mentales"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20225\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_trastornos-mentales1-300x168.png\" width=\"300\" height=\"168\" alt=\"trastornos-mentales1-300x168\" class=\"caption\" style=\"float: left;\" \/>Cient\u00edficos japoneses, alarmados por el creciente uso de los dispositivos m\u00f3viles, realizaron un estudio donde concluyeron que los adolescentes que los utilizan por la noche son m\u00e1s propensos a desarrollar trastornos mentales.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Especialistas de diferentes organizaciones m\u00e9dicas de Jap\u00f3n examinaron a 17.920 adolescentes de entre 13 y 18 a\u00f1os. Los participantes del estudio contestaron a preguntas dise\u00f1adas para descubrir s\u00edntomas de ansiedad y depresi\u00f3n y revelar si los j\u00f3venes ten\u00edan inclinaciones al suicidio.<\/p>\n<p>Adem\u00e1s, los investigadores preguntaron a los participantes cu\u00e1ntas horas dorm\u00edan y si se conectaban a Internet para entrar a las redes sociales o chequear sus correos electr\u00f3nicos despu\u00e9s de acostarse.<\/p>\n<p>Los cient\u00edficos encontraron que los adolescentes que utilizaban su celular despu\u00e9s de haberse acostado resultaron m\u00e1s propensos a tener problemas con su salud mental y padecer depresi\u00f3n. Asimismo, las ideas suicidas eran m\u00e1s recurrentes.<\/p>\n<p>El estudio de los cient\u00edficos japoneses se complementa con los resultados de una investigaci\u00f3n de sus colegas estadounidenses del Instituto Polit\u00e9cnico Rensselaer de Nueva York. Ellos demostraron que la iluminaci\u00f3n de las pantallas de los dispositivos (retroiluminaci\u00f3n) reprime la producci\u00f3n de melatonina en el organismo humano. As\u00ed se cambia el ritmo del reloj biol\u00f3gico, que empieza a funcionar mal.<\/p>\n<p>Seg\u00fan los investigadores japoneses, la alteraci\u00f3n de ese ritmo en los adolescentes, cuya mentalidad se est\u00e1 formando, es especialmente peligroso y podr\u00eda llevar a graves trastornos mentales.<\/p>\n<p>El estudio fue publicado en la revista \u2018Journal of Pediatric Psychology\u2019.<\/p>\n<p>Recientemente, los psic\u00f3logos decidieron incluir el trastorno causado por el uso desmedido de Internet en la lista de enfermedades mentales de una enciclopedia psiqui\u00e1trica internacional. Los menores de edad corren particularmente el riesgo de contraer este trastorno.<\/p>\n<p><a href=\"http:\/\/cachicha.com\/2012\/10\/llamada-de-atencion-el-uso-de-celulares-podria-provocar-trastornos-mentales\/\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cient\u00edficos japoneses, alarmados por el creciente uso de los dispositivos m\u00f3viles, realizaron un estudio donde concluyeron que los adolescentes que los utilizan por la noche son m\u00e1s propensos a desarrollar trastornos mentales.<\/p>\n","protected":false},"author":3,"featured_media":20225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20226"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20225"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}