{"id":20285,"date":"2012-10-05T14:36:38","date_gmt":"2012-10-05T18:36:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/descubren-unas-abejas-en-francia-que-producen-miel-de-color-azul-y-verde\/"},"modified":"2012-10-05T14:36:38","modified_gmt":"2012-10-05T18:36:38","slug":"descubren-unas-abejas-en-francia-que-producen-miel-de-color-azul-y-verde","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/descubren-unas-abejas-en-francia-que-producen-miel-de-color-azul-y-verde\/","title":{"rendered":"Descubren unas abejas en Francia que producen miel de color azul y verde"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20284\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_abeja--478x270.jpg\" width=\"478\" height=\"269\" alt=\"abeja--478x270\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_abeja--478x270.jpg 478w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_abeja--478x270-300x168.jpg 300w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/>Los apicultores de&nbsp;Ribeauville, en la regi\u00f3n de Alsacia (Francia) no pueden creer lo que ven sus ojos, seg\u00fan informa&nbsp;<a title=\"\u00abQue!\u00bb\" href=\"http:\/\/www.que.es\/ultimas-noticias\/curiosas\/201210042121-descubren-unas-abejas-francia-producen-cont.html?anker_1\" target=\"_blank\">\u00abQue!\u00bb<\/a>. Sus abejas est\u00e1n produciendo una miel de color verde y azul.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<div>Y todo porque los insectos est\u00e1n comiendoM&amp;m&#8217;s&nbsp;(los \u00ablacasitos\u00bb americanos)&#8230; o mejor dicho, est\u00e1n comiendo los residuos azucarados de una planta productora que la empresa tiene en esa localidad francesa. La noticia fue publicada ayer por el diario franc\u00e9s&nbsp;Le Monde.<\/div>\n<p>Los responsables de la planta aseguran que dieron cuenta del problema a los apicultores y que ya est\u00e1n trabajando para solucionar el vertido de esos \u00abdulces deshechos\u00bb.<\/p>\n<p>Dicen que han limpiado los contenedores y que los van a poner desde ahora en un recinto cerrado.<\/p>\n<p>Ahora queda determinar si la miel est\u00e1 envenenada por ello aunque los apicultores de la zona lo tienen claro: \u00abPara m\u00ed esto no es miel. No es vendible\u00bb, asegura uno de sus portavoces.<\/p>\n<p><a href=\"http:\/\/www.abc.es\/20121005\/ciencia\/abci-abejas-miel-azul-201210051126.html\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los apicultores de&nbsp;Ribeauville, en la regi\u00f3n de Alsacia (Francia) no pueden creer lo que ven sus ojos, seg\u00fan informa&nbsp;\u00abQue!\u00bb. Sus abejas est\u00e1n produciendo una miel de color verde y azul.<\/p>\n","protected":false},"author":3,"featured_media":20284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-20285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20285"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20284"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}