{"id":20299,"date":"2012-10-06T15:32:23","date_gmt":"2012-10-06T19:32:23","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/chaleco-permite-a-los-usuarios-de-facebook-abrazarse-en-la-distancia\/"},"modified":"2012-10-06T15:32:23","modified_gmt":"2012-10-06T19:32:23","slug":"chaleco-permite-a-los-usuarios-de-facebook-abrazarse-en-la-distancia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/chaleco-permite-a-los-usuarios-de-facebook-abrazarse-en-la-distancia\/","title":{"rendered":"Chaleco permite a los usuarios de Facebook abrazarse en la distancia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20298\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_7186a8007344d06c311b3c642bb6f70f-300x199.jpg\" width=\"300\" height=\"199\" alt=\"7186a8007344d06c311b3c642bb6f70f-300x199\" class=\"caption\" style=\"float: left;\" \/>Un chaleco dise\u00f1ado en el prestigioso Instituto de Tecnolog\u00eda de Massachusetts (MIT) permite a los usuarios de Facebook abrazarse sin importar qu\u00e9 tan lejos est\u00e9n f\u00edsicamente.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El chaleco \u201cLike-A-Hug\u201d presentado este viernes en el sitio web de la dise\u00f1adora Melissa Kit Chow fue promocionado como un \u201cmedio de comunicaci\u00f3n social llevable\u201d.<\/p>\n<p>De acuerdo a la informaci\u00f3n del sitio, la prenda se infla para abrazar a quienes la utilizan cada vez que un contacto de Facebook pone \u201cMe Gusta\u201d en una publicaci\u00f3n que hayan hecho en la red social.<\/p>\n<p>Chow trabaj\u00f3 con Andy Payne y Phil Seaton en el Media Lab (laboratorio dentro de la Escuela de Arquitectura y Planificaci\u00f3n) del Instituto de Tecnolog\u00eda de Massachusetts para crear los chalecos inflados negros, informa la p\u00e1gina.<\/p>\n<p>Los chalecos \u201cLike-A-Hug\u201d permiten que los abrazos \u201csean dados a trav\u00e9s de Facebook, acerc\u00e1ndonos a pesar de la distancia f\u00edsica\u201d, dijo Chow en una entrada describiendo la prenda.<\/p>\n<p>Adem\u00e1s, si quien env\u00eda el abrazo tambi\u00e9n est\u00e1 utilizando el Like-A-Hug, el receptor puede devolv\u00e9rselo apretando su propio chaleco para desinflarlo.<\/p>\n<p>Chow se describi\u00f3 a s\u00ed misma como una graduada de la Escuela de Dise\u00f1o de Harvard que distorsiona sutilmente las interacciones de cada d\u00eda con el entorno para lograr el \u201cdespertar de una experiencia sensorial espacial\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un chaleco dise\u00f1ado en el prestigioso Instituto de Tecnolog\u00eda de Massachusetts (MIT) permite a los usuarios de Facebook abrazarse sin importar qu\u00e9 tan lejos est\u00e9n f\u00edsicamente.<\/p>\n","protected":false},"author":3,"featured_media":20298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-20299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20299"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20298"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}