{"id":20310,"date":"2012-10-07T19:58:45","date_gmt":"2012-10-07T23:58:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-semana-pasada-vergonzoso-espectaculo-protagonizado-por-concejal-del-p-l-d-y-vice-alcalde-en-sala-capitular-de-sosua\/"},"modified":"2012-10-07T19:58:45","modified_gmt":"2012-10-07T23:58:45","slug":"la-semana-pasada-vergonzoso-espectaculo-protagonizado-por-concejal-del-p-l-d-y-vice-alcalde-en-sala-capitular-de-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-semana-pasada-vergonzoso-espectaculo-protagonizado-por-concejal-del-p-l-d-y-vice-alcalde-en-sala-capitular-de-sosua\/","title":{"rendered":"La semana pasada: Vergonzoso espect\u00e1culo protagonizado por concejal del P L D y Vice Alcalde en Sala Capitular de Sos\u00faa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16841\" style=\"float: left;\" alt=\"ayuntamiento_de_sosua\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_ayuntamiento_de_sosua.png\" width=\"300\" height=\"225\" \/>Sos\u00faa:- De vergonzoso, catalogaron mun\u00edcipes consultados con respeto a espect\u00e1culo de mal gusto protagonizado por el vice alcalde de aqu\u00ed empresario Wilfredo (Willy El Chamo)&nbsp;Olivences y el concejal del Partido de la Liberaci\u00f3n Dominicana, Santos Pe\u00f1al\u00f3 (Beroa) en medio de una sesi\u00f3n del Concejo Municipal, donde se conoc\u00eda una moci\u00f3n relativa a la ocupaci\u00f3n de las aceras del frente de un negocio que remodela el vice alcalde.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan una fuente de entero cr\u00e9dito el concejal Yhonny Matos Mella, actual presidente del concejo se vio precisado a llamar al orden a los referidos miembros del cabildo quienes no obtemperaron al llamado disciplinario culminando casi a la garata con pu\u00f1os, empero manifest\u00f3 que mientras el vice alcalde Olivences defend\u00eda su posici\u00f3n con respecto a la moci\u00f3n el concejal lo llam\u00f3 v\u00e1ndalo, entre otros t\u00e9rminos despectivos lo que provoc\u00f3 la reacci\u00f3n de Olivences llegando hasta a citarse para resolver en las calles las diferencias.<\/p>\n<p>Esperemos la guerra de intereses propio de los pol\u00edticos y empresarios no den pie a un hecho lamentable que nos averg\u00fcence y nos haga sufrir m\u00e1s de lo que hemos sufrido, desde esta humilde tribuna llamamos a la concordia y nos sentimos confiados en todo se quedar\u00e1 ah\u00ed, por las dotes de conciliaci\u00f3n que desde siempre ha exhibido la se\u00f1ora alcaldesa.<\/p>\n<p>Tranquilos muchachos todav\u00eda nos toca soportarlos cuatro a\u00f1os m\u00e1s\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>[<a href=\"http:\/\/sosuadigital.net\/index.php\/noticias-del-momento\/2840-vergonzoso-espectaculo-protagonizado-por-concejal-del-p-l-d-y-vice-alcalde-en-sala-capitular-de-sosua-\">FUENTE<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa:- De vergonzoso, catalogaron mun\u00edcipes consultados con respeto a espect\u00e1culo de mal gusto protagonizado por el vice alcalde de aqu\u00ed empresario Wilfredo (Willy El Chamo)&nbsp;Olivences y el concejal del Partido de la Liberaci\u00f3n Dominicana, Santos Pe\u00f1al\u00f3 (Beroa) en medio de una sesi\u00f3n del Concejo Municipal, donde se conoc\u00eda una moci\u00f3n relativa a la ocupaci\u00f3n de las aceras del frente de un negocio que remodela el vice alcalde.<\/p>\n","protected":false},"author":3,"featured_media":16841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20310"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16841"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}