{"id":20411,"date":"2012-10-11T12:05:34","date_gmt":"2012-10-11T16:05:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/kelloggs-retira-cereales-por-temor-a-contaminacion-con-metales\/"},"modified":"2012-10-11T12:05:34","modified_gmt":"2012-10-11T16:05:34","slug":"kelloggs-retira-cereales-por-temor-a-contaminacion-con-metales","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/kelloggs-retira-cereales-por-temor-a-contaminacion-con-metales\/","title":{"rendered":"Kellogg&#8217;s retira cereales por temor a contaminaci\u00f3n con metales"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20410\" style=\"float: left;\" alt=\"kellogg_cereals_304x171_ap\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_kellogg_cereals_304x171_ap.jpg\" width=\"304\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_kellogg_cereals_304x171_ap.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_kellogg_cereals_304x171_ap-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>La multinacional estadounidense Kellogg&#8217;s retir\u00f3 millones de cajas de sus cereales \u00abMini-Wheats\u00bb por posible contaminaci\u00f3n con fragmentos met\u00e1licos durante el proceso de producci\u00f3n.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un portavoz de la compa\u00f1\u00eda inform\u00f3 que unos 3,2 millones de cajas fueron retiradas de los mercados de Estados Unidos, Canad\u00e1 y M\u00e9xico, seg\u00fan la agencia de noticias AFP.<\/p>\n<p>De acuerdo con lo notificado a la Administraci\u00f3n de Alimentos y F\u00e1rmacos (FDA, por sus siglas en ingl\u00e9s), las partidas afectadas tienen fechas de caducidad comprendidas entre abril y septiembre de 2013.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La multinacional estadounidense Kellogg&#8217;s retir\u00f3 millones de cajas de sus cereales \u00abMini-Wheats\u00bb por posible contaminaci\u00f3n con fragmentos met\u00e1licos durante el proceso de producci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":20410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20411"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20410"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}