{"id":20475,"date":"2012-10-15T12:02:42","date_gmt":"2012-10-15T16:02:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/httpwwwsosuanewscomindexphp\/"},"modified":"2012-10-15T12:02:42","modified_gmt":"2012-10-15T16:02:42","slug":"httpwwwsosuanewscomindexphp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/httpwwwsosuanewscomindexphp\/","title":{"rendered":"Charyt\u00edn crea p\u00e1nico y preocupa por mensajes en twitter"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20474\" style=\"float: left;\" alt=\"charitynGoico\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_charitynGoico.jpg\" width=\"238\" height=\"320\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_charitynGoico.jpg 238w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_charitynGoico-223x300.jpg 223w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/>Charyt\u00edn ha preocupado a sus seguidores de Twitter luego de publicar enigm\u00e1ticos tweets acerca de la vida, la muerte, los vicios y las separaciones, as\u00ed lo hizo saber el peri\u00f3dico Primera Hora, en su edici\u00f3n del pasado s\u00e1bado.<\/div>\n<p>  <!--more-->  <\/p>\n<div>La dominicana primero dijo el s\u00e1bado, que le encantar\u00eda que la muerte viniera antes que la vida. Despu\u00e9s aclar\u00f3 que desea una vida nueva.<\/div>\n<div>\u201cMe hubiera encantado que la muerte fuera antes que la vida. Ya todos hubi\u00e9ramos \u2018salido de eso\u2019\u201d, expres\u00f3 la animadora dominicana en su cuenta de esa red social de Internet esta tarde. \u201cOigan&#8230;..esta vida no es un \u2018ensayo\u2019, \u00bfverdad? Porque yo o pienso repetirla&#8230; A m\u00ed que me den una \u2018nueva\u2019\u201d, a\u00f1adi\u00f3 minutos despu\u00e9s.<\/div>\n<div>La esposa del productor El\u00edn Ortiz continu\u00f3 con su desahogo al a\u00f1adir este otro tweet: \u201cLa vida puede conmigo&#8230; \u00a1el tiempo no!\u201d.<\/div>\n<div>Charyt\u00edn Goyco qued\u00f3 fuera de Univisi\u00f3n y Telefutura el a\u00f1o pasado luego de conducir con \u00e9xito el programa \u201cEsc\u00e1ndalo TV\u201d.<\/div>\n<div>Desde entonces, ha manifestado su deseo de regresar a la televisi\u00f3n, un anhelo salpicado de melancol\u00eda, pero aderezado por una firme fe en Dios que expresa constantemente.<\/div>\n<div>En ese sentido, estos mensajes han preocupado a algunos de sus fan\u00e1ticos, quienes le han enviado fortaleza. Estas reflexiones se suman a otras que ha venido compartiendo la mam\u00e1 del actor Shalim en el trayecto de esta semana.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Charyt\u00edn ha preocupado a sus seguidores de Twitter luego de publicar enigm\u00e1ticos tweets acerca de la vida, la muerte, los vicios y las separaciones, as\u00ed lo hizo saber el peri\u00f3dico Primera Hora, en su edici\u00f3n del pasado s\u00e1bado.<\/p>\n","protected":false},"author":3,"featured_media":20474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20475"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20474"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}