{"id":20533,"date":"2012-10-17T14:32:00","date_gmt":"2012-10-17T18:32:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/interpol-captura-dos-rusos-buscado-por-estafa-y-narcotrafico\/"},"modified":"2012-10-17T14:32:00","modified_gmt":"2012-10-17T18:32:00","slug":"interpol-captura-dos-rusos-buscado-por-estafa-y-narcotrafico","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/interpol-captura-dos-rusos-buscado-por-estafa-y-narcotrafico\/","title":{"rendered":"Interpol Captura dos rusos buscado por estafa y narcotrafico"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20532\" style=\"float: left;\" alt=\"fotominiatura_rusodetenidos\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_fotominiatura_rusodetenidos.jpg\" width=\"630\" height=\"250\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_fotominiatura_rusodetenidos.jpg 630w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_fotominiatura_rusodetenidos-300x119.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/>Una mujer y un hombre de nacionalidad rusa fueron apresados ayer en dos allanamientos realizados en Punta Cana, La Altagracia, y en Sos\u00faa, Puerto Plata, por existir en su contra ordenes de capturas internacionales.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Se trata de Daria Vinogradova, contra quien existe una difusi\u00f3n roja por asuntos relacionados con drogas, y Vladimir Kondrashin, buscado en las mismas condiciones, pero por presunto delito de estafa.<\/p>\n<p>Los arrestos fueron realizados por personal de la OCN-Interpol dominicana, en coordinaci\u00f3n con miembros de la Direcci\u00f3n Nacional de Investigaciones (DNI), luego de labores de inteligencia desplegadas durante varias semanas en las referidas comunidades.<span id=\"more-6232\">&nbsp;<\/span><\/p>\n<p>Dijo que los extranjeros, se\u00f1alados como pr\u00f3fugos, fueron arrestados en el caso de Vinogradova, en atenci\u00f3n a la difusi\u00f3n 228-2085, por tr\u00e1fico de drogas y asociaci\u00f3n o grupo delictivo.<\/p>\n<p>Mientras que Kondrashin fue capturado mediante la difusi\u00f3n roja 2011-51215-1, por presunto delito de estafa.<\/p>\n<p>Ambos detenidos se encuentran bajo custodia de la OCN-Interpol dominicana y ser\u00e1n entregados a oficiales de la Interpol de Mosc\u00fa, quienes los escoltaran hasta su pa\u00eds de origen, para que enfrenten los delitos que se les imputa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una mujer y un hombre de nacionalidad rusa fueron apresados ayer en dos allanamientos realizados en Punta Cana, La Altagracia, y en Sos\u00faa, Puerto Plata, por existir en su contra ordenes de capturas internacionales.<\/p>\n","protected":false},"author":3,"featured_media":20532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20533"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20532"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}