{"id":20545,"date":"2012-10-19T00:17:14","date_gmt":"2012-10-19T04:17:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/sosuense-oscar-taveras-debuta-en-pelota-invernal-con-excelente-participacion\/"},"modified":"2012-10-19T00:17:14","modified_gmt":"2012-10-19T04:17:14","slug":"sosuense-oscar-taveras-debuta-en-pelota-invernal-con-excelente-participacion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sosuense-oscar-taveras-debuta-en-pelota-invernal-con-excelente-participacion\/","title":{"rendered":"Sosuense Oscar Taveras debuta en pelota invernal con excelente participaci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20544\" style=\"float: left;\" alt=\"oscar_taveras-aguilas1\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_oscar_taveras-aguilas1.jpg\" width=\"570\" height=\"300\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_oscar_taveras-aguilas1.jpg 570w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_oscar_taveras-aguilas1-300x157.jpg 300w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/>San Francisco de Macor\u00eds.- El sosuense, novato sensaci\u00f3n de Los cardenales de San Luis, hizo su debut en la pelota invernal dominicana, con una magistral actuaci\u00f3n de 5-2 &nbsp;(1 doble, 1 hit y 1 anotada), aportando de esta manera para el triunfo de Las \u00c1guilas 9-5.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Carlos Mart\u00ednez, el doble compa\u00f1ero de equipos de Oscar Taveras, le fue prohibido el picheo con el equipo amarillo.<\/p>\n<p>Bartolo Col\u00f3n debutar\u00e1 con Las \u00c1guilas Cibae\u00f1as este mi\u00e9rcoles en el valle de la muerte, contra el equipo de El Escogido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Francisco de Macor\u00eds.- El sosuense, novato sensaci\u00f3n de Los cardenales de San Luis, hizo su debut en la pelota invernal dominicana, con una magistral actuaci\u00f3n de 5-2 &nbsp;(1 doble, 1 hit y 1 anotada), aportando de esta manera para el triunfo de Las \u00c1guilas 9-5.<\/p>\n","protected":false},"author":3,"featured_media":20544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20545"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20544"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}