{"id":20867,"date":"2012-10-31T17:31:47","date_gmt":"2012-10-31T21:31:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/consejos-para-evitar-fraudes-en-internet\/"},"modified":"2012-10-31T17:31:47","modified_gmt":"2012-10-31T21:31:47","slug":"consejos-para-evitar-fraudes-en-internet","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/consejos-para-evitar-fraudes-en-internet\/","title":{"rendered":"Consejos para evitar fraudes en Internet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-20866\" style=\"float: left;\" alt=\"fraudes-en-Internet\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_fraudes-en-Internet.jpg\" width=\"400\" height=\"300\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_fraudes-en-Internet.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/10\/sosua_images_fraudes-en-Internet-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Al igual que en el mundo real, en la web tambi\u00e9n hay gente que puede querer enga\u00f1arnos. La principal soluci\u00f3n es ser precavidos y cuidadosos al brindar datos personales y financieros .<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan datos provistos por Visa en 2011, 5 de cada 10 transacciones fraudulentas con tarjetas de cr\u00e9dito eran realizadas por Internet, lo que nos da un peque\u00f1o pantallazo sobre el escenario que se presenta.<\/p>\n<p>alaMaula, sitio de clasificados online en el que no hay que pagar con tarjetas de cr\u00e9dito sino que el cierre se hace en forma persona a persona, elabor\u00f3 un Dec\u00e1logo de Seguridad en E-Commerce, que aplica tanto a vendedores como consumidores<\/p>\n<p>Las transacciones por internet siguen creciendo en el mundo, y es por eso que alaMaula mantiene un fuerte compromiso de educaci\u00f3n, prevenci\u00f3n de fraude y acciones para garantizar la seguridad de sus usuarios en Argentina y Latinoam\u00e9rica.<\/p>\n<p>No conf\u00edes en precios sospechosamente bajos, comprueba cual es la media en el mercado verificando anuncios similares en la plataforma.<\/p>\n<p>Utiliza la mensajer\u00eda interna del sitio para un mejor seguimiento.<\/p>\n<p>Evita hacer clic en cualquier enlace que pueda resultar sospechoso o no relacionado con la operaci\u00f3n que est\u00e1 intentando llevar a cabo. Tampoco abra archivos adjuntos que sean de dudosa procedencia. Este tipo de t\u00e1cticas podr\u00eda ser utilizada por un usuario malicioso para infectar su equipo y hacerse luego con sus datos personales o financieros.<\/p>\n<p>Se cauteloso con la informaci\u00f3n personal o bancaria que compartes al vender o comprar en l\u00ednea, y evita realizar grandes transferencias de dinero si no est\u00e1s seguro sobre el perfil del vendedor.<\/p>\n<p>Evita utilizar sistemas de giros de pagos y transferencias an\u00f3nimos como Wester Union o MoneyGram, que no aseguren un reembolso en caso de estafa. Utiliza transferencias bancarias, contra reembolso o realiza tus pagos personalmente. Cuando hagas una venta controla siempre la calidad de los billetes que te entregan.<\/p>\n<p>Utiliza contrase\u00f1as seguras y \u00fanicas para cada servicio. No uses contrase\u00f1as relacionadas a fechas de nacimiento, n\u00fameros de documento o secuencias de letras o num\u00e9ricas. Crea claves de m\u00e1s de 8 caracteres combinando min\u00fasculas, may\u00fasculas, n\u00fameros y caracteres especiales siempre que sea posible. Renueva las contrase\u00f1as con cierta periodicidad.<\/p>\n<p>Evita acceder a tu correo electr\u00f3nico y sitios desde equipos p\u00fablicos o utilizando redes Wi-Fi inseguras o p\u00fablicas. Recuerda siempre finalizar su sesi\u00f3n antes de dejar el equipo. Se recomienda visitar p\u00e1ginas reconocidas.<\/p>\n<p>Desconf\u00eda de las personas que no provean un n\u00famero telef\u00f3nico verificable. Siempre trata de contactarte con tel\u00e9fonos fijos.<\/p>\n<p>Evita adquirir r\u00e9plicas de productos conocidos. No solo estar\u00e1s cometiendo un delito sino que estar\u00e1s poniendo en riesgo la privacidad de sus datos al intentar ahorrar un poco de dinero comprando un producto de inferior calidad.<\/p>\n<p>Por \u00faltimo, usa el sentido com\u00fan, si algo te resulta sospechoso o tienes dudas no continues con la operaci\u00f3n. Informate antes de poner en riesgo tu privacidad y seguridad.<\/p>\n<p>Es indispensable que te apoyes en el \u00e1rea de atenci\u00f3n al cliente de la plataforma en la que est\u00e9s operando, para recibir asesoramiento y asistencia y as\u00ed operar en forma efectiva y segura. Por eso es conveniente que identifiques de antemano cuales son los canales de comunicaci\u00f3n con el Centro de ayuda del sitio y que priorices la plataforma que te da mejor respuesta y asistencia.<\/p>\n<p>Es fundamental que te apoyes en los centros de ayuda ante cualquier duda o consulta t\u00e9cnica para poder y que esto te haga sentir m\u00e1s seguro en cualquier operaci\u00f3n a trav\u00e9s de internet.<\/p>\n<p>La seguridad en internet es responsabilidad de las plataformas tecnol\u00f3gicas, medios de pago online, los centros de ayuda y tambi\u00e9n de los usuarios que son los principales beneficiarios de operar en internet.<\/p>\n<p><a href=\"http:\/\/www.infobae.com\/notas\/678607-Consejos-para-la-prevencion-de-fraudes-en-internet.html\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al igual que en el mundo real, en la web tambi\u00e9n hay gente que puede querer enga\u00f1arnos. La principal soluci\u00f3n es ser precavidos y cuidadosos al brindar datos personales y financieros .<\/p>\n","protected":false},"author":3,"featured_media":20866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-20867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=20867"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/20867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/20866"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=20867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=20867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=20867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}