{"id":21065,"date":"2012-11-08T16:43:34","date_gmt":"2012-11-08T20:43:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/nuria-piera-podria-ser-la-directora-de-cdn\/"},"modified":"2012-11-08T16:43:34","modified_gmt":"2012-11-08T20:43:34","slug":"nuria-piera-podria-ser-la-directora-de-cdn","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nuria-piera-podria-ser-la-directora-de-cdn\/","title":{"rendered":"Nuria Piera podr\u00eda ser la directora de CDN"},"content":{"rendered":"<div align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21064\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_833c7f7365de67f6c07e76c479eb7eb6_300x226.jpg\" width=\"300\" height=\"226\" alt=\"833c7f7365de67f6c07e76c479eb7eb6_300x226\" class=\"caption\" style=\"float: left;\" \/>La experimentada periodista de investigaci\u00f3n y licenciada en Leyes, Nuria Piera, podr\u00eda pasar a asumir la direcci\u00f3n de CDN (canal 37) y CDN 2 (canal 38), de Multimedios \u201cEl Caribe\u201d en los pr\u00f3ximos d\u00edas.<\/div>\n<p>  <!--more-->  <a name=\"more\" target=\"_blank\"><\/a><br \/>Al parecer todo es cuesti\u00f3n de tiempo para que la respetada comunicadora asuma la posici\u00f3n, seg\u00fan inform\u00f3 una fuente a la secci\u00f3n \u00a1Alegr\u00eda! <\/p>\n<div align=\"justify\">Nuria Piera continuar\u00e1 con su programa de investigaci\u00f3n period\u00edstica por Color Visi\u00f3n, canal 9, los s\u00e1bados de 9:00 a 11:00 de la noche y su resumen especial por CDN (canal 37), los lunes a las 8:00 de la noche.&nbsp; <\/p>\n<p>La multipremiada periodista ganadora de El Soberano en el a\u00f1o 1999 y de los premios que entrega la Asociaci\u00f3n de Cronistas de Arte (Acroarte), es adem\u00e1s miembro de la Asociaci\u00f3n Dominicana de Productores de Televisi\u00f3n (Adomprotel).<\/p>\n<\/p><\/div>\n<div align=\"justify\">Seg\u00fan se supo, en los pr\u00f3ximos d\u00edas se estar\u00eda realizando el anuncio oficial.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Hoy.com.do&nbsp;<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/blogger.googleusercontent.com\/tracker\/222000870403453191-3397061864140348052?l=www.sacandomelao.com\" alt=\"\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La experimentada periodista de investigaci\u00f3n y licenciada en Leyes, Nuria Piera, podr\u00eda pasar a asumir la direcci\u00f3n de CDN (canal 37) y CDN 2 (canal 38), de Multimedios \u201cEl Caribe\u201d en los pr\u00f3ximos d\u00edas.<\/p>\n","protected":false},"author":3,"featured_media":21064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-21065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21065"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21064"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}