{"id":21145,"date":"2012-11-11T07:30:33","date_gmt":"2012-11-11T11:30:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/icomo-saben-los-animales-hacia-donde-migrar\/"},"modified":"2012-11-11T07:30:33","modified_gmt":"2012-11-11T11:30:33","slug":"icomo-saben-los-animales-hacia-donde-migrar","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/icomo-saben-los-animales-hacia-donde-migrar\/","title":{"rendered":"\u00bfC\u00f3mo saben los animales hacia donde migrar?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21141\" style=\"float: left;\" alt=\"como_saben_la_aves_donde_van\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_como_saben_la_aves_donde_van.jpg\" width=\"304\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_como_saben_la_aves_donde_van.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_como_saben_la_aves_donde_van-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>Algunas aves, peces, tortugas y ballenas recorren enormes distancias para encontrar comida o aparearse. La que viaja m\u00e1s lejos es la becasina de cola barrada, que vuela m\u00e1s de 10.000 km desde Nueva Zelanda a Alaska.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Los \u00e1nades son capaces de encontrar el norte analizando las estrellas, una habilidad gen\u00e9ticamente programada.<\/p>\n<p>Muchas otras aves, al igual que las salamandras, los salmones y los h\u00e1msteres, utilizan el campo magn\u00e9tico de la tierra.<\/p>\n<p>Las tortugas bobas pueden sentir la fuerza y la direcci\u00f3n del campo magn\u00e9tico de la tierra poco despu\u00e9s de su nacimiento, y luego usar esta habilidad para navegar a lo largo de su ruta migratoria.<\/p>\n<p>Otros animales utilizan las caracter\u00edsticas de la tierra, como cordilleras, r\u00edos y oc\u00e9anos.<\/p>\n<p>Los \u00f1us siguen el olor de la lluvia y los salmones hacen uso de su olfato para volver a la misma corriente que los vio nacer.<\/p>\n<h2>\u00bfEl hombre seguir\u00e1 batiendo r\u00e9cords de atletismo indefinidamente?<\/h2>\n<div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-21142\" alt=\"\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_10_08_121008114731_usain_bolt_304x171_getty_nocredit.jpg\" width=\"304\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_10_08_121008114731_usain_bolt_304x171_getty_nocredit.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_10_08_121008114731_usain_bolt_304x171_getty_nocredit-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/> <\/p>\n<p>La velocidad al correr est\u00e1 limitada por nuestra anotom\u00eda.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>Los deportes ol\u00edmpicos mas \u00abpuros\u00bb, como correr, saltar y nadar, est\u00e1n limitados por nuestra anatom\u00eda.<\/p>\n<p>El r\u00e9cord de 100 metros planos probablemente nunca ser\u00e1 menos que 8,99 segundos, porque las fuerzas necesarias para hacer menos tiempo, romper\u00edan los tendones de los huesos.<\/p>\n<p>Es poco probable que la evoluci\u00f3n cambie tanto nuestro cuerpo como para pasar sobrepasar esos l\u00edmites.<\/p>\n<p>Sin embargo, si las piernas bi\u00f3nicas de los paral\u00edmpicos contin\u00faan evolucionando, es posible que alg\u00fan d\u00eda rompan los r\u00e9cords del atletismo convencional.<\/p>\n<p>Seguramente se inventar\u00e1n m\u00e1s deportes con nuevos r\u00e9cords que romper.<\/p>\n<h2>\u00bfLa estatura la determinan m\u00e1s los padres que las madres?<\/h2>\n<div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-21143\" alt=\"\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_04_04_120404122329_height_measurment_304x171_bbc_nocredit.jpg\" width=\"304\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_04_04_120404122329_height_measurment_304x171_bbc_nocredit.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_04_04_120404122329_height_measurment_304x171_bbc_nocredit-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/> <\/p>\n<p>En lo que se refiere a la estatura, heredamos los genes de ambos padres y de igual manera.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>No. La estatura adulta se determina por una combinaci\u00f3n de genes, dieta y hormonas.<\/p>\n<p>Heredamos los genes de ambos padres y de igual manera.<\/p>\n<p>Es cierto que la estatura se puede predecir con bastante precisi\u00f3n a partir de la estatura del padre y de la madre.<\/p>\n<p>Pero s\u00f3lo podemos llegar a nuestro m\u00e1ximo potencial si contamos con una buena alimentaci\u00f3n durante nuestra infancia y adolescencia &#8211; y cuando se trata de alimentaci\u00f3n, es probable que sean las mam\u00e1s las m\u00e1s influyentes.<\/p>\n<h2>\u00bfPodr\u00eda existir agua en otros lugares del sistema solar?<\/h2>\n<div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-21144\" alt=\"\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_11_09_121109123136_marte_304x171_associatedpress_nocredit.jpg\" width=\"304\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_11_09_121109123136_marte_304x171_associatedpress_nocredit.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/wscdn.bbc.co.uk_worldservice_assets_images_2012_11_09_121109123136_marte_304x171_associatedpress_nocredit-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/> <\/p>\n<p>Los signos de erosi\u00f3n del agua y el flujo de escombros en Marte se ven en esta imagen de alta resoluci\u00f3n.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>La tierra es el \u00fanico planeta que tiene grandes cantidades de agua corriente, aunque algunos cient\u00edficos afirman que Marte podr\u00eda albergar cantidades sustanciales.<\/p>\n<p>A principios de este a\u00f1o, un equipo dirigido por Francis McCubbin, de la Universidad de Nuevo M\u00e9xico, descubri\u00f3 compuestos hidratados en meteoritos provenientes de Marte.<\/p>\n<p>Argumentan que estos compuestos apoyan la existencia de grandes cantidades de agua en las rocas, debajo de la superficie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunas aves, peces, tortugas y ballenas recorren enormes distancias para encontrar comida o aparearse. La que viaja m\u00e1s lejos es la becasina de cola barrada, que vuela m\u00e1s de 10.000 km desde Nueva Zelanda a Alaska.<\/p>\n","protected":false},"author":3,"featured_media":21141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-21145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21145"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21141"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}