{"id":21203,"date":"2012-11-13T18:38:48","date_gmt":"2012-11-13T22:38:48","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/un-ingeniero-de-google-crea-un-escaner-de-libros-con-la-ayuda-de-una-aspiradora\/"},"modified":"2012-11-13T18:38:48","modified_gmt":"2012-11-13T22:38:48","slug":"un-ingeniero-de-google-crea-un-escaner-de-libros-con-la-ayuda-de-una-aspiradora","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-ingeniero-de-google-crea-un-escaner-de-libros-con-la-ayuda-de-una-aspiradora\/","title":{"rendered":"Un ingeniero de Google crea un esc\u00e1ner de libros con la ayuda de una aspiradora"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-21202\" alt=\"scanner_con_aspiradora\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_scanner_con_aspiradora.jpg\" width=\"592\" height=\"298\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_scanner_con_aspiradora.jpg 592w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_scanner_con_aspiradora-300x151.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_scanner_con_aspiradora-400x200.jpg 400w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/>Teniendo en cuenta que en Google trabajan por ofrecer de forma digital una gran cantidad de libros que puedan estar al alcance de cualquiera, era de esperar que alguna mente pensante de Mountain View estuviera exprimiendo sus neuronas con la intenci\u00f3n de facilitar el proceso de digitalizaci\u00f3n del viejo formato. Y as\u00ed es como ha nacido este peculiar esc\u00e1ner, ya que es fruto del trabajo de Dany Qumsiyeh, un ingeniero de Google que ha sabido aprovechar el tiempo que la empresa deja para desarrollar proyectos personales.<br \/> <!--more-->  <\/p>\n<p>Tal y como explica en el v\u00eddeo que tienes tras el salto, el equipo se encarga de desplazar horizontalmente un libro abierto que, una vez escaneado, pasa por una zona de succi\u00f3n accionada por una aspiradora (s\u00ed, como la que tienes en casa) que se encarga de atrapar la p\u00e1gina escaneada. Este movimiento automatizado permite digitalizar un libro de 1.000 p\u00e1ginas en 90 minutos, aunque siempre requerir\u00e1 una peque\u00f1a configuraci\u00f3n de no m\u00e1s de 40 segundos con la que ajustar el tama\u00f1o y grosor del libro a trabajar. Seg\u00fan su creador, el precio de esta herramienta ronda los 1.500 d\u00f3lares, aunque asegura que todav\u00eda quedan muchos detalles por perfilar antes de plantear una salida comercial.<\/p>\n<p>[V\u00eda <a href=\"http:\/\/www.theverge.com\/2012\/11\/13\/3639016\/google-books-scanner-vacuum-diy\" target=\"_blank\">The Verge<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teniendo en cuenta que en Google trabajan por ofrecer de forma digital una gran cantidad de libros que puedan estar al alcance de cualquiera, era de esperar que alguna mente pensante de Mountain View estuviera exprimiendo sus neuronas con la intenci\u00f3n de facilitar el proceso de digitalizaci\u00f3n del viejo formato. Y as\u00ed es como ha nacido este peculiar esc\u00e1ner, ya que es fruto del trabajo de Dany Qumsiyeh, un ingeniero de Google que ha sabido aprovechar el tiempo que la empresa deja para desarrollar proyectos personales.<\/p>\n","protected":false},"author":3,"featured_media":21202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-21203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21203"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21202"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}