{"id":21235,"date":"2012-11-14T20:03:50","date_gmt":"2012-11-15T00:03:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/amazon-principal-vendedor-de-lectores-de-libros-electronicos-del-mundo\/"},"modified":"2012-11-14T20:03:50","modified_gmt":"2012-11-15T00:03:50","slug":"amazon-principal-vendedor-de-lectores-de-libros-electronicos-del-mundo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/amazon-principal-vendedor-de-lectores-de-libros-electronicos-del-mundo\/","title":{"rendered":"Amazon principal vendedor de lectores de libros electr\u00f3nicos del mundo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21234\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_amazon-may-be-launching-an-ebook-lending-library-which-would-not-be-the-first-of-its-kind-but-it.jpg\" width=\"240\" height=\"301\" alt=\"amazon-may-be-launching-an-ebook-lending-library-which-would-not-be-the-first-of-its-kind-but-it\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_amazon-may-be-launching-an-ebook-lending-library-which-would-not-be-the-first-of-its-kind-but-it.jpg 240w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_amazon-may-be-launching-an-ebook-lending-library-which-would-not-be-the-first-of-its-kind-but-it-239x300.jpg 239w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>Las editoriales se est\u00e1n lanzando a la edici\u00f3n en formato ebook y las previsiones de facturaci\u00f3n asociadas van en aumento. La facturaci\u00f3n del libro electr\u00f3nico va en aumento y el ebook ha empujado a realidades que hasta ahora eran marginales, como la autoedici\u00f3n. Y sin embargo, y teniendo en cuenta c\u00f3mo crecen los lectores en este formato, los lectores electr\u00f3nicos, los ereaders, no est\u00e1n viendo una progresi\u00f3n paralela a la de los libros a los que dan cobijo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00bfHan tocado techo los ereaders? Los env\u00edos de lectores electr\u00f3nicos, es decir, el n\u00famero de estos dispositivos que saldr\u00e1n de f\u00e1brica a tienda (no quiere decir que todos ellos se vendan, simplemente que estar\u00e1n all\u00ed esperando a sus potenciales compradores), alcanzar\u00e1n los 4,57 millones de unidades en el cuarto trimestre del a\u00f1o, seg\u00fan estimaciones de Digitimes. Las cifras suponen una ca\u00edda del 49,1% frente a la distribuci\u00f3n de terminales en el mismo per\u00edodo del a\u00f1o anterior. En todo el a\u00f1o, se habr\u00e1n distribuido 9,82 millones de terminales, lo que supone un 57,3% menos que en 2011.<\/p>\n<p>No es que los lectores no est\u00e9n interesados en leer en soporte electr\u00f3nico es que simplemente han encontrado otro dispositivo que les permite hacer eso y muchas m\u00e1s cosas. Los tablets de tama\u00f1o mini, como el Kindle Fire, el Nexus 7 o el iPad mini, est\u00e1n canibalizando el mercado de los lectores electr\u00f3nicos. El tama\u00f1o creciente de los smartphones tampoco juega a favor de los ereaders.<\/p>\n<p>Los contenidos se pueden leer de forma sencilla desde estos dispositivos descarg\u00e1ndose la app de la distribuidora de turno o incluso acudiendo a la tienda de contenidos de la compa\u00f1\u00eda que est\u00e1 detr\u00e1s del sistema operativo de estos terminales, lo que elimina la necesidad de hacerse con un ereader.<\/p>\n<p>Las previsiones de Digitimes es que se mantenga la tendencia y que las cifras de cierre de 2013 se coloquen 8,2 millones de unidades distribuidas, 6,3 millones para 2014 y 5 millones de unidades en 2015.<\/p>\n<p>La ca\u00edda de las ventas afectar\u00e1 de forma diferente a las compa\u00f1\u00edas que fabrican lectores, ya que la fuerza de ventas de cada una de ellas es diferente.<\/p>\n<p><strong>Amazon es la principal vendedora de lectores electr\u00f3nicos del mundo. Seg\u00fan Digitimes,<\/strong>&nbsp;la compa\u00f1\u00eda est\u00e1 detr\u00e1s del 55% de los ereaders distribuidos. Le siguen la japonesa Kobo, con el 20% de los lectores electr\u00f3nicos distribuidos; Barnes&amp;Noble, con el 10%;&nbsp; y Sony, con el 6. Entre estas compa\u00f1\u00edas se reparten el 91% de los env\u00edos: a las dem\u00e1s les queda un limitado 9%.<\/p>\n<p><a href=\"http:\/\/www.ticbeat.com\/sim\/los-ebooks-ya-son-para-lectores-electrnicos\/\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las editoriales se est\u00e1n lanzando a la edici\u00f3n en formato ebook y las previsiones de facturaci\u00f3n asociadas van en aumento. La facturaci\u00f3n del libro electr\u00f3nico va en aumento y el ebook ha empujado a realidades que hasta ahora eran marginales, como la autoedici\u00f3n. Y sin embargo, y teniendo en cuenta c\u00f3mo crecen los lectores en este formato, los lectores electr\u00f3nicos, los ereaders, no est\u00e1n viendo una progresi\u00f3n paralela a la de los libros a los que dan cobijo.<\/p>\n","protected":false},"author":3,"featured_media":21234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-21235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21235"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21234"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}