{"id":21293,"date":"2012-11-17T12:54:34","date_gmt":"2012-11-17T16:54:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/nashla-admite-fotos-de-ella-desnuda-se-las-tomo-hace-seis-anos\/"},"modified":"2012-11-17T12:54:34","modified_gmt":"2012-11-17T16:54:34","slug":"nashla-admite-fotos-de-ella-desnuda-se-las-tomo-hace-seis-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nashla-admite-fotos-de-ella-desnuda-se-las-tomo-hace-seis-anos\/","title":{"rendered":"Nashla admite fotos de ella desnuda; se las tom\u00f3 hace seis a\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21292\" style=\"float: left;\" alt=\"Nashla_Bogaert\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_Nashla_Bogaert.jpg\" width=\"300\" height=\"380\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_Nashla_Bogaert.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_Nashla_Bogaert-236x300.jpg 236w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00abNo tengo nada de qu\u00e9 avergonzarme\u00bb, afirma la comunicadora tras advertir que llevar\u00e1 el caso a la justicia. Nashla Bogaert admiti\u00f3 que son suyas las fotos que circulan en internet y que la muestran desnuda en una ba\u00f1era, pero advirti\u00f3 que llevar\u00e1 el caso a los tribunales.  <!--more-->  <\/p>\n<p>Las im\u00e1genes fueron tomadas hace seis a\u00f1os, cuando ella ten\u00eda 19, por una persona que gozaba de su confianza (evidentemente que su pareja de entonces).<\/p>\n<p>\u00abHace aproximadamente seis a\u00f1os, cuando apenas ten\u00eda 19 a\u00f1os, en un ambiente estrictamente privado e \u00edntimo, una persona que gozaba de mi total confianza tom\u00f3 las fotograf\u00edas que hoy est\u00e1n siendo divulgadas sin mi consentimiento, atentando totalmente contra mis derechos y tratando de lacerar una carrera que tanto esfuerzo me ha costado construir\u00bb, coment\u00f3 en el comunicado grabado por el canal 7.<\/p>\n<p>Alguien, no mencion\u00f3 nombre, se dio a la tarea de difundir las fotos que circulan en la internet (M\u00e1sVip no las ha publicado por respeto a la comunicadora) y que ella cre\u00eda se encontraban \u00aben manos de una sola persona\u00bb.<\/p>\n<p><object width=\"536\" height=\"353\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/hgYelyVtggU&amp;feature=player_embedded#t=3s\" \/><embed width=\"536\" height=\"353\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/hgYelyVtggU&amp;feature=player_embedded#t=3s\" wmode=\"opaque\"\/><\/object><\/p>\n<p><strong>SU ADVERTENCIA<\/strong><\/p>\n<p>Nashla advirti\u00f3 que someter\u00eda a \u00abtodos aquellos\u00bb que subieron las im\u00e1genes, desde el origen hasta quienes la han reproducido. \u00abDeben saber que han cometido un grave delito, sancionado por la ley\u00bb.<\/p>\n<p>Al igual que ella, agreg\u00f3, cientos de j\u00f3venes son victimas de este tipo de acciones criminales\u2026 Y espera que su ejemplo sirva para que muchas puedan encontrar ayuda para poder actuar en momentos como \u00e9ste.<\/p>\n<p>\u00abLa violaci\u00f3n a la intimidad de las personas es un asunto grave, no puede ser tomado a la ligera\u2026 por eso nuestras leyes disponen de dr\u00e1sticas sanciones para quienes incurren en hechos como \u00e9ste, del cual soy soy v\u00edctima\u00bb, sostuvo.<\/p>\n<p>\u00abTodos me conocen, saben que soy una persona que actua con responsabildad\u00bb, coment\u00f3 al a\u00f1adir que dejar\u00e1 en manos de sus abogados las acciones a seguir.<\/p>\n<p>\u00abVoy a dejar en manos de mis abogados este asunto para que inicien las acciones pertinentes que sirvan sancionar a todo aquel que ha atentado contra mi intimidad\u00bb, expres\u00f3 en el video visto por MasVip.<\/p>\n<p><strong>NO SE AVERGUENZA<\/strong><\/p>\n<p>Luego a\u00f1adi\u00f3: \u00abYo quiero que quede claro que yo no tengo absolutamente nada de qu\u00e9 avergonzarme porque las figuras p\u00fablicas tambi\u00e9n tenemos una vida privada y sobre esto no estamos obligados a dar dar explicaciones de nada\u00bb.<\/p>\n<p>Tambi\u00e9n le agradeci\u00f3 \u00abde coraz\u00f3n y con el alma en las manos\u00bb a mucha gente \u00abpor darme tanto apoyo en las llamadas y los comentarios que he recibido. Ustedes han sido el az\u00facar que yo he necesitado para este trago tan amargo en mi carrera profesional\u00bb.<\/p>\n<p>Se despidi\u00f3 depositando su confianza en la justicia y con la certeza de que el p\u00fablico y los medios \u00abvan a saber respetar mi decisi\u00f3n de no seguir tratando este tema nunca m\u00e1s; personalmente es muy penoso\u00bb.<\/p>\n<p>Antes hab\u00eda dicho: \u00abEste inconveniente ser\u00e1 resuelto por las v\u00edas correspondientes, por lo que a trav\u00e9s de estas palabras lo cierro de manera oficial\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>[<a href=\"http:\/\/masvip.com.do\/index.php?option=com_k2&amp;view=item&amp;id=5670:nashla-admite-fotos-de-ella-desnuda-se-las-tom%C3%B3-hace-seis-a%C3%B1os&amp;Itemid=17\">Fuente<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abNo tengo nada de qu\u00e9 avergonzarme\u00bb, afirma la comunicadora tras advertir que llevar\u00e1 el caso a la justicia. Nashla Bogaert admiti\u00f3 que son suyas las fotos que circulan en internet y que la muestran desnuda en una ba\u00f1era, pero advirti\u00f3 que llevar\u00e1 el caso a los tribunales.<\/p>\n","protected":false},"author":3,"featured_media":21292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-21293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21293"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21292"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}