{"id":21317,"date":"2012-11-19T04:00:00","date_gmt":"2012-11-19T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/mecanismo-cerebral-relacionado-con-la-paralisis-del-musculo-de-la-respiracion-durante-el-sueno\/"},"modified":"2012-11-19T04:00:00","modified_gmt":"2012-11-19T08:00:00","slug":"mecanismo-cerebral-relacionado-con-la-paralisis-del-musculo-de-la-respiracion-durante-el-sueno","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mecanismo-cerebral-relacionado-con-la-paralisis-del-musculo-de-la-respiracion-durante-el-sueno\/","title":{"rendered":"Mecanismo cerebral relacionado con la par\u00e1lisis del m\u00fasculo de la respiraci\u00f3n durante el sue\u00f1o"},"content":{"rendered":"<p><i><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21316\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_2012_11_16_VQwncI47Izbk2idiVSVx53.jpg\" width=\"322\" height=\"482\" alt=\"2012_11_16_VQwncI47Izbk2idiVSVx53\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_2012_11_16_VQwncI47Izbk2idiVSVx53.jpg 322w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_2012_11_16_VQwncI47Izbk2idiVSVx53-200x300.jpg 200w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/>Un mecanismo cerebral que media en la inhibici\u00f3n de los m\u00fasculos respiratorios cr\u00edticos durante la fase REM del sue\u00f1o, en la que se produce un movimiento r\u00e1pido de los ojos (&#8216;rapid eye movement&#8217;), se ha identificado por primera vez en un nuevo estudio, ofreciendo la posibilidad de nuevos tratamientos para problemas respiratorios relacionados con el sue\u00f1o.&nbsp;<\/i><b>\u00abEl sue\u00f1o REM se acompa\u00f1a de una inhibici\u00f3n profunda de la actividad muscular\u00bb<\/b>, dijo el investigador<b>Richard Horner<\/b>, profesor de Medicina y Fisiolog\u00eda en la Universidad de Toronto, en Canad\u00e1.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;&nbsp; Los hallazgos, publicados en &#8216;American Journal of<b>&nbsp;Respiratory<\/b>&nbsp;and<b>Critical Care Medicine<\/b>&#8216;, muestran que esta \u00abpar\u00e1lisis\u00bb afecta a los m\u00fasculos respiratorios y es una de las causas de los ronquidos y otros problemas respiratorios, como la apnea obstructiva del sue\u00f1o. La apnea del sue\u00f1o es un problema com\u00fan y grave que aumenta el riesgo de ataques al coraz\u00f3n, presi\u00f3n arterial alta, diabetes, derrame cerebral y somnolencia diurna.<\/p>\n<p>&nbsp;&nbsp; En el estudio, realizado por la estudiante de doctorado Kevin Grace, las ratas fueron analizadas en los estados de sue\u00f1o y vigilia, manipulando la regi\u00f3n del cerebro que controla m\u00fasculos de la lengua durante el sue\u00f1o. La lengua es un m\u00fasculo de la respiraci\u00f3n importante debido a que su actividad mantiene el espacio a\u00e9reo abierto detr\u00e1s de la leng\u00fceta para permitir el paso efectivo de aire en los pulmones.<\/p>\n<p>&nbsp;&nbsp; La inhibici\u00f3n de la actividad de m\u00fasculo de la lengua en el sue\u00f1o en algunas personas conduce a movimientos hacia atr\u00e1s de la lengua y el consiguiente bloqueo del espacio a\u00e9reo, que conduce a episodios de autoasfixia (apnea del sue\u00f1o) que son rescatados por el despertar de su sue\u00f1o. Estos episodios pueden ocurrir cientos de veces por noche.<\/p>\n<p>&nbsp;&nbsp; Es importante destacar que los efectos de estas intervenciones en la activaci\u00f3n muscular fueron mayores durante el sue\u00f1o REM y m\u00ednimos o ausentes en los otros estados de sue\u00f1o y vigilia.<\/p>\n<p>&nbsp;&nbsp; La qu\u00edmica del cerebro que media en esta inhibici\u00f3n de la actividad respiratoria del m\u00fasculo en el sue\u00f1o REM es la acetilcolina, que act\u00faa a trav\u00e9s de receptores muscar\u00ednicos que est\u00e1n funcionalmente ligados a una clase particular de canal de potasio.<\/p>\n<p> &nbsp;&nbsp; \u00abLa identificaci\u00f3n de los mecanismos fundamentales responsables del cierre de un m\u00fasculo en el sue\u00f1o que es fundamental para la respiraci\u00f3n efectiva tambi\u00e9n halla un objetivo racional para dise\u00f1ar medicamentos que eviten esta falta de actividad y as\u00ed prevenir la apnea obstructiva del sue\u00f1o y otros problemas relacionados con el sue\u00f1o de respiraci\u00f3n\u00bb, concluye Horner.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un mecanismo cerebral que media en la inhibici\u00f3n de los m\u00fasculos respiratorios cr\u00edticos durante la fase REM del sue\u00f1o, en la que se produce un movimiento r\u00e1pido de los ojos (&#8216;rapid eye movement&#8217;), se ha identificado por primera vez en un nuevo estudio, ofreciendo la posibilidad de nuevos tratamientos para problemas respiratorios relacionados con el sue\u00f1o.&nbsp;\u00abEl sue\u00f1o REM se acompa\u00f1a de una inhibici\u00f3n profunda de la actividad muscular\u00bb, dijo el investigadorRichard Horner, profesor de Medicina y Fisiolog\u00eda en la Universidad de Toronto, en Canad\u00e1.<\/p>\n","protected":false},"author":3,"featured_media":21316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-21317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21317"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21316"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}