{"id":21348,"date":"2012-11-19T19:42:05","date_gmt":"2012-11-19T23:42:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/efemerides-se-celebra-hoy-el-dia-internacional-del-hombre\/"},"modified":"2012-11-19T19:42:05","modified_gmt":"2012-11-19T23:42:05","slug":"efemerides-se-celebra-hoy-el-dia-internacional-del-hombre","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/efemerides-se-celebra-hoy-el-dia-internacional-del-hombre\/","title":{"rendered":"Se celebra hoy el D\u00eda Internacional del Hombre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21347\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_15507_dia_del_hombre.jpg\" width=\"800\" height=\"775\" alt=\"15507_dia_del_hombre\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_15507_dia_del_hombre.jpg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_15507_dia_del_hombre-300x290.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Fue inaugurado en 1999 en Trinidad y Tobago, por Jerome Teelucksingh. Se trata de un evento apoyado por Naciones Unidas que se celebra en varios pa\u00edses del mundo.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Luego de que fuera inaugurado, en Trinidad y Tobago el D\u00eda Internacional del Hombre, un 19 de noviembre de 1999, por Jerome Teelucksingh, bajo el marco de un seminario p\u00fablico que trataba sobre la violencia, los cr\u00edmenes dom\u00e9sticos y la importancia de la vida en matrimonio, esta celebraci\u00f3n se ha ido expandiendo de a poco hacia otros pa\u00edses.<\/p>\n<p>Para Teelucksingh era importante darles tanto a ni\u00f1os, adolescentes, y hombres un d\u00eda para resaltar el rol positivo y las contribuciones que los varones tienen d\u00eda a d\u00eda para con sus comunidades.<\/p>\n<p>En la actualidad existe un comit\u00e9 dedicado a su celebraci\u00f3n, y cuyo principal objetivo es el de proteger y ofrecer un punto de referencia fiable par todos los hombres, as\u00ed como promover la igualdad de g\u00e9nero y celebrar la masculinidad.<\/p>\n<p>Los `6 Pilares` del D\u00eda Internacional del Hombre son:<\/p>\n<p>1. Promover modelos masculinos positivos, no s\u00f3lo las estrellas de cine y deportes de los hombres, sino los de todos los d\u00edas: varones trabajadores de clase media que viven vidas decentes y honestas.<\/p>\n<p>2. Celebrar las contribuciones positivas de los hombres a la sociedad, comunidad, familia, matrimonio, cuidado de ni\u00f1os, y para el medio ambiente.<\/p>\n<p>3. Centrarse en la salud y el bienestar social, emocional, f\u00edsico y espiritual de los varones.<\/p>\n<p>4. Poner de relieve la discriminaci\u00f3n contra los hombres, en las \u00e1reas de servicios sociales, las actitudes y expectativas sociales, y la ley.<\/p>\n<p>5. Mejorar las relaciones de g\u00e9nero y promover la igualdad de g\u00e9nero.<\/p>\n<p>6. Crear un mundo m\u00e1s seguro y mejor, donde la gente puede estar segura y crecer para alcanzar su pleno potencial.<\/p>\n<p>El D\u00eda Internacional del Hombre es reconocido por Naciones Unidas como un evento internacional, y es celebrado en diversos pa\u00edses del mundo como Australia, Estados Unidos, Canad\u00e1, Rusia, Jamaica, Hungr\u00eda, India, Irlanda, Malta, Reino Unido, Per\u00fa, entre otros.<\/p>\n<p><em><strong>Fuente: lmcordoba.com.ar<\/strong><\/em><\/p>\n<p>-.-.-.-.-.-<\/p>\n<p><strong>Un d\u00eda como hoy\u2026&nbsp;<\/strong><\/p>\n<p>1493 \u2013 Crist\u00f3bal Colon desembarca en la isa de Borinquen, a la que llam\u00f3 San Juan Bautista, hoy San Juan de Puerto Rico.<br \/>1600 \u2013 Nace el rey Carlos I de Inglaterra.<br \/>1752 \u2013 Nace George Rogers Clark, l\u00edder militar en la Guerra Revolucionaria.<br \/>1803 \u2013 Las tropas haitianas del general Dessalines entran victoriosas en Cap Francais, con lo que termina el dominio franc\u00e9s sobre la isla Espa\u00f1ola.<br \/>1805 \u2013 Nace Ferdinand de Lesseps, diplom\u00e1tico franc\u00e9s que proyect\u00f3 y dirigi\u00f3 la construcci\u00f3n del canal de Suez y trat\u00f3 de abrir el de Panam\u00e1.<br \/>1819 \u2013 Inauguraci\u00f3n del Museo del Prado (en Madrid, Espa\u00f1a).<br \/>1828 \u2013 Muere Franz Schubert, compositor austriaco.<br \/>1831 \u2013 Nace James A. Garfield, presidente de los Estados Unidos.<br \/>1837 \u2013 Inauguraci\u00f3n del primer ferrocarril cubano, que uni\u00f3 La Habana con la localidad de Benjucal.<br \/>1859 \u2013 Comienza la guerra de Africa entre tropas espa\u00f1olas y marroqu\u00edes.<br \/>1859 \u2013 Nace Mikhail Ippolitov-Ivanov, compositor ruso.<br \/>1867 \u2013 Nace el Dr. Angel Gallardo, naturalista y entom\u00f3logo argentino.<br \/>1875 \u2013 Nace Mikhail Ivanovich Kalinin, lider sovietico.<br \/>1882 \u2013 Dardo Rocha, gobernador de la provincia de Buenos Aires, funda la Ciudad de La Plata.<br \/>1888 \u2013 Nace Jos\u00e9 Ra\u00fal Capablanca, maestro de ajedrez, cubano.<br \/>1897 \u2013 Se corre la primera carrera de motos en pista, en Richmond, Inglaterra.<br \/>1905 \u2013 Nace Tommy Dorsey, m\u00fasico estadounidense.<br \/>1911 \u2013 Asesinan al presidente de la Rep\u00fablica Dominicana, general Ram\u00f3n C\u00e1ceres.<br \/>1913 \u2013 Nace Ata\u00falfo Argenta, director de orquesta espa\u00f1ol.<br \/>1917 \u2013 Nace Indira Ghandi, pol\u00edtica india.<br \/>1931 \u2013 Adolf Windaus difunde que ha sido posible la fabricaci\u00f3n de la vitamina D1 en forma de cristales puros.<br \/>1933 \u2013 Nace Larry King, conductor de la televisi\u00f3n estadounidense.<br \/>1934 \u2013 Guerra del Chaco. El Gobierno boliviano afirma en un comunicado que sus tropas dominan frente a sus rivales paraguayas.<br \/>1936 \u2013 Muere en la guerra civil espa\u00f1ola el dirigente anarquista Buenaventura Durruti.<br \/>1938 \u2013 Nace Robert Edward \u201cTed\u201d Turner III, empresario estadounidense.<br \/>1942 \u2013 Nace Calvin Klein, dise\u00f1ador de modas estadounidense.<br \/>1942 \u2013 Segunda Guerra Mundial: ofensiva rusa en el Volga.<br \/>1943 \u2013 Muere Froil\u00e1n Turcios, escritor y pol\u00edtico hondure\u00f1o.<br \/>1957 \u2013 El departamento de Defensa de EE.UU. anuncia que los pa\u00edses de Europa Occidental ser\u00e1n equipados con misiles at\u00f3micos de alcance medio.<br \/>1962 \u2013 Nace Jodie Foster, actriz estadounidense.<br \/>1963 \u2013 Muere Carmen Amaya, bailarina espa\u00f1ola.<br \/>1965 \u2013 nace Laurent Blanc, futbolista franc\u00e9s.<br \/>1977 \u2013 Hist\u00f3rico viaje del presidente de Egipto, Anwar el Sadat, a Israel.<br \/>1983 \u2013 Las fuerzas armadas iran\u00edes emprenden una ofensiva contra el Kurdist\u00e1n iraqu\u00ed.<br \/>1984 \u2013 Explosi\u00f3n de gas en una planta de almacenamiento en el cintur\u00f3n urbano de la ciudad de M\u00e9xico.<br \/>1985 \u2013 Cumbre en Ginebra entre los m\u00e1ximos dirigentes de EEUU, Ronald Reagan, y la URSS, Mijail Gorbachov, sobre la reducci\u00f3n de armas nucleares.<br \/>1986 \u2013 Un cuadro de Joan Mir\u00f3 alcanza la cifra de 2.350.000 d\u00f3lares en una subasta en Nueva York.<br \/>1988 \u2013 Muere Cristina Onassis, multimillonaria griega.<br \/>1990 \u2013 La OTAN y el Pacto de Varsovia firman la paz.<br \/>1992 \u2013 El presidente Boris Yeltsin anuncia en Se\u00fal la decisi\u00f3n de Rusia de paralizar la fabricaci\u00f3n de submarinos nucleares.<br \/>1994 \u2013 Muere Julian Symone, novelista brit\u00e1nico.<br \/>1995 \u2013 Victoria del candidato socialdem\u00f3crata Aleksander Kwasniewski, en las elecciones presidenciales de Polonia.<br \/>1996 \u2013 Hist\u00f3rica entrevista en el Vaticano entre el Papa Juan Pablo II y el presidente cubano, Fidel Castro.<br \/>1997 \u2013 Muere Pilar Mir\u00f3, directora espa\u00f1ola de cine.<br \/>1998 \u2013 Muere Alan J. Pakula, director y productor de cine de EE.UU.<br \/>2003 \u2013 Nace en Chile, M\u00e1ximo Sa\u00fal Menem, hijo del ex presidente Carlos Menem y Cecilia Bolocco.<br \/>2003 \u2013 Michael Jackson es acusado de nueve cargos por abuso de menores.<br \/>2003 \u2013 El Gobierno decide quitarle la concesi\u00f3n del Correo Argentino a la familia Macri.<\/p>\n<p><em><strong>Fuente: periodismo.com&nbsp;<\/strong><\/em><\/p>\n<div><\/div>\n<div><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fue inaugurado en 1999 en Trinidad y Tobago, por Jerome Teelucksingh. Se trata de un evento apoyado por Naciones Unidas que se celebra en varios pa\u00edses del mundo.&nbsp;<\/p>\n","protected":false},"author":3,"featured_media":21347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-21348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21348"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21347"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}