{"id":21403,"date":"2012-11-21T14:54:18","date_gmt":"2012-11-21T18:54:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/hoy-se-celebra-el-dia-mundial-de-la-television\/"},"modified":"2012-11-21T14:54:18","modified_gmt":"2012-11-21T18:54:18","slug":"hoy-se-celebra-el-dia-mundial-de-la-television","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hoy-se-celebra-el-dia-mundial-de-la-television\/","title":{"rendered":"Hoy se celebra el D\u00eda Mundial de la Televisi\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21402\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_Television-retro.jpg\" width=\"500\" height=\"332\" alt=\"Television-retro\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_Television-retro.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_Television-retro-300x199.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Desde 1996 la Asamblea General de la Organizaci\u00f3n de Naciones Unidas conmemora el papel de la televisi\u00f3n como \u201cs\u00edmbolo de la comunicaci\u00f3n y de la globalizaci\u00f3n en el mundo contempor\u00e1neo\u201d. Manteniendo el principio de la Organizaci\u00f3n, el Observatorio Europeo del Audiovisual ha publicado un nuevo informe sobre la concentraci\u00f3n de los medios.<\/p>\n<p>  <!--more-->  <\/p>\n<div id=\"cuerpoNoticia\">\n<p>Hoy mi\u00e9rcoles, 21 de noviembre, la Organizaci\u00f3n de Naciones Unidas, ONU celebra el D\u00eda Mundial de la Televisi\u00f3n para destacar el papel de este medio como un \u00abs\u00edmbolo de la comunicaci\u00f3n y la globalizaci\u00f3n en el mundo contempor\u00e1neo\u00bb.<\/p>\n<p>Este d\u00eda se conmemora desde 1996, a\u00f1o en el que&nbsp; la Asamblea General de la ONU consider\u00f3 que el medio de comunicaci\u00f3n se merec\u00eda una jornada de celebraci\u00f3n. La elecci\u00f3n de la fecha&nbsp; coincide con el inicio del primer Foro Mundial de la Televisi\u00f3n.&nbsp;&nbsp;<\/p>\n<\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td>Esta declaraci\u00f3n coincide con la publicaci\u00f3n del Observatorio Europeo del Audiovisual, que forma parte del Consejo de Europa, de un nuevo informe IRIS dedicado las formas en que los broadcasters&nbsp; pueden alcanzar o mantener posiciones significativo en el mercado audiovisual.&nbsp; <\/p>\n<p>El informe ofrece un an\u00e1lisis de las medidas paneuropeas para limitar el poder del&nbsp; mercado en el sector audiovisual y examina los marcos normativos en 11 pa\u00edses europeos. Uno de los cap\u00edtulos presente los antecedentes econ\u00f3micos en t\u00e9rminos de cuota de audiencia en el sector de la televisi\u00f3n y v\u00eddeo online. Otra parte del informe destaca las tendencias comunes en la regulaci\u00f3n estatal y explora algunos de los m\u00e9todos m\u00e1s novedosos en este campo.&nbsp;&nbsp;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>En la primera parte, Ralf Capito explica la estrategia de la UE para limitar la concentraci\u00f3n del mercado, principalmente a trav\u00e9s de la ley de competencia. Examina&nbsp; los conceptos de&nbsp; abuso de posici\u00f3n dominante y explica c\u00f3mo eval\u00faa el dominio de la legislaci\u00f3n comunitaria, en particular en el \u00e1rea de fusiones. Este cap\u00edtulo tambi\u00e9n explica los retos de la definici\u00f3n de mercado con el fin de hacer frente a los diferentes servicios prestados en el sector audiovisual para garantizar una regulaci\u00f3n adecuada. Las nociones de must-carry&nbsp; y neutralidad de la red, instrumentos fundamentales para prevenir la concentraci\u00f3n de medios, se analizan al final de esta primera parte.<\/p>\n<p>Andr\u00e9 Lange, director del departamento de Informaci\u00f3n de Mercados y Financiaci\u00f3n del&nbsp; Observatorio, proporciona un an\u00e1lisis de los shares como posible medida de la concentraci\u00f3n&nbsp; de medios de comunicaci\u00f3n. Tomando la audiencia combinada de los cuatro principales grupos de cada pa\u00eds analizado, basados en datos facilitados por Eurodata TV a nivel mundial, el informe muestra que el mayor grado de concentraci\u00f3n de&nbsp; medios se produce en Suecia. Si se tiene en cuenta las cuotas de los tres principales grupos europeos (ProSiebenSat1 Media AG de Alemania, RTL Group de Dinamarca y TF1 de Francia), es Hungr\u00eda el pa\u00eds con mayor nivel de concentraci\u00f3n, con el grupo RTL que concentra casi el 30 por ciento de la audiencia diaria<\/p>\n<p><a href=\"http:\/\/www.cineytele.com\/noticia.php?nid=38171\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desde 1996 la Asamblea General de la Organizaci\u00f3n de Naciones Unidas conmemora el papel de la televisi\u00f3n como \u201cs\u00edmbolo de la comunicaci\u00f3n y de la globalizaci\u00f3n en el mundo contempor\u00e1neo\u201d. Manteniendo el principio de la Organizaci\u00f3n, el Observatorio Europeo del Audiovisual ha publicado un nuevo informe sobre la concentraci\u00f3n de los medios.<\/p>\n","protected":false},"author":3,"featured_media":21402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-21403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21403"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21402"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}