{"id":21472,"date":"2012-11-23T17:00:00","date_gmt":"2012-11-23T21:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ex-ingenieros-de-nokia-lanzan-un-nuevo-sistema-operativo-para-smartphones\/"},"modified":"2012-11-23T17:00:00","modified_gmt":"2012-11-23T21:00:00","slug":"ex-ingenieros-de-nokia-lanzan-un-nuevo-sistema-operativo-para-smartphones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ex-ingenieros-de-nokia-lanzan-un-nuevo-sistema-operativo-para-smartphones\/","title":{"rendered":"Ex-ingenieros de Nokia lanzan un nuevo sistema operativo para smartphones"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21471\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_nokia_mex_photo1_lowres_500.jpg\" width=\"500\" height=\"355\" alt=\"nokia_mex_photo1_lowres_500\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_nokia_mex_photo1_lowres_500.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_nokia_mex_photo1_lowres_500-300x213.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_nokia_mex_photo1_lowres_500-75x52.jpg 75w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>La compa\u00f1\u00eda finlandesa Jolla, fundada por exingenieros de Nokia, present\u00f3 hoy en Helsinki \u2018Sailfish\u2019, un nuevo sistema operativo para \u2018smartphones\u2019 (tel\u00e9fonos inteligentes) con el que busca competir con el Android de Google y el Windows Phone de Microsoft.<\/p>\n<p>  <!--more-->  <\/p>\n<p><strong>\u2018Sailfish\u2019 est\u00e1 basado en MeeGo, la plataforma m\u00f3vil de c\u00f3digo abierto desarrollada por Intel y Nokia<\/strong>&nbsp;a la que el fabricante finland\u00e9s de celulares renunci\u00f3 el pasado a\u00f1o tras lanzar un \u00fanico modelo de \u2018smartphone\u2019 (el Nokia N9), para adoptar en su lugar el Windows Phone.<\/p>\n<p>Seg\u00fan explic\u00f3 Jolla en un comunicado, el nuevo sistema operativo cuenta con una funci\u00f3n multitarea que proporciona \u201cuna facilidad de uso y una velocidad nunca vistas\u201d en la industria de la telefon\u00eda m\u00f3vil.<\/p>\n<p>\u201cLos usuarios pueden interactuar con las aplicaciones activas directamente desde la pantalla de inicio, finalizando llamadas o pausando canciones sin necesidad de entrar en la aplicaci\u00f3n\u201d, se\u00f1al\u00f3 la compa\u00f1\u00eda.<\/p>\n<p>\u2018Sailfish\u2019 permite adem\u00e1s personalizar el m\u00f3vil de manera sencilla y, seg\u00fan sus creadores,&nbsp;<strong>es compatible tambi\u00e9n con otros terminales electr\u00f3nicos como tabletas, televisores inteligentes o dispositivos para automoci\u00f3n<\/strong>.<\/p>\n<p>Jolla anunci\u00f3 tambi\u00e9n la firma de un acuerdo de cooperaci\u00f3n con DNA, la tercera operadora de telecomunicaciones de Finlandia, para comercializar en el pa\u00eds n\u00f3rdico los primeros \u2018smartphones\u2019 equipados con \u2018Sailfish\u2019 que salgan al mercado.<\/p>\n<p>Con sede en Helsinki, Jolla tiene dos centros de investigaci\u00f3n y desarrollo (I+D) en Finlandia y oficinas en Hong Kong (China), pa\u00eds desde el que quiere lanzar la expansi\u00f3n de su sistema operativo para m\u00f3viles.<\/p>\n<p><a href=\"http:\/\/www.eleconomista.es\/tecnologia\/noticias\/4415740\/11\/12\/Exingenieros-de-Nokia-lanzan-un-nuevo-sistema-operativo-para-smartphones.html\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La compa\u00f1\u00eda finlandesa Jolla, fundada por exingenieros de Nokia, present\u00f3 hoy en Helsinki \u2018Sailfish\u2019, un nuevo sistema operativo para \u2018smartphones\u2019 (tel\u00e9fonos inteligentes) con el que busca competir con el Android de Google y el Windows Phone de Microsoft.<\/p>\n","protected":false},"author":3,"featured_media":21471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-21472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21472"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21471"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}