{"id":21559,"date":"2012-11-25T19:59:45","date_gmt":"2012-11-25T23:59:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-mundo-conmemora-dia-internacional-de-la-eliminacion-de-la-violencia-contra-la-mujer\/"},"modified":"2012-11-25T19:59:45","modified_gmt":"2012-11-25T23:59:45","slug":"el-mundo-conmemora-dia-internacional-de-la-eliminacion-de-la-violencia-contra-la-mujer","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-mundo-conmemora-dia-internacional-de-la-eliminacion-de-la-violencia-contra-la-mujer\/","title":{"rendered":"El mundo conmemora &#8216;D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21558\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_no_violencia.jpg\" width=\"400\" height=\"297\" alt=\"no_violencia\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_no_violencia.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/sosua_images_no_violencia-300x222.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Las mujeres son v\u00edctimas de muchos tipos de violencia en el mundo, desde la que ejerce sobre ellas su pareja hasta las mutilaciones genitales, la violaci\u00f3n, los abortos de fetos femeninos y las agresiones para salvaguardar el \u00abhonor\u00bb de la familia.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<div>Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), una de cada tres mujeres asesinadas muere a manos de su pareja (el 35%), mientras que se producen en torno a 5.000 asesinatos cada a\u00f1o por cuestiones de honor, sobre todo en Oriente Medio y el sur de Asia.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Las cifras, publicadas con motivo de la celebraci\u00f3n ma\u00f1ana domingo del D\u00eda Mundial para la Eliminaci\u00f3n de la Violencia contra las Mujeres, se quedan cortas ya que en muchos pa\u00edses no hay datos oficiales y las agresiones no se denuncian.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Algunos casos a veces son primera p\u00e1gina de los peri\u00f3dicos, como el de la ni\u00f1a paquistan\u00ed de 14 a\u00f1os asesinada este mes por sus propios padres, que al sospechar que manten\u00eda una relaci\u00f3n con un chico la rociaron con \u00e1cido, un tipo de agresi\u00f3n que se cobr\u00f3 las vidas de 943 mujeres en Pakist\u00e1n el a\u00f1o pasado.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>O el de la tambi\u00e9n paquistan\u00ed Malala Yusufzai, de 15 a\u00f1os, a la que los talibanes dispararon e hirieron por defender el derecho de las ni\u00f1as a la educaci\u00f3n.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Seg\u00fan un estudio del Centro canadiense de Investigaci\u00f3n Global para la Salud, en las \u00faltimas tres d\u00e9cadas se han producido en la India 12 millones de abortos selectivos de fetos femeninos, la mitad de ellos en los \u00faltimos diez a\u00f1os.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Miles de indias mueren cada a\u00f1o por agresiones ligadas al impago de sus dotes, pese a que estas son ilegales, y el matrimonio infantil afecta al 56% de las f\u00e9minas rurales, mientras que m\u00e1s de 14 millones de ni\u00f1as son v\u00edctimas de casamientos forzosos antes de los 18 a\u00f1os en el \u00c1frica subsahariana.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Y m\u00e1s de tres millones de ni\u00f1as sufren cada a\u00f1o el riesgo de mutilaci\u00f3n genital en \u00c1frica, seg\u00fan ONU Mujeres.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Otro tipo de violencia es la que se ejerce en los conflictos armados, donde seg\u00fan la OMS la violencia sexual es empleada como un arma de guerra.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>La violencia dentro de la pareja es una de las formas de agresi\u00f3n m\u00e1s usuales en el mundo occidental, donde pese a las campa\u00f1as de concienciaci\u00f3n, la protecci\u00f3n a las v\u00edctimas y el endurecimiento de las leyes el problema parece estar en aumento.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>A ello contribuye la crisis econ\u00f3mica actual, que impide en muchos casos a una pareja separarse por motivos econ\u00f3micos.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>En Espa\u00f1a una nueva ley de tasas judiciales propuesta por el Gobierno puede empeorar la situaci\u00f3n, ya que muchas mujeres sin medios tendr\u00e1n mayores dificultades para acceder a la Justicia.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Seg\u00fan la Comisi\u00f3n Europea, una de cada diez mujeres en Europa ha sufrido violencia sexual y cerca de una de cada cinco ha sido v\u00edctima de malos tratos al menos una vez en su vida.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>En el Reino Unido hay una media de tres incidentes de violencia dom\u00e9stica cada minuto, pero las autoridades calculan que s\u00f3lo se denuncian un 40 % de los casos, mientras que en Francia un 2 % de las mujeres han sido v\u00edctimas de alg\u00fan tipo de violencia machista en los dos \u00faltimos a\u00f1os.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>En Rusia, el concepto de violencia familiar no figura en el c\u00f3digo penal ni en el civil, y en China los datos son muy escasos, quiz\u00e1s porque muchas mujeres en \u00e1reas rurales no denuncian su situaci\u00f3n por miedo o verg\u00fcenza en una sociedad machista y tradicional.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>Un estudio de la estatal Academia China de Ciencias Sociales asegura que un tercio de las mujeres chinas han sufrido violencia f\u00edsica, psicol\u00f3gica o social, pero la Federaci\u00f3n de Mujeres de China s\u00f3lo recibe unas 50.000 denuncias anuales.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>La OMS tambi\u00e9n ha denunciado los asesinatos sistem\u00e1ticos de mujeres, especialmente en Latinoam\u00e9rica, y cita los de al menos 400 durante la \u00faltima d\u00e9cada en Ciudad Ju\u00e1rez (M\u00e9xico) o de otras 700 en 2008 en Guatemala.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>En Am\u00e9rica Latina destacan los avances logrados en Brasil, donde han sido condenadas 100.000 personas desde que se aprob\u00f3 en 2006 una severa legislaci\u00f3n contra la violencia dom\u00e9stica y se han recibido 2,7 millones de llamadas en el servicio telef\u00f3nico para la recepci\u00f3n de denuncias que opera desde ese mismo a\u00f1o, seg\u00fan Amnist\u00eda Internacional.<\/div>\n<p> <\/p>\n<div><\/div>\n<div><\/div>\n<div>La incapacidad de aceptar la emancipaci\u00f3n de la mujer y el que haya conquistado todos sus derechos es algo que muchos hombres \u00abno pueden tolerar\u00bb y lleva a matarlas, afirm\u00f3 hoy el diario vaticano L&#8217;Osservatore Romano en un art\u00edculo sobre la jornada mundial contra la violencia a las mujeres.<\/div>\n<p> <\/p>\n<div>Por: EFE<\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres son v\u00edctimas de muchos tipos de violencia en el mundo, desde la que ejerce sobre ellas su pareja hasta las mutilaciones genitales, la violaci\u00f3n, los abortos de fetos femeninos y las agresiones para salvaguardar el \u00abhonor\u00bb de la familia.<\/p>\n","protected":false},"author":3,"featured_media":21558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-21559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21559"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21558"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}