{"id":21998,"date":"2012-12-11T14:36:34","date_gmt":"2012-12-11T18:36:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/dizque-el-amor-en-el-matrimonio-dura-solo-dos-anos-estudio\/"},"modified":"2012-12-11T14:36:34","modified_gmt":"2012-12-11T18:36:34","slug":"dizque-el-amor-en-el-matrimonio-dura-solo-dos-anos-estudio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dizque-el-amor-en-el-matrimonio-dura-solo-dos-anos-estudio\/","title":{"rendered":"Dizque el amor en el matrimonio dura solo dos a\u00f1os (Estudio)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-21997\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_pareja-feliz-enamorados.jpg\" width=\"649\" height=\"322\" alt=\"pareja-feliz-enamorados\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_pareja-feliz-enamorados.jpg 649w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_pareja-feliz-enamorados-300x148.jpg 300w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/>La Investigaci\u00f3n que dur\u00f3 15 a\u00f1os y se realiz\u00f3 en m\u00e1s de 1700 matrimonios demostr\u00f3 que, en promedio, el impulso de felicidad de la pareja reci\u00e9n casada dura los primeros dos de a\u00f1os.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Despu\u00e9s de estos dos a\u00f1os, la pareja regresa a un estado de bienestar previo a su matrimonio, lo que significa que vuelven a la misma felicidad que ten\u00edan antes de casarse. Esto puede ser un aspecto positivo o negativo, pero depende de c\u00f3mo lo tome cada pareja.<\/p>\n<p>Un grupo multinacional de investigadores hizo pruebas en 1761 matrimonios, los cuales tuvieron que monitorear durante los \u00faltimos 15 a\u00f1os.<\/p>\n<p>El estudio tiene varios par\u00e1metros, los cuales convergen cuando hay dos personas enamoradas, y que van del deseo sexual hasta la \u201cadaptaci\u00f3n hed\u00f3nica\u201d.<\/p>\n<p>La \u201cadaptaci\u00f3n hed\u00f3nica\u201d es la forma emocional en la que afrontamos lo novedoso, algo que no s\u00f3lo pasa con el amor, sino cuando se compra un accesorio nuevo, se cambia de trabajo o se vive en un nuevo lugar.<\/p>\n<p>Esta adaptaci\u00f3n s\u00f3lo se logra al encontrar cosas positivas. Sin embargo la inclinaci\u00f3n emotiva a lo novedoso va desapareciendo poco a poco. De acuerdo con el estudio, en el amor es igual, se va aplacando de manera progresiva hasta convertirse en algo muy normal a los dos a\u00f1os (en promedio).<\/p>\n<p>El amor tambi\u00e9n se puede terminar por causas \u201cEvolutivas y pr\u00e1cticas\u201d. Esto significa que el ser humano no puede mantener la misma intensidad de sentimiento, de lo contrario caer\u00eda en obsesi\u00f3n de niveles patol\u00f3gicos que podr\u00edan afectar su vida cotidiana.<\/p>\n<p>LAS BUENAS NOTICIAS<\/p>\n<p>Por otra parte el estudio tambi\u00e9n encontr\u00f3 que a las mujeres les gusta mucho la \u201cidea de novedad\u201d en el sexo, m\u00e1s que a los hombres (descubrir o experimentar cosas nuevas).<\/p>\n<p>La misma excitaci\u00f3n que las personas ten\u00edan al estar reci\u00e9n casadas, regresa entre 18 y 20 a\u00f1os despu\u00e9s. Y casualmente, esto ocurre cuando los hijos comienzan a independizarse y los esposos comienzan a tener m\u00e1s libertad en cuanto a su intimidad<\/p>\n<p>Estas teor\u00edas a\u00fan no se han comprobado, pero se est\u00e1n haciendo m\u00e1s pruebas para tener conclusiones m\u00e1s acertadas. El estudio fue publicado por la psic\u00f3loga Sonja Lyubomirsky en el New York Times.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Investigaci\u00f3n que dur\u00f3 15 a\u00f1os y se realiz\u00f3 en m\u00e1s de 1700 matrimonios demostr\u00f3 que, en promedio, el impulso de felicidad de la pareja reci\u00e9n casada dura los primeros dos de a\u00f1os.<\/p>\n","protected":false},"author":3,"featured_media":21997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-21998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=21998"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/21998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/21997"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=21998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=21998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=21998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}