{"id":22012,"date":"2012-12-11T16:49:55","date_gmt":"2012-12-11T20:49:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/republica-dominicana-mas-que-preparada-para-el-juego-de-las-estrellas-contra-venezuela\/"},"modified":"2012-12-11T16:49:55","modified_gmt":"2012-12-11T20:49:55","slug":"republica-dominicana-mas-que-preparada-para-el-juego-de-las-estrellas-contra-venezuela","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/republica-dominicana-mas-que-preparada-para-el-juego-de-las-estrellas-contra-venezuela\/","title":{"rendered":"Rep\u00fablica Dominicana m\u00e1s que preparada para el Juego de las Estrellas contra Venezuela"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22011\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_RaulValdez-SM-300x180.jpg\" width=\"300\" height=\"180\" alt=\"RaulValdez-SM-300x180\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_RaulValdez-SM-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_RaulValdez-SM-300x180-500x300.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>El d\u00eda de hoy las ligas dominicanas y venezolanas se enfrentar\u00e1n en el estadio Universitario a las 8:00 PM, con miras al Cl\u00e1sico Mundial, y donde los locales buscar\u00e1n la revancha luego de las dos ca\u00eddas sufridas en el pasado ante el equipo sudamericano.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Es por ello que Ra\u00fal Vald\u00e9s fue designado por el dirigente Alberto Castillo como lanzador abridor, respaldado por los receptores Frank Pe\u00f1a y Robinson D\u00edaz.<\/p>\n<p>Como Infielders jugar\u00e1n H\u00e9ctor Luna, Willis Ot\u00e1\u00f1ez Junior Lake, Erick Almonte, Jos\u00e9 Ram\u00edrez, Hanley Ram\u00edrez, Alex Valdez y Luis Jim\u00e9nez.<\/p>\n<p>Los outfielders ser\u00e1n Juan Carlos P\u00e9rez, Eli\u00e1n Herrera, Marcell Ozuna, Engel Beltr\u00e9, Ricardo Nanita, y Mois\u00e9s Sierra.<\/p>\n<p>Los pitchers ser\u00e1n Miguel Batista, Pedro Viola, Jairo Ascensio, Luis Perdomo, \u00c1ngel Castro, Ra\u00fal Vald\u00e9s, Manauris B\u00e1ez, Jos\u00e9 Rafael D\u00edaz, Enerio del Rosario, Wikins de la Rosa, Daniel Cabrera y Jerry Gil.<\/p>\n<p>Esta ser\u00e1 la tercera edici\u00f3n del Juego de las Estrellas que estas dos selecciones disputen, la cual es organizada por la LVBP y a petici\u00f3n de la Asociaci\u00f3n de Peloteros.<\/p>\n<p>La primera edici\u00f3n se llev\u00f3 a cabo en diciembre de 2008, donde los venezolanos vencieron 4 carreras por 3.<\/p>\n<p>En la segunda edici\u00f3n, disputada en diciembre de 2011, nuevamente el equipo sudamericano dobleg\u00f3 al conjunto dominicano, esta vez 4 carreras por 0.<\/p>\n<p>El partido ser\u00e1 transmitido por el canal Antena 21, contando con las voces de Tom\u00e1s Cabrera y Rafaelito D\u00edaz. Asimismo, podr\u00e1 ser visto desde cualquier parte del mundo a trav\u00e9s del sitio web LVBP.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda de hoy las ligas dominicanas y venezolanas se enfrentar\u00e1n en el estadio Universitario a las 8:00 PM, con miras al Cl\u00e1sico Mundial, y donde los locales buscar\u00e1n la revancha luego de las dos ca\u00eddas sufridas en el pasado ante el equipo sudamericano.<\/p>\n","protected":false},"author":3,"featured_media":22011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22012"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22011"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}