{"id":22031,"date":"2012-12-12T05:20:07","date_gmt":"2012-12-12T09:20:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/reconocen-jugador-oscar-taveras-chilote-llenas\/"},"modified":"2012-12-12T05:20:07","modified_gmt":"2012-12-12T09:20:07","slug":"reconocen-jugador-oscar-taveras-chilote-llenas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/reconocen-jugador-oscar-taveras-chilote-llenas\/","title":{"rendered":"Reconocen jugador Oscar Taveras, Chilote Llenas"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22030\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_oscar_y_chilotes_reconocidos.jpg\" width=\"575\" height=\"340\" alt=\"oscar_y_chilotes_reconocidos\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_oscar_y_chilotes_reconocidos.jpg 575w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_oscar_y_chilotes_reconocidos-300x177.jpg 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/>Dirigentes de diferentes Ligas Deportivas donde se practica b\u00e9isbol de Peque\u00f1as Ligas en Puerto&nbsp;Plataentregaron sendas placas de reconocimiento al jugador de las \u00c1guilas Cibae\u00f1as, Oscar Taveras y al presidente de dicho equipo, Winston Llenas D\u00e1vila (El Chilote).<\/div>\n<p>  <!--more-->  <\/p>\n<div>&nbsp;<\/div>\n<div>Esta actividad se llev\u00f3 a cabo este domingo \u00faltimo en el Estadio Cibaoprevio&nbsp;al partido que escenificaron los Leones del Escogido y las \u00c1guilas del Cibao.<\/div>\n<div>&nbsp;<\/div>\n<div>Los dirigentes deportivos puertoplate\u00f1os, los cuales estuvieron acompa\u00f1ados de un centenar de ni\u00f1os, quienes fueron invitados por los directivos del equipo mamey a presenciar completamente gratis, &nbsp;premiaron al&nbsp;jardinero&nbsp;Taveras &nbsp;por su destacada actuaci\u00f3n en los circuitos minoritarios de los Estados Unidos y en la pelota rentada criolla.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;Taveras, nativo del municipio de Sos\u00faa, agradeci\u00f3 esta distinci\u00f3n, a la vez que exhort\u00f3 a dichos ni\u00f1os practicar beisbol y continuar con sus estudios escolares.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;Mientras, que el presidente y gerente general de las \u00c1guillas Cibae\u00f1as, Llenas D\u00e1vila (El Chilote), fue reconocido &nbsp;por las facilidades que brinda cada a\u00f1o a las Peque\u00f1as Ligas de Puerto Plata, &nbsp;de llevar a decenas de ni\u00f1os al Estadio Cibao a presenciar los partidos del beisbol profesional de invierno.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;La comitiva de dirigentes deportivos de Puerto Plata estuvo integrada por Antonio Irrizarry (Loly); Santo Mart\u00ednez (Tato); Miguel \u00c1ngel de la Cruz (Pij\u00edn); Melvin Lantigua y la comunicadora Lisset Cuevas.<\/div>\n<div>&nbsp;<\/div>\n<div>El grupo de ni\u00f1os que pertenecen a las Ligas Deportivas Antera Mota, Atl\u00e1ntico, Tato Martinez, entre otras, tuvieron la oportunidad de tomarse fotos, compartir y recibir bolas autografiadas de los jugadores del&nbsp;equipomamey Manny Ram\u00edrez, Miguel Tejada, Erick Almonte, entre otros.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dirigentes de diferentes Ligas Deportivas donde se practica b\u00e9isbol de Peque\u00f1as Ligas en Puerto&nbsp;Plataentregaron sendas placas de reconocimiento al jugador de las \u00c1guilas Cibae\u00f1as, Oscar Taveras y al presidente de dicho equipo, Winston Llenas D\u00e1vila (El Chilote).<\/p>\n","protected":false},"author":3,"featured_media":22030,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22031"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22030"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}